


{"id":51708,"date":"2026-04-17T15:19:16","date_gmt":"2026-04-17T13:19:16","guid":{"rendered":"https:\/\/spacewell.com\/senza-categoria\/energy-management-in-manufacturing-gamo-outdoors\/"},"modified":"2026-04-17T15:19:19","modified_gmt":"2026-04-17T13:19:19","slug":"energy-management-in-manufacturing-gamo-outdoors","status":"publish","type":"post","link":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/","title":{"rendered":"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor"},"content":{"rendered":"<div class=\"gb-container gb-container-aed9b6dc\">\n<div class=\"gb-container gb-container-1a3e729b\">\n<div class=\"gb-container gb-container-eb07e1c0\">\n<div class=\"gb-container gb-container-78881d30\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-29899c24\">\n<div class=\"gb-grid-column gb-grid-column-4d6298f2\"><div class=\"gb-container gb-container-4d6298f2\">\n\n<p class=\"m-0\"><strong>Cliente<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-457cd430\"><div class=\"gb-container gb-container-457cd430\">\n\n<p>GAMO Outdoor<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-41ce83e0\"><div class=\"gb-container gb-container-41ce83e0\">\n\n<p><strong>Ambito di applicazione<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-f1b0d34f\"><div class=\"gb-container gb-container-f1b0d34f\">\n\n<p>Implementazione di una strategia di efficienza energetica per ridurre i costi unitari in tutte le linee industriali.<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-0a57ced2\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4b271d4e\">\n<div class=\"gb-grid-column gb-grid-column-8e03d3d9\"><div class=\"gb-container gb-container-8e03d3d9\">\n\n<p><strong>Posizione<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-b80fa4b3\"><div class=\"gb-container gb-container-b80fa4b3\">\n\n<p>Spagna<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9b7bd408\"><div class=\"gb-container gb-container-9b7bd408\">\n\n<p class=\"m-0\"><strong>Soluzione<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-007b9a17\"><div class=\"gb-container gb-container-007b9a17\">\n\n<p><a href=\"https:\/\/spacewell.com\/solutions\/spacewell-energy-management\/\">Spacewell Energy<\/a><\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"gb-container gb-container-e6112bc5 gb-container-5731d80c\">\n\n<p>Gli impianti industriali hanno generalmente bollette energetiche elevate, poich\u00e9 richiedono molte risorse. Tuttavia, l&#8217;elevato consumo di energia comporta l&#8217;opportunit\u00e0 di ottenere risparmi con una gestione intelligente dell&#8217;energia nel settore manifatturiero.   <\/p>\n\n\n\n<p>In qualit\u00e0 di leader europeo nella produzione di armi ad aria compressa, l&#8217;obiettivo di GAMO era quello di ridurre la spesa energetica. La strategia prevedeva l&#8217;implementazione di un sistema di gestione dell&#8217;energia a livello aziendale, la definizione di politiche energetiche, la diffusione di campagne di comunicazione e la formazione dei dipendenti a tutti i livelli.   <\/p>\n\n\n\n<p>L<strong>&#8216;obiettivo iniziale era una riduzione del 10%<\/strong> <strong>del consumo energetico<\/strong>. Qual \u00e8 un buon indicatore del risparmio energetico nella produzione? Dato l&#8217;aumento del tasso di produzione dell&#8217;azienda, il<strong> costo per unit\u00e0 prodotta era un indicatore chiave<\/strong>. GAMO cercava una gestione trasparente dell&#8217;energia per analizzare il rapporto tra consumi e produzione.     <\/p>\n\n\n\n<p>Per iniziare, l&#8217;azienda ha eseguito un audit energetico dettagliato, con il supporto di Spacewell Energy e del nostro partner 3eX4. Hanno monitorato il consumo elettrico dei loro quattro edifici industriali, oltre al consumo dei principali sotto-contatori.   <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-energy-savings-measures-to-reduce-energy-in-manufacturing\">Misure di risparmio energetico per ridurre l&#8217;energia nel settore manifatturiero<\/h3>\n\n\n\n<p>Entrando nel dettaglio, quali sono le misure di risparmio energetico che possono aiutare a ridurre i costi energetici nel settore manifatturiero?  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gestione dei processi termici  <\/strong> <\/li>\n\n\n\n<li><strong>Trattamento delle acque reflue<\/strong>  <\/li>\n\n\n\n<li>Riduzione del <strong>consumo passivo <\/strong>  <\/li>\n\n\n\n<li><strong>Installazione di luci LED e sensori di luce  <\/strong><\/li>\n<\/ul>\n\n\n\n<p>Puoi leggere tutti i dettagli e vedere le cifre dei risparmi ottenuti nella versione pdf del caso di studio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-detailed-results-and-production-kpi\"><strong>Risultati dettagliati e KPI di produzione  <\/strong> <\/h2>\n\n\n\n<p>Il rendimento energetico per unit\u00e0 prodotta \u00e8 diminuito del 28% in due anni.<\/p>\n\n\n\n<p><strong>I miglioramenti implementati hanno ridotto il costo di GAMO per unit\u00e0 prodotta del 15%<\/strong>.<\/p>\n\n\n\n<p>In totale sono state applicate quindici misure e investimenti per il risparmio energetico, che insieme hanno dimostrato un <strong>ROI inferiore a un anno.<\/strong> Ci\u00f2 ha rivelato un&#8217;enorme opportunit\u00e0 per la gestione dell&#8217;energia nel settore manifatturiero di realizzare risparmi energetici in un breve periodo di tempo.  <\/p>\n\n\n\n<p>Il risparmio totale nei primi due anni ha superato gli <strong>85.000 euro<\/strong>. GAMO e 3ex4 insieme hanno ridotto dinamicamente il consumo energetico, aumentato la competitivit\u00e0 dell&#8217;azienda e instillato una cultura del risparmio energetico in tutta l&#8217;organizzazione.   <\/p>\n\n\n\n<p>&#8220;<em>Siamo riusciti a implementare un protocollo di efficienza energetica a livello aziendale che ci ha permesso di ridurre i costi energetici del 20% all&#8217;anno, aumentando la nostra competitivit\u00e0 sul mercato e coinvolgendo l&#8217;intera organizzazione nei nostri sforzi di efficienza energetica.<\/em>&#8221; Josep Centelles, Direttore Industriale GAMO Outdoor  <\/p>\n\n<\/div><div class=\"gb-container gb-container-183829c3 gb-container-5731d80c\"><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli impianti industriali hanno generalmente bollette energetiche elevate, poich\u00e9 richiedono molte risorse. Tuttavia, l&#8217;elevato consumo di energia comporta l&#8217;opportunit\u00e0 di ottenere risparmi con una gestione intelligente dell&#8217;energia nel settore manifatturiero. In qualit\u00e0 di leader europeo nella produzione di armi ad aria compressa, l&#8217;obiettivo di GAMO era quello di ridurre la spesa energetica. La strategia prevedeva &#8230; <a title=\"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor\" class=\"read-more\" href=\"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/\" aria-label=\"Per saperne di pi\u00f9 su Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor\">Leggi tutto<\/a><\/p>\n","protected":false},"author":33,"featured_media":51709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1083,1084,1045,1081,1046,1064,1086,1075],"tags":[],"class_list":["post-51708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisi-dellenergia","category-analisi-dellenergia-2","category-blog","category-energia","category-energy","category-reporting-di-energy","category-reporting-sullenergia","category-storie-di-clienti","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gestione dell&#039;energia nel settore manifatturiero: GAMO Outdoor<\/title>\n<meta name=\"description\" content=\"Scopri come gestire al meglio la gestione dell&#039;energia nella produzione con l&#039;esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestione dell&#039;energia nel settore manifatturiero: GAMO Outdoor\" \/>\n<meta property=\"og:description\" content=\"Scopri come gestire al meglio la gestione dell&#039;energia nella produzione con l&#039;esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T13:19:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T13:19:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Helena Palomo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Palomo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/\"},\"author\":{\"name\":\"Helena Palomo\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#\\\/schema\\\/person\\\/fb39acde59094999074f3ae62e2b159a\"},\"headline\":\"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor\",\"datePublished\":\"2026-04-17T13:19:16+00:00\",\"dateModified\":\"2026-04-17T13:19:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/\"},\"wordCount\":448,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Case-Study-GAMO.png\",\"articleSection\":[\"Analisi dell'energia\",\"Analisi dell'energia\",\"Blog\",\"Energia\",\"Energy\",\"Reporting di Energy\",\"Reporting sull'energia\",\"Storie di clienti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/\",\"name\":\"Gestione dell'energia nel settore manifatturiero: GAMO Outdoor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Case-Study-GAMO.png\",\"datePublished\":\"2026-04-17T13:19:16+00:00\",\"dateModified\":\"2026-04-17T13:19:19+00:00\",\"description\":\"Scopri come gestire al meglio la gestione dell'energia nella produzione con l'esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Case-Study-GAMO.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Case-Study-GAMO.png\",\"width\":1200,\"height\":630,\"caption\":\"Gestione dell'energia nel settore manifatturiero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/risorse\\\/storie-di-clienti\\\/energy-management-in-manufacturing-gamo-outdoors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/it\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/it\\\/#\\\/schema\\\/person\\\/fb39acde59094999074f3ae62e2b159a\",\"name\":\"Helena Palomo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"caption\":\"Helena Palomo\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/it\\\/author\\\/helena-palomo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gestione dell'energia nel settore manifatturiero: GAMO Outdoor","description":"Scopri come gestire al meglio la gestione dell'energia nella produzione con l'esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/","og_locale":"it_IT","og_type":"article","og_title":"Gestione dell'energia nel settore manifatturiero: GAMO Outdoor","og_description":"Scopri come gestire al meglio la gestione dell'energia nella produzione con l'esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.","og_url":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2026-04-17T13:19:16+00:00","article_modified_time":"2026-04-17T13:19:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png","type":"image\/png"}],"author":"Helena Palomo","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Scritto da":"Helena Palomo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/"},"author":{"name":"Helena Palomo","@id":"https:\/\/spacewell.com\/it\/#\/schema\/person\/fb39acde59094999074f3ae62e2b159a"},"headline":"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor","datePublished":"2026-04-17T13:19:16+00:00","dateModified":"2026-04-17T13:19:19+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/"},"wordCount":448,"publisher":{"@id":"https:\/\/spacewell.com\/it\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png","articleSection":["Analisi dell'energia","Analisi dell'energia","Blog","Energia","Energy","Reporting di Energy","Reporting sull'energia","Storie di clienti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/","url":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/","name":"Gestione dell'energia nel settore manifatturiero: GAMO Outdoor","isPartOf":{"@id":"https:\/\/spacewell.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png","datePublished":"2026-04-17T13:19:16+00:00","dateModified":"2026-04-17T13:19:19+00:00","description":"Scopri come gestire al meglio la gestione dell'energia nella produzione con l'esempio del produttore di armi GAMO Outdoors, che ha ottenuto un risparmio del 28%.","breadcrumb":{"@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2025\/05\/Case-Study-GAMO.png","width":1200,"height":630,"caption":"Gestione dell'energia nel settore manifatturiero"},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/it\/risorse\/storie-di-clienti\/energy-management-in-manufacturing-gamo-outdoors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gestione dell&#8217;energia nel settore manifatturiero: GAMO Outdoor"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/it\/#website","url":"https:\/\/spacewell.com\/it\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/it\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/spacewell.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/it\/#\/schema\/person\/fb39acde59094999074f3ae62e2b159a","name":"Helena Palomo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","caption":"Helena Palomo"},"url":"https:\/\/spacewell.com\/it\/author\/helena-palomo\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/posts\/51708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/comments?post=51708"}],"version-history":[{"count":11,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/posts\/51708\/revisions"}],"predecessor-version":[{"id":51721,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/posts\/51708\/revisions\/51721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/media\/51709"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/media?parent=51708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/categories?post=51708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/it\/wp-json\/wp\/v2\/tags?post=51708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}