


{"id":6583,"date":"2020-11-04T09:05:00","date_gmt":"2020-11-04T08:05:00","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/quest-ce-que-le-smart-building\/"},"modified":"2023-11-29T11:14:17","modified_gmt":"2023-11-29T10:14:17","slug":"quest-ce-que-le-smart-building","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/","title":{"rendered":"Qu\u2019est-ce que le smart building ?"},"content":{"rendered":"<div class=\"gb-container gb-container-1834b05a gb-container-5731d80c\">\n\n<p>Le smart building, \u00e9galement appel\u00e9 b\u00e2timent intelligent ou encore b\u00e2timent connect\u00e9, d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es de diverses natures (occupation, temp\u00e9rature, \u00e9clairage, etc.) au sein d\u2019un b\u00e2timent et de les mettre \u00e0 disposition de tous les acteurs qui gravitent autour : occupants, exploitants, gestionnaires.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-190c6719 gb-headline-text\">Les principaux atouts du smart building<\/h2>\n\n\n\n<p>Le smart building en tant que solution innovante permet de poursuivre plusieurs objectifs conjointement :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>l\u2019am\u00e9lioration du confort des occupants<\/li>\n\n\n\n<li>la r\u00e9duction des co\u00fbts d\u2019exploitation<\/li>\n\n\n\n<li>la gestion pr\u00e9visionnelle des usages<\/li>\n<\/ul>\n\n\n\n<h3 class=\"gb-headline gb-headline-f7ab7be4 gb-headline-text\">Contribuer au confort et \u00e0 l\u2019environnement des occupants<\/h3>\n\n\n\n<p>Il r\u00e9pond \u00e0 des enjeux environnementaux tels que le d\u00e9cret tertiaire qui pr\u00e9voit d\u2019am\u00e9liorer la performance \u00e9nerg\u00e9tique des b\u00e2timents tertiaires d\u2019au moins 40% en 2030, ou bien encore la mutualisation des espaces et des usages afin de limiter la surench\u00e8re de constructions inutiles. Dans ce cas pr\u00e9sent, il permet de superviser en temps r\u00e9el les conditions ambiantes au sein des locaux (CO2, temp\u00e9rature).  <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-193af9fb gb-headline-text\">Ma\u00eetrise des co\u00fbts de maintenance du b\u00e2timent<\/h3>\n\n\n\n<p>Il r\u00e9pond \u00e9galement \u00e0 des enjeux \u00e9conomiques puisqu\u2019il est principalement utilis\u00e9 sur un b\u00e2timent en phase d\u2019exploitation (post construction), phase qui concentre \u00e0 elle seule environ 80% des co\u00fbts totaux du cycle de vie d\u2019un b\u00e2timent (dur\u00e9e moyenne entre 30 et 35 ans). Dans ce cas pr\u00e9sent, le b\u00e2timent intelligent permet de superviser en temps r\u00e9el l\u2019\u00e9tat des \u00e9quipements techniques. <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-f3f7a7ad gb-headline-text\">Anticiper les tendances d\u2019occupation et d\u2019usage des locaux<\/h3>\n\n\n\n<p>Enfin il participe activement \u00e0 l\u2019adoption des nouveaux usages de travail en entreprise puisqu\u2019il permet par exemple une mise en place efficace du t\u00e9l\u00e9travail (flex office) dans les bureaux et garantit un dimensionnement efficace des espaces dans le temps. Ainsi les directions m\u00e9tier ont plus de flexibilit\u00e9 pour s\u2019organiser et garantir des conditions de travail saines. <\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-5b9a227c gb-headline-text\">Quels sont les avantages du smart building pour l\u2019entreprise et son \u00e9cosyst\u00e8me ?<\/h2>\n\n\n\n<p>Ils sont nombreux et varient selon les diff\u00e9rents profils en relation avec l\u2019environnement de travail \u00e0 savoir :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>les occupants,<\/li>\n\n\n\n<li>les exploitants\/techniciens,<\/li>\n\n\n\n<li>les gestionnaires\/propri\u00e9taires.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"gb-headline gb-headline-ac4d84f8 gb-headline-text\">Avantages du smart building pour les occupants<\/h3>\n\n\n\n<p>Garantir le bien-\u00eatre et la s\u00e9curit\u00e9 des usagers car le b\u00e2timent intelligent va permettre d\u2019accro\u00eetre le tissu de confiance entre les collaborateurs\/occupants et leur lieu de travail en favorisant la <a href=\"\/fr\/solutions\/solutions-denvironnements-travail\/workplace-analytics\/utilisation-de-lespace\/\">consommation d\u2019espaces<\/a> vari\u00e9s (poste non attribu\u00e9, salle de r\u00e9union, bulle, etc.) de mani\u00e8re plus intuitive et rapide. Mais il va aussi remettre au centre de toutes les attentions la satisfaction de l\u2019employ\u00e9 par exemple en permettant de r\u00e9colter en temps r\u00e9el les demandes de dysfonctionnement (bouton tactile dans les sanitaires d\u00e9clenchant une intervention lorsqu\u2019on appuie dessus). La n\u00e9cessit\u00e9 de proposer un cadre de travail agr\u00e9able est d\u00e9sormais un facteur cl\u00e9 dans la r\u00e9tention des talents. <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-f56b558a gb-headline-text\">Avantages du smart building pour les gestionnaires\/propri\u00e9taires<\/h3>\n\n\n\n<p>Maintenir une valorisation de son actif immobilier d\u2019entreprise car le b\u00e2timent connect\u00e9 va permettre de conna\u00eetre de mani\u00e8re tr\u00e8s pr\u00e9cise et en continu l\u2019occupation r\u00e9elle au sein des locaux afin d\u2019optimiser les usages et les espaces (moins de salles de r\u00e9union \u00e0 tel \u00e9tage donc privil\u00e9gier des bulles) ainsi qu\u2019anticiper les besoins \u00e0 venir (places flex office d\u2019un plateau occup\u00e9es seulement \u00e0 20% pouvant accueillir de nouveaux collaborateurs). Toutes les tendances sont d\u00e9sormais facilement lisibles et \u00e0 disposition des organisations.  <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-4dc64e70 gb-headline-text\">Avantages du smart building pour les exploitants\/techniciens<\/h3>\n\n\n\n<p><a href=\"https:\/\/spacewell.com\/fr\/solutions\/maintenance-batiment\/\">Optimiser la gestion et la maintenance<\/a> des installations car le smart building va permettre d\u2019une part d\u2019augmenter la productivit\u00e9 des \u00e9quipes op\u00e9rationnelles au travers d\u2019outils digitaux affichant les informations temps r\u00e9el et d\u2019autre part renforcer la s\u00e9curit\u00e9 de ces m\u00eames employ\u00e9s, notamment en p\u00e9riode de crise sanitaire, via la mise \u00e0 disposition d\u2019outils digitaux ad\u00e9quats (personnel de nettoyage en milieu hospitalier qui visualisent en temps r\u00e9el les blocs op\u00e9ratoires covid disponibles pour nettoyage avec liste d\u2019instructions sp\u00e9cifique).<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-52ee1206 gb-headline-text\">Comment fonctionne un smart building ?<\/h2>\n\n\n\n<p>Le b\u00e2timent connect\u00e9 se comporte comme un \u00e9cosyst\u00e8me ouvert qui fonctionne sur n\u2019importe quel b\u00e2timent (tertiaire ou non) interconnect\u00e9 d\u2019un c\u00f4t\u00e9 avec des logiciels d\u2019entreprises (ticketing, r\u00e9servations, etc.) et de l\u2019autre c\u00f4t\u00e9 avec des syst\u00e8mes tiers de remont\u00e9e de donn\u00e9es li\u00e9es aux b\u00e2timents selon 3 approches d\u2019int\u00e9gration possibles :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019internet des objets (IoT), il s\u2019agit de l\u2019interconnexion entre Internet et des objets, des lieux et des environnements physiques<\/li>\n\n\n\n<li>Gestion Technique du B\u00e2timent (GTB), c\u2019est un syst\u00e8me informatique g\u00e9n\u00e9ralement install\u00e9 dans des grands b\u00e2timents ou dans des installations industrielles afin de superviser l\u2019ensemble des \u00e9quipements qui y sont install\u00e9s (\u00e9clairage, climatisation, etc.)<\/li>\n\n\n\n<li>Une coexistence des deux \u00e9l\u00e9ments IoT et GTB au sein d\u2019un m\u00eame site<\/li>\n<\/ul>\n\n\n\n<p>Quel que soit l\u2019approche retenue, le b\u00e2timent intelligent permet la r\u00e9colte de ces donn\u00e9es et leur transmission vers une plateforme logicielle SaaS (cloud) de mani\u00e8re anonyme et s\u00e9curis\u00e9e puis leur restitution via des applications m\u00e9tier sans oublier leur analyse au travers de tableaux de bord \u00e0 destination d\u2019experts concern\u00e9s.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-03d873cd\">\n\n<figure class=\"gb-block-image gb-block-image-e39db5f3\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" class=\"gb-image gb-image-e39db5f3 gb-image-b19acb23\" src=\"\/wp-content\/uploads\/2023\/06\/building-graphics-connected-1200x630-1.png\" alt=\"B\u00e2timents li\u00e9s au graphisme\" srcset=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/building-graphics-connected-1200x630-1.png 1200w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/building-graphics-connected-1200x630-1-500x263.png 500w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/building-graphics-connected-1200x630-1-1024x538.png 1024w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/building-graphics-connected-1200x630-1-768x403.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-9f300bd2 gb-container-5731d80c\">\n\n<h3 class=\"gb-headline gb-headline-b6c273e3 gb-headline-text\">IoT et smart building<\/h3>\n\n\n\n<p>Le mat\u00e9riel IoT utilis\u00e9 dans le cadre du smart building comprend tr\u00e8s souvent des capteurs de diff\u00e9rentes natures (pr\u00e9sence, humidit\u00e9, CO2, demande tactile, ouverture portes) s\u2019appuyant sur un protocole de communication sp\u00e9cifique (Sigfox ou LoRA) qui n\u2019interf\u00e8re pas avec le r\u00e9seau informatique des entreprises. La grande majorit\u00e9 de ces capteurs sont non filaires (autonomie de plusieurs ann\u00e9es) ce qui rend le dispositif discret et facilement d\u00e9pla\u00e7able. Les donn\u00e9es issues de ces capteurs ne collectent aucune information personnelle puisqu\u2019elles sont relatives \u00e0 des espaces de travail et en aucun cas \u00e0 des individus.  <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-9522e486 gb-headline-text\">GTB et smart building<\/h3>\n\n\n\n<p>Certains fabricants proposent d\u00e9sormais d\u2019acc\u00e9der aux informations de leurs syst\u00e8mes GTB, cela est principalement valable pour les derniers mod\u00e8les du march\u00e9 qui embarquent d\u00e9j\u00e0 certains types de capteurs. Toutes les donn\u00e9es relatives aux \u00e9quipements supervis\u00e9s (climatisation, \u00e9clairage) ainsi qu\u2019aux usages (pr\u00e9sence, contr\u00f4le d\u2019acc\u00e8s) sont d\u00e9sormais accessibles sur la plateforme cloud du fabricant pour laquelle il est possible de s\u2019interconnecter via des protocoles type API (Application Protocol Interface). <\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-3afe8661 gb-headline-text\">Smart building avec IoT et GTB en m\u00eame temps<\/h3>\n\n\n\n<p>Il est \u00e9videmment possible de coupler ces deux dispositifs sur un m\u00eame site ou b\u00e2timent puisqu\u2019ils peuvent \u00eatre compl\u00e9mentaires. En effet, il est possible que la collecte en temps r\u00e9el des informations relatives aux \u00e9quipements \u00e9clairage et climatisation provienne de la GTB install\u00e9e et que les informations relatives \u00e0 l\u2019occupation et temp\u00e9rature soient collect\u00e9es depuis des capteurs de pr\u00e9sence et de confort (IoT). L\u2019ensemble \u00e9tant ensuite inject\u00e9 dans une plateforme logicielle SaaS qui va mettre \u00e0 disposition ces donn\u00e9es aupr\u00e8s des acteurs de la cha\u00eene immobili\u00e8re d\u2019entreprise.  <\/p>\n\n\n\n<p>L\u2019avantage de l\u2019IoT est son co\u00fbt de mise en place et qu\u2019il est applicable sur n\u2019importe quel type de b\u00e2timent (neuf ou ancien) quel que soit son cycle (d\u00e9j\u00e0 construit ou non).<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-7c365016 gb-headline-text\">Quelles sont les prochaines \u00e9tapes du smart building ?<\/h2>\n\n\n\n<h3 class=\"gb-headline gb-headline-66b5ce08 gb-headline-text\">Smart building avec GMAO<\/h3>\n\n\n\n<p>Ce rapprochement de la connaissance approfondie des \u00e9quipements techniques du b\u00e2timent (CVC, \u00e9clairage, etc.) et de l\u2019utilisation r\u00e9elle des usages des locaux (occupation salles r\u00e9union, passage dans les sanitaires, etc.) conduit les entreprises en charge de la maintenance et de l\u2019entretien \u00e0 red\u00e9finir leur c\u0153ur de m\u00e9tier en proposant une maintenance plus r\u00e9active et d\u00e9sormais pr\u00e9dictive visant \u00e0 am\u00e9liorer le confort des usagers d\u2019une part et \u00e0 optimiser la dur\u00e9e de vie des installations d\u2019autre part. Le smart building adoss\u00e9 \u00e0 l\u2019activit\u00e9 <a href=\"https:\/\/spacewell.com\/fr\/solutions\/maintenance-batiment\/\">GMAO<\/a> (Gestion Maintenance Assist\u00e9e Ordinateur) permet ainsi de d\u00e9finir un outil de nouvelle g\u00e9n\u00e9ration que nous appelons Smart GMAO. <\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-49448a45\">\n\n<figure class=\"gb-block-image gb-block-image-c74e5a85\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" class=\"gb-image gb-image-c74e5a85 gb-image-b19acb23\" src=\"\/wp-content\/uploads\/2023\/06\/mcs-20-1200x630-1.png\" alt=\"MCS 20 : IWMS avec BIM int\u00e9gr\u00e9\" srcset=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/mcs-20-1200x630-1.png 1200w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/mcs-20-1200x630-1-500x263.png 500w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/mcs-20-1200x630-1-1024x538.png 1024w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/mcs-20-1200x630-1-768x403.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-0d2297fd gb-container-5731d80c\">\n\n<h3 class=\"gb-headline gb-headline-c91a60e9 gb-headline-text\">Smart building avec BIM<\/h3>\n\n\n\n<p>L\u2019utilisation de la maquette num\u00e9rique BIM (3D) dans la phase de Gestion-Exploitation-Maintenance d\u2019un b\u00e2timent est d\u00e9j\u00e0 une remarquable avanc\u00e9e en soi et l\u2019ajout du smart building vient naturellement renforcer la digitalisation de l\u2019ensemble du cycle de vie d\u2019un b\u00e2timent. La vision num\u00e9rique de bout en bout, depuis la conception jusqu\u2019\u00e0 la construction suivie de la surveillance en continu des usages et de l\u2019utilisation\/consommation des ressources devient le socle d\u2019\u00e9changes collaboratifs entre tous les acteurs du b\u00e2timent. <\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-fe812f9b gb-headline-text\">Comment le smart building influence une future construction ?<\/h2>\n\n\n\n<p>Cette vision num\u00e9rique de bout en bout d\u00e9crite plus t\u00f4t constitue un cercle vertueux puisque cela va permettre d\u2019influencer la conception des futures constructions. En effet, toutes les informations terrain issues du smart building nous permettent de savoir si telle architecture\/configuration d\u2019un type d\u2019espace est pl\u00e9biscit\u00e9e par les occupants ou bien \u00e0 bannir parce que jamais occup\u00e9e, si un type d\u2019\u00e9quipement est plus fr\u00e9quemment en panne en rapport avec son lieu de stockage, etc. Toutes ces donn\u00e9es du smart building vont \u00eatre exploit\u00e9es \u00e0 bon escient par les architectures pour les aider \u00e0 concevoir un futur site sur la base de ces pr\u00e9cieux \u00e9l\u00e9ments.  <\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-b5870daf gb-headline-text\">Questions fr\u00e9quentes<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1686555472798\"><strong class=\"schema-faq-question\">Pourquoi le smart building est-il int\u00e9ressant \u00e0 mettre en place aujourd\u2019hui ?<\/strong> <p class=\"schema-faq-answer\">Les principaux atouts du smart building sont les suivants :<br>&#8211; Contribuer au confort et \u00e0 l\u2019environnement des occupants<br>&#8211; Ma\u00eetriser des co\u00fbts de maintenance du b\u00e2timent gr\u00e2ce notamment \u00e0 la maintenance pr\u00e9dictive<br>&#8211; Anticiper les tendances d\u2019occupation et d\u2019usage des locaux<br><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1686555559816\"><strong class=\"schema-faq-question\">Comment d\u00e9ployer le smart building plus efficacement ?<\/strong> <p class=\"schema-faq-answer\">Le smart building fonctionne gr\u00e2ce \u00e0 la remont\u00e9e de donn\u00e9es, un smart building avec IoT (l\u2019internet des objets) et GTB (gestion technique de b\u00e2timent) en m\u00eame temps est la solution la plus compl\u00e9mentaire. <\/p> <\/div> <\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le smart building, \u00e9galement appel\u00e9 b\u00e2timent intelligent ou encore b\u00e2timent connect\u00e9, d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es de diverses natures (occupation, temp\u00e9rature, \u00e9clairage, etc.) au sein d\u2019un b\u00e2timent et de les mettre \u00e0 disposition de tous les acteurs qui gravitent autour : occupants, exploitants, gestionnaires. Les principaux &#8230; <a title=\"Qu\u2019est-ce que le smart building ?\" class=\"read-more\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/\" aria-label=\"En savoir plus sur Qu\u2019est-ce que le smart building ?\">Lire plus<\/a><\/p>\n","protected":false},"author":29,"featured_media":1469,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-6583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qu\u2019est-ce que le smart building ? | Spacewell<\/title>\n<meta name=\"description\" content=\"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u2019est-ce que le smart building ?\" \/>\n<meta property=\"og:description\" content=\"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T08:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T10:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/\"},\"author\":{\"name\":\"Marketing Team\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\"},\"headline\":\"Qu\u2019est-ce que le smart building ?\",\"datePublished\":\"2020-11-04T08:05:00+00:00\",\"dateModified\":\"2023-11-29T10:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/\"},\"wordCount\":1713,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/smart-buildings-1200x630-1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/\",\"name\":\"Qu\u2019est-ce que le smart building ? | Spacewell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/smart-buildings-1200x630-1.jpg\",\"datePublished\":\"2020-11-04T08:05:00+00:00\",\"dateModified\":\"2023-11-29T10:14:17+00:00\",\"description\":\"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555472798\"},{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555559816\"}],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/smart-buildings-1200x630-1.jpg\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/smart-buildings-1200x630-1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Vue d'ensemble de la ville\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u2019est-ce que le smart building ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\",\"name\":\"Marketing Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"caption\":\"Marketing Team\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/marketing-team\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555472798\",\"position\":1,\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555472798\",\"name\":\"Why is it worthwhile to implement a smart building today?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"The main advantages of the smart building include the following:<br\\\/>- It contributes to the comfort and working environment of the occupants.<br\\\/>- It enables you to manage building maintenance costs, particularly through predictive maintenance.<br\\\/>- It helps you to anticipate occupancy and usage patterns of the property.<br\\\/>\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555559816\",\"position\":2,\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/quest-ce-que-le-smart-building\\\/#faq-question-1686555559816\",\"name\":\"How to deploy the smart building in the most efficient way?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Smart buildings rely on data feedback. A smart building with IoT (Internet of Things) and BMS (Building Management System) is the most complementary solution.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qu\u2019est-ce que le smart building ? | Spacewell","description":"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu\u2019est-ce que le smart building ?","og_description":"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2020-11-04T08:05:00+00:00","article_modified_time":"2023-11-29T10:14:17+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg","type":"image\/jpeg"}],"author":"Marketing Team","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"Marketing Team","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/"},"author":{"name":"Marketing Team","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a"},"headline":"Qu\u2019est-ce que le smart building ?","datePublished":"2020-11-04T08:05:00+00:00","dateModified":"2023-11-29T10:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/"},"wordCount":1713,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/","name":"Qu\u2019est-ce que le smart building ? | Spacewell","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg","datePublished":"2020-11-04T08:05:00+00:00","dateModified":"2023-11-29T10:14:17+00:00","description":"Le smart building d\u00e9signe l\u2019ensemble des technologies num\u00e9riques qui permettent de recueillir en temps r\u00e9el des donn\u00e9es au sein d\u2019un b\u00e2timent","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555472798"},{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555559816"}],"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/06\/smart-buildings-1200x630-1.jpg","width":1200,"height":630,"caption":"Vue d'ensemble de la ville"},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu\u2019est-ce que le smart building ?"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a","name":"Marketing Team","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","caption":"Marketing Team"},"url":"https:\/\/spacewell.com\/fr\/author\/marketing-team\/"},{"@type":"Question","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555472798","position":1,"url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555472798","name":"Why is it worthwhile to implement a smart building today?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"The main advantages of the smart building include the following:<br\/>- It contributes to the comfort and working environment of the occupants.<br\/>- It enables you to manage building maintenance costs, particularly through predictive maintenance.<br\/>- It helps you to anticipate occupancy and usage patterns of the property.<br\/>","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555559816","position":2,"url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/#faq-question-1686555559816","name":"How to deploy the smart building in the most efficient way?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Smart buildings rely on data feedback. A smart building with IoT (Internet of Things) and BMS (Building Management System) is the most complementary solution.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/6583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=6583"}],"version-history":[{"count":11,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/6583\/revisions"}],"predecessor-version":[{"id":28205,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/6583\/revisions\/28205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/1469"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=6583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=6583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=6583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}