


{"id":38652,"date":"2020-06-19T09:13:57","date_gmt":"2020-06-19T07:13:57","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/"},"modified":"2020-06-19T09:13:57","modified_gmt":"2020-06-19T07:13:57","slug":"gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/","title":{"rendered":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Par ses vertus p\u00e9dagogiques et sa dimension ludique,<strong> le jeu est un puissant levier de sensibilisation \u00e0 des th\u00e9matiques complexes<\/strong>. Ces derni\u00e8res ann\u00e9es ce principe a pris une importance nouvelle gr\u00e2ce \u00e0 l\u2019expansion des nouvelles technologies. En effet, qu\u2019il s\u2019agisse de jeux-concours, d\u2019applications pour faire d\u00e9couvrir un secteur, de jeux s\u00e9rieux (serious games)&#8230;, la fronti\u00e8re entre le domaine ludique (le jeu) et le domaine s\u00e9rieux (la gestion d\u2019une entreprise ou individuelle, la recherche, l\u2019\u00e9ducation, etc.) s\u2019est estomp\u00e9e.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Plus r\u00e9cemment, un terme a \u00e9t\u00e9 utilis\u00e9 notamment pour les applications qui comportent des \u00e9l\u00e9ments de jeux : Gagner\/perdre, d\u00e9fis et r\u00e9compenses\/p\u00e9nalit\u00e9s. Ce terme est celui de <\/span><strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ludification\" target=\"_blank\" rel=\"noopener noreferrer\">\u201cGamification\u201d ou Ludification<\/a><\/strong><span style=\"font-weight: 400;\"> et d\u00e9signe la rencontre des deux univers.<\/span><\/p>\n<p><!--more--><br \/>\n<!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-node hs-cta-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/8bfbdd5f-5507-4074-b262-d219ff3c8d7a.png\" alt=\"Demo DEXMA Energy Intelligence\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"color: #003b6f;\">Comment fonctionne la Gamification ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Lorsque nous parlons de la <\/span><b>gamification<\/b><span style=\"font-weight: 400;\">, nous faisons surtout r\u00e9f\u00e9rence \u00e0 <\/span><b>l&rsquo;application des concepts et techniques de la <\/b><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Th%C3%A9orie_des_jeux\" target=\"_blank\" rel=\"noopener noreferrer\"><b>th\u00e9orie des jeux<\/b><\/a><b> \u00e0 des activit\u00e9s non li\u00e9es au jeu<\/b><span style=\"font-weight: 400;\">. Ce sont des applications qui <\/span><b>incorporent des \u00e9l\u00e9ments de jeux vid\u00e9o <\/b><span style=\"font-weight: 400;\">qui peuvent maintenir l&rsquo;int\u00e9r\u00eat des utilisateurs en leur donnant une motivation suppl\u00e9mentaire pour continuer \u00e0 utiliser l&rsquo;application, mais surtout, <\/span><b>pour atteindre certains objectifs<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les applications \u00e9ducatives constituent un excellent exemple de gamification : les utilisateurs peuvent se fixer comme objectif quotidien un certain nombre de le\u00e7ons \u00e0 terminer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce syst\u00e8me s&rsquo;est av\u00e9r\u00e9 tr\u00e8s efficace pour plusieurs applications, aidant les utilisateurs non seulement \u00e0 apprendre \u00e0 faire quelque chose de mani\u00e8re plus facile et interactive, mais aussi \u00e0 pouvoir <\/span><b>cr\u00e9er de fortes habitudes<\/b><span style=\"font-weight: 400;\"> en les motivant \u00e0 se connecter tous les jours et<\/span><b> \u00e0 atteindre les objectifs fix\u00e9s<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">M\u00eame si de nos jours l<\/span><b>es applications sont le moyen le plus populaire et le plus efficace de jouer<\/b><span style=\"font-weight: 400;\">, les syst\u00e8mes non virtuels peuvent \u00e9galement tirer parti du pouvoir de la gamification et utiliser les applications comme un outil compl\u00e9mentaire.<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">Quelle est la valeur ajout\u00e9e de la Gamification dans le Secteur de l&rsquo;\u00c9nergie ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Le d\u00e9sir, et souvent la n\u00e9cessit\u00e9, pour les organisations, les propri\u00e9taires, les entreprises et les grandes industries de lutter contre le gaspillage d&rsquo;\u00e9nergie ou de r\u00e9duire simplement les niveaux d&rsquo;\u00e9nergie consomm\u00e9s s\u2019intensifie \u00e0 mesure que les prix de l&rsquo;\u00e9nergie et les pr\u00e9occupations concernant l&rsquo;environnement augmentent.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La question de savoir quand l&rsquo;\u00e9nergie consomm\u00e9e peut \u00eatre consid\u00e9r\u00e9e comme un gaspillage est quelque chose de plut\u00f4t subjectif, car chaque organisation a des besoins diff\u00e9rents en mati\u00e8re d&rsquo;\u00e9nergie. Par exemple, un fabricant peut avoir besoin de consommer beaucoup plus d&rsquo;\u00e9nergie en 4 heures de travail qu&rsquo;un grand magasin.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La difficult\u00e9, lorsqu&rsquo;il s&rsquo;agit de d\u00e9terminer si la consommation d&rsquo;\u00e9nergie est sup\u00e9rieure aux besoins, est que cette connaissance n&rsquo;est pas toujours disponible et que l&rsquo;on craint souvent de r\u00e9duire l&rsquo;\u00e9nergie utilis\u00e9e de fa\u00e7on peu op\u00e9rationnelle et efficace.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C&rsquo;est l\u00e0 qu&rsquo;intervient la <\/span><b>gamification dans l&rsquo;industrie de l&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\">, en donnant aux utilisateurs, c&rsquo;est-\u00e0-dire \u00e0 ceux qui consomment de l&rsquo;\u00e9nergie, la possibilit\u00e9 de savoir quand leurs niveaux de consommation d&rsquo;\u00e9nergie se situent dans les bonnes moyennes, et en les aidant \u00e0 <\/span><b>changer leurs comportements de consommation d&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\"> et \u00e0 acqu\u00e9rir un sentiment d&rsquo;accomplissement.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il existe d\u00e9j\u00e0 des outils, et plus pr\u00e9cis\u00e9ment des <\/span><a href=\"http:\/\/www.dexma.com\/fr\/quest-ce-que-la-plateforme-dexma\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Logiciels de Gestion de l&rsquo;\u00c9nergie (SGE), tels que la plateforme DEXMA <\/b><\/a><span style=\"font-weight: 400;\">qui fait d\u00e9j\u00e0 un excellent travail de collecte des donn\u00e9es des compteurs intelligents et autres appareils, et qui les retranscrit de mani\u00e8re intuitive afin que vous puissiez d\u00e9tecter les inefficacit\u00e9s, analyser les donn\u00e9es et optimiser votre consommation d&rsquo;\u00e9nergie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, le recours \u00e0 un SGE n&rsquo;est pas toujours aussi efficace que nous le souhaiterions pour \u00e9conomiser de l&rsquo;\u00e9nergie, car la consommation d&rsquo;\u00e9nergie, et surtout <\/span><b>l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, d\u00e9pend encore beaucoup du<\/b><a href=\"https:\/\/get.dexma.com\/le-facteur-humain-dans-la-gestion-energetique\" target=\"_blank\" rel=\"noopener noreferrer\"><b> comportement des consommateurs<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><b>La gamification d&rsquo;un logiciel de gestion de l&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\">, ou la mise en \u0153uvre de solutions d\u00e9j\u00e0 existantes qui utilisent la gamification pour aider les utilisateurs \u00e0 <\/span><b>cr\u00e9er de meilleures habitudes de consommation d&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\"> sont un moyen efficace qui devrait \u00eatre explor\u00e9 en amont<\/span><b> afin d&rsquo;atteindre les objectifs d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique des industries et des particuliers<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">4 Conseils sur la mise en \u0153uvre de la Gamification pour accro\u00eetre l&rsquo;Engagement des Consommateurs d&rsquo;\u00c9nergie<\/span><\/h2>\n<p><b>L&rsquo;un des grands avantages de la mise en \u0153uvre de la gamification dans le contexte de l&rsquo;industrie \u00e9nerg\u00e9tique <\/b><span style=\"font-weight: 400;\">est que, m\u00eame s&rsquo;il y a encore des d\u00e9fis \u00e0 relever pour d\u00e9terminer quand la quantit\u00e9 d&rsquo;\u00e9nergie est appropri\u00e9e ou non, <\/span><b>les objectifs sont assez clairs<\/b><span style=\"font-weight: 400;\">, ce qui facilite l&rsquo;application des r\u00e9compenses et des d\u00e9fis \u00e0 cet \u00e9gard.<\/span><\/p>\n<p><span style=\"color: #003b6f;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-size: 20px;\"><strong>1.<\/strong> <\/span><\/span><\/span><\/span><span style=\"font-weight: 400;\">Tout d&rsquo;abord, l&rsquo;organisation ou l&rsquo;individu doit pouvoir <\/span><span style=\"color: #003b6f;\"><b>d\u00e9terminer la quantit\u00e9 d&rsquo;\u00e9nergie n\u00e9cessaire <\/b><\/span><span style=\"font-weight: 400;\">pour pouvoir continuer \u00e0 exercer ses activit\u00e9s sans devoir modifier ou r\u00e9duire sa productivit\u00e9.<\/span><\/p>\n<p><b><span style=\"color: #003b6f;\"><span style=\"font-weight: 400;\"><span style=\"font-size: 20px;\"><strong>2.<\/strong> <\/span><\/span><\/span><\/b><span style=\"font-weight: 400;\">Une fois que cela a \u00e9t\u00e9 d\u00e9termin\u00e9, il est possible de <\/span><span style=\"color: #003b6f;\"><b>fixer des objectifs clairs sur l&rsquo;application ou le syst\u00e8me \u201cgamifi\u00e9\u201d<\/b><\/span><span style=\"font-weight: 400;\">, et de permettre aux utilisateurs de mieux suivre leurs habitudes de consommation d&rsquo;\u00e9nergie et d&rsquo;\u00e9tablir des d\u00e9fis efficaces qui peuvent les maintenir motiv\u00e9s.<\/span><\/p>\n<p><b><span style=\"color: #003b6f;\"><span style=\"font-weight: 400;\"><span style=\"font-size: 20px;\"><strong>3.<\/strong> <\/span><\/span><\/span><\/b><span style=\"color: #003b6f;\"><b>Le partage des r\u00e9sultats <\/b><\/span><span style=\"font-weight: 400;\">est un autre facteur important qui peut r\u00e9ellement stimuler la motivation des personnes engag\u00e9es dans un projet d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, car cela motive davantage ceux qui participent au jeu de la gestion de l&rsquo;\u00e9nergie, et encourage une concurrence saine ainsi que la coop\u00e9ration entre les utilisateurs.<\/span><\/p>\n<p><b><span style=\"color: #003b6f;\"><span style=\"font-weight: 400;\"><span style=\"font-size: 20px;\"><strong>4.<\/strong> <\/span><\/span><\/span><\/b><span style=\"color: #003b6f;\"><b>L&rsquo;introduction d&rsquo;une monnaie virtuelle<\/b><\/span><span style=\"font-weight: 400;\"> que l&rsquo;on peut gagner en \u00e9tant constant sur les objectifs de consommation d&rsquo;\u00e9nergie fix\u00e9s, en donnant aux utilisateurs des pi\u00e8ces ou des jetons qu&rsquo;ils peuvent \u00e9changer pour obtenir certains avantages, telle qu\u2019une r\u00e9duction sur leur facture d\u2019\u00e9lectricit\u00e9, pouvoir obtenir des services personnalis\u00e9s qui rendent l&rsquo;exp\u00e9rience plus personnalis\u00e9e, est un autre excellent outil pour <\/span><a href=\"https:\/\/get.dexma.com\/investissement-mesures-efficacite-energetique-webinar\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">encourager la mise en place de mesures d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans l&rsquo;ensemble, il est important de comprendre le public cible de l&rsquo;application ou du syst\u00e8me. En d&rsquo;autres termes, il s&rsquo;agit de savoir qui seront les consommateurs. Cela permettra de faciliter la prise de d\u00e9cisions sur la fa\u00e7on d\u2019impl\u00e9menter la solution \u201cgamifi\u00e9e\u201d afin que davantage d&rsquo;utilisateurs en profitent et, par cons\u00e9quent, \u00e0 ce qu&rsquo;ils <\/span><b>restent engag\u00e9s de mani\u00e8re p\u00e9renne<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">Les d\u00e9fis de la Gamification dans la r\u00e9duction de la Consommation d&rsquo;\u00c9nergie<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Comme mentionn\u00e9 pr\u00e9c\u00e9demment, l&rsquo;un des principaux obstacles \u00e0 la gestion de l&rsquo;\u00e9nergie, et donc \u00e0 la gamification, est le fait que l&rsquo;\u00e9nergie est consomm\u00e9e de nombreuses mani\u00e8res diff\u00e9rentes : selon les besoins \u00e9nerg\u00e9tiques de chaque appareil, ainsi qu\u2019en fonction des profils des consommateurs.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En ce sens, ce pourrait \u00eatre l&rsquo;un des premiers d\u00e9fis \u00e0 relever lors de l&rsquo;application de la gamification dans le secteur de l&rsquo;\u00e9nergie, car il serait <\/span><b>n\u00e9cessaire de conna\u00eetre certaines informations au pr\u00e9alable<\/b><span style=\"font-weight: 400;\">, comme <\/span><b>la consommation des appareils utilis\u00e9s par le consommateur<\/b><span style=\"font-weight: 400;\">, afin de fixer des objectifs appropri\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, les exigences globales d&rsquo;une entreprise ou d&rsquo;une industrie en mati\u00e8re d&rsquo;\u00e9nergie sont des \u00e9l\u00e9ments qu&rsquo;il convient de conna\u00eetre, afin de pouvoir fixer des objectifs. Il est donc utile d&rsquo;utiliser un SGE, car on ignore souvent pourquoi et o\u00f9 nous consommons plus d&rsquo;\u00e9nergie que n\u00e9cessaire.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, un<\/span><a href=\"http:\/\/www.dexma.com\/news-en\/h2020-feedback-energy-efficiency-gamification\/\" target=\"_blank\" rel=\"noopener noreferrer\"> <b>logiciel de gestion de l&rsquo;\u00e9nergie int\u00e9grant la gamification (article en anglais)<\/b><\/a><span style=\"font-weight: 400;\"> peut fixer ces objectifs en fonction des nouvelles informations qu&rsquo;un Gestionnaire de l&rsquo;\u00c9nergie obtient au fur et \u00e0 mesure que des donn\u00e9es sont collect\u00e9es, ce qui le rend plus efficace et le transforme en une solution \u00e9volutive, qui peut cr\u00e9er un engagement plus durable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Exploiter la puissance de techniques telles que la ludification ou gamification, en modifiant les habitudes ou en renfor\u00e7ant les meilleures d&rsquo;entre elles de mani\u00e8re ludique, est une fa\u00e7on d&rsquo;atteindre l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique sans se limiter \u00e0 suivre des r\u00e8gles de consommation, mais en adaptant r\u00e9ellement nos comportements.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si vous souhaitez \u00eatre au courant des derni\u00e8res tendances technologiques, nous vous recommandons de regarder l&rsquo;enregistrement de notre webinaire (en anglais) sur la Gamification dans le Secteur de l&rsquo;\u00c9nergie :<\/span><br \/>\n<!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-d02d5b44-ba9f-414f-bfbc-2448f322e104\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-d02d5b44-ba9f-414f-bfbc-2448f322e104\" class=\"hs-cta-node hs-cta-d02d5b44-ba9f-414f-bfbc-2448f322e104\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/d02d5b44-ba9f-414f-bfbc-2448f322e104\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-d02d5b44-ba9f-414f-bfbc-2448f322e104\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/d02d5b44-ba9f-414f-bfbc-2448f322e104.png\" alt=\"New call-to-action\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Par ses vertus p\u00e9dagogiques et sa dimension ludique, le jeu est un puissant levier de sensibilisation \u00e0 des th\u00e9matiques complexes. Ces derni\u00e8res ann\u00e9es ce principe a pris une importance nouvelle gr\u00e2ce \u00e0 l\u2019expansion des nouvelles technologies. En effet, qu\u2019il s\u2019agisse de jeux-concours, d\u2019applications pour faire d\u00e9couvrir un secteur, de jeux s\u00e9rieux (serious games)&#8230;, la fronti\u00e8re [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":38653,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie\" \/>\n<meta property=\"og:description\" content=\"Par ses vertus p\u00e9dagogiques et sa dimension ludique, le jeu est un puissant levier de sensibilisation \u00e0 des th\u00e9matiques complexes. Ces derni\u00e8res ann\u00e9es ce principe a pris une importance nouvelle gr\u00e2ce \u00e0 l\u2019expansion des nouvelles technologies. En effet, qu\u2019il s\u2019agisse de jeux-concours, d\u2019applications pour faire d\u00e9couvrir un secteur, de jeux s\u00e9rieux (serious games)&#8230;, la fronti\u00e8re [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-19T07:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie\",\"datePublished\":\"2020-06-19T07:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/\"},\"wordCount\":1548,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Blog-Posts-Covers-5-New-Branding-4.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/\",\"name\":\"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Blog-Posts-Covers-5-New-Branding-4.png\",\"datePublished\":\"2020-06-19T07:13:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Blog-Posts-Covers-5-New-Branding-4.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Blog-Posts-Covers-5-New-Branding-4.png\",\"width\":840,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/","og_locale":"fr_FR","og_type":"article","og_title":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie","og_description":"Par ses vertus p\u00e9dagogiques et sa dimension ludique, le jeu est un puissant levier de sensibilisation \u00e0 des th\u00e9matiques complexes. Ces derni\u00e8res ann\u00e9es ce principe a pris une importance nouvelle gr\u00e2ce \u00e0 l\u2019expansion des nouvelles technologies. En effet, qu\u2019il s\u2019agisse de jeux-concours, d\u2019applications pour faire d\u00e9couvrir un secteur, de jeux s\u00e9rieux (serious games)&#8230;, la fronti\u00e8re [&hellip;]","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2020-06-19T07:13:57+00:00","og_image":[{"width":840,"height":472,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie","datePublished":"2020-06-19T07:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/"},"wordCount":1548,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/","name":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png","datePublished":"2020-06-19T07:13:57+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2020\/06\/Blog-Posts-Covers-5-New-Branding-4.png","width":840,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/gamification-un-outil-pour-renforcer-lengagement-des-consommateurs-denergie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Gamification : Un Outil pour Renforcer l&amp;rsquo;Engagement des Consommateurs d&amp;rsquo;\u00c9nergie"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38652"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/38653"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}