


{"id":38596,"date":"2021-01-22T09:39:31","date_gmt":"2021-01-22T08:39:31","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/"},"modified":"2021-01-22T09:39:31","modified_gmt":"2021-01-22T08:39:31","slug":"la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/","title":{"rendered":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Les fournisseurs d&rsquo;\u00e9nergie sont confront\u00e9s depuis quelques ann\u00e9es \u00e0 un d\u00e9fi majeur, \u00e0 savoir un taux \u00e9lev\u00e9 d\u2019attrition ou de \u201cswitch\u201d de leurs clients B2B.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans cet article, nous vous expliquons comment le taux d\u2019attrition affecte les utilities, quelle est son \u00e9volution sur le march\u00e9 de l&rsquo;\u00e9nergie et comment le r\u00e9duire.<\/span><\/p>\n<p><!--more--><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Quel est le Probl\u00e8me ? <\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Les op\u00e9rateurs<\/span> <span style=\"font-weight: 400;\">d\u00e9taillants en \u00e9nergie (\u00e9galement appel\u00e9s fournisseurs), tout comme les distributeurs et les producteurs, sont confront\u00e9s \u00e0 de nombreux d\u00e9fis li\u00e9s \u00e0 la r\u00e9volution \u00e9nerg\u00e9tique au sens large.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, la privatisation et la lib\u00e9ralisation de ces services au cours des derni\u00e8res d\u00e9cennies en Europe a consid\u00e9rablement accru la concurrence et a encourag\u00e9 de nouveaux acteurs innovants \u00e0 entrer sur le march\u00e9 de d\u00e9tail de l&rsquo;\u00e9lectricit\u00e9 ou du gaz.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, les consommateurs, en particulier pour les locaux \u00e0 usage non-domestique<\/span> <span style=\"font-weight: 400;\">\u00a0(ou inter-entreprises), ont b\u00e9n\u00e9fici\u00e9 du choix et de la facilit\u00e9 de<\/span><b> changer de fournisseur, ce qui a encourag\u00e9 une forte concurrence.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En r\u00e9ponse, les fournisseurs se sont engag\u00e9s dans une course vers \u201cle bas\u00a0\u00bb afin d&rsquo;optimiser leurs prix pour l&rsquo;\u00e9lectricit\u00e9 et le gaz en tant que produits de base. Il n&rsquo;est pas surprenant que cela se soit r\u00e9v\u00e9l\u00e9 insoutenable pour de nombreux op\u00e9rateurs d\u00e9taillants, qui se tournent maintenant vers des moyens plus innovants afin de fid\u00e9liser leur client\u00e8le existante et attirer de nouveaux clients.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Comment en Sommes-nous Arriv\u00e9s l\u00e0 ? Aper\u00e7u sur la Lib\u00e9ralisation du March\u00e9 de l&rsquo;\u00c9nergie<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En Europe, les march\u00e9s de l&rsquo;\u00e9lectricit\u00e9 et du gaz \u00e9taient g\u00e9n\u00e9ralement des monopoles au sein de chaque \u00c9tat membre, comprenant la production, la distribution et la vente au d\u00e9tail. Un processus de lib\u00e9ralisation a commenc\u00e9 dans de nombreux pays \u00e0 la fin des ann\u00e9es 1990, lorsque l&rsquo;Union Europ\u00e9enne a introduit de nouvelles directives pour encourager la baisse des prix de l&rsquo;\u00e9nergie et am\u00e9liorer le service aux consommateurs.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cons\u00e9quence, les monopoles \u00e9nerg\u00e9tiques existants ont \u00e9t\u00e9 divis\u00e9s. Dans la plupart des cas, les branches de distribution et de transmission sont rest\u00e9es des monopoles naturels, appartenant \u00e0 des int\u00e9r\u00eats priv\u00e9s, mais soumis \u00e0 la r\u00e9glementation du march\u00e9, tandis que les branches de production et de vente au d\u00e9tail ont \u00e9t\u00e9 privatis\u00e9es et lib\u00e9ralis\u00e9es. Cela a permis \u00e0 de nouveaux producteurs d&rsquo;entrer sur le march\u00e9 \u00e0 un moment o\u00f9 les nouvelles technologies renouvelables \u00e9taient commercialis\u00e9es.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De surcro\u00eet, les op\u00e9rateurs d\u00e9taillant, qui \u00e9taient auparavant limit\u00e9s par les fronti\u00e8res politiques, pouvaient d\u00e8s lors op\u00e9rer dans de nombreuses r\u00e9gions d&rsquo;Europe, et ont \u00e9t\u00e9 confront\u00e9s \u00e0 une augmentation du nombre de <\/span><b>nouvelles entreprises entrant \u00e9galement sur le march\u00e9 de d\u00e9tail de l&rsquo;\u00e9nergie.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ce processus de lib\u00e9ralisation du march\u00e9 de d\u00e9tail de l&rsquo;\u00e9nergie en est \u00e0 diff\u00e9rentes \u00e9tapes en Europe, avec une mise en \u0153uvre qui varie entre les \u00c9tats membres et les r\u00e9gions. Alors que la Bulgarie et Malte fonctionnent toujours dans une situation de monopole, la majorit\u00e9 des autres \u00c9tats membres s&rsquo;efforcent d&rsquo;\u00e9tablir ou ont d\u00e9j\u00e0 \u00e9tabli des march\u00e9s matures offrant un choix de 100 op\u00e9rateurs d\u00e9taillants aux consommateurs.\u00a0<\/span><b><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Toutefois, nombre de ces nouveaux fournisseurs ne d\u00e9tiennent encore qu&rsquo;une petite part de march\u00e9, bien que <\/span><b>les tendances dans les pays matures tels que le Royaume-Uni montrent une baisse significative de la part de march\u00e9 des plus grands fournisseurs <\/b><span style=\"font-weight: 400;\">(ou des op\u00e9rateurs historiques).\u00a0\u00a0<\/span><b><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Le graphique suivant montre le nombre de principaux op\u00e9rateurs d\u00e9taillants d&rsquo;\u00e9lectricit\u00e9 (d\u00e9finis comme ayant une part de march\u00e9 sup\u00e9rieure \u00e0 5 %) et leur part de march\u00e9 cumul\u00e9e.\u00a0 On constate que sur de nombreux march\u00e9s europ\u00e9ens, les faibles parts de march\u00e9 cumul\u00e9es de ces principaux op\u00e9rateurs d\u00e9taillants d&rsquo;\u00e9lectricit\u00e9 est due aux nouveaux venus dans le secteur, plus petits et souvent plus innovants, qui suscitent un<\/span><b> int\u00e9r\u00eat et un engagement \u00e9lev\u00e9s de la part des consommateurs<\/b>.<\/p>\n<p><a href=\"https:\/\/ec.europa.eu\/eurostat\/statistics-explained\/pdfscache\/9144.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32914\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Number-of-main-electricity-retailers-2018.png\" alt=\"Number of main electricity retailers and their cumulative market share 2018\" width=\"555\" height=\"312\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Number-of-main-electricity-retailers-2018.png 618w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Number-of-main-electricity-retailers-2018-300x168.png 300w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/span><\/i><\/a><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Taux de \u00ab\u00a0Switch\u00a0\u00bb \u00c9lev\u00e9 : Le D\u00e9fi des Fournisseurs d&rsquo;\u00c9nergie<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">L&rsquo;explosion du nombre de fournisseurs en \u00e9nergie sur les march\u00e9s europ\u00e9ens lib\u00e9ralis\u00e9s arriv\u00e9s \u00e0 maturit\u00e9 a donn\u00e9 lieu \u00e0 un paysage <\/span><b>hautement concurrentiel<\/b><span style=\"font-weight: 400;\">, tant pour l&rsquo;\u00e9lectricit\u00e9 que pour le gaz.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour de nombreux clients, l&rsquo;id\u00e9e de faire des achats et de <\/span><b>passer d&rsquo;un op\u00e9rateur d\u00e9taillant d&rsquo;\u00e9nergie \u00e0 l&rsquo;autre est devenue la norme.\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Le graphique suivant montre que ce ph\u00e9nom\u00e8ne se produit pour une partie importante des consommateurs et que la plupart des pays europ\u00e9ens en font l&rsquo;exp\u00e9rience.<\/span><\/p>\n<p><a href=\"https:\/\/www.ceer.eu\/documents\/104400\/6287243\/C18-MRM-93-03_Retail_Market_Monitoring_Report_for+publication_final.pdf\/e02fea9a-9a74-f9af-475c-f183db4f449e\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"https:\/\/www.ceer.eu\/documents\/104400\/6287243\/C18-MRM-93-03_Retail_Market_Monitoring_Report_for+publication_final.pdf\/e02fea9a-9a74-f9af-475c-f183db4f449e aligncenter wp-image-32919\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Switching-rates-for-electricity-non-household-customer-2017.png\" alt=\"Switching rates for electricity non-household customer 2017 UE\" width=\"554\" height=\"527\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Switching-rates-for-electricity-non-household-customer-2017.png 641w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Switching-rates-for-electricity-non-household-customer-2017-300x285.png 300w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/span><\/i><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Si nous prenons l&rsquo;exemple du Royaume-Uni, le nombre de clients domestiques et professionnels qui changent de fournisseur a plus que doubl\u00e9 entre 2014 et 2019. Une culture de m\u00e9fiance \u00e0 l&rsquo;\u00e9gard des utilities traditionnelles, associ\u00e9e \u00e0 des syst\u00e8mes de tarification innovants et \u00e0 des offres de la part des nouveaux venus, a fait que plus de 50% de ces changements de fournisseur se font en faveur de fournisseurs autres que le groupe des<\/span> <a href=\"https:\/\/en.wikipedia.org\/wiki\/Big_Six_energy_suppliers\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">\u00ab\u00a0Big 6\u00a0\u00bb<\/span><\/a><span style=\"font-weight: 400;\">\u00a0(article en anglais).\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le tableau ci-dessous nous montre l\u2019\u00e9volution de ces changements au cours des deux derni\u00e8res ann\u00e9es. On peut constater que le changement de fournisseur ou \u201cswitch\u201d est une r\u00e9alit\u00e9 constante chez les op\u00e9rateurs d\u00e9taillants, et qu\u2019ils doivent rester \u00e0 la hauteur de la concurrence, sous peine de perdre des parts de march\u00e9.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.energy-uk.org.uk\/publication.html?task=file.download&amp;id=7733\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32924 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Graphic-number-of-switches-per-month-UK.png\" alt=\" of switches per month UK - Graphic\" width=\"624\" height=\"364\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Graphic-number-of-switches-per-month-UK.png 624w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Graphic-number-of-switches-per-month-UK-300x175.png 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/span><\/i><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Bien que cette situation ait apport\u00e9 des avantages aux consommateurs sous la forme de choix et de prix tr\u00e8s comp\u00e9titifs, elle a \u00e9galement entra\u00een\u00e9 <\/span><b>une baisse des marges de b\u00e9n\u00e9fices pour de nombreux fournisseurs<\/b><span style=\"font-weight: 400;\">, ainsi qu&rsquo;une volatilit\u00e9 du march\u00e9. Certains fournisseurs quittant le march\u00e9 chaque ann\u00e9e.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le r\u00e9gulateur du march\u00e9 de l&rsquo;\u00e9nergie britannique, l&rsquo;OFGEM, <\/span><b>estime que les marges de b\u00e9n\u00e9fices des grands fournisseurs d&rsquo;\u00e9nergie au Royaume-Uni sont tomb\u00e9es \u00e0 3% en moyenne en 2018.<\/b><span style=\"font-weight: 400;\">\u00a0 Cela a entra\u00een\u00e9 une r\u00e9duction g\u00e9n\u00e9rale des co\u00fbts, qui a souvent des r\u00e9percussions sur les services d\u2019attention clients et entra\u00eene des erreurs dans les rapports et la facturation, etc.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cons\u00e9quence, surtout pour les clients professionnels, on a constat\u00e9 un nombre croissant de plaintes et une augmentation du m\u00e9contentement des clients. Cela est particuli\u00e8rement vrai pour les tr\u00e8s petites entreprises, qui n&rsquo;ont pas le pouvoir d&rsquo;achat des grands clients industriels et paient donc souvent des prix beaucoup plus \u00e9lev\u00e9s.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ces faibles marges de b\u00e9n\u00e9fices signifient \u00e9galement que le co\u00fbt d&rsquo;acquisition de nouveaux clients doit \u00eatre faible et que l\u2019op\u00e9rateur d\u00e9taillant doit \u00eatre s\u00fbr de conserver un nouveau client pendant une longue p\u00e9riode, afin que cette acquisition soit rentable \u00e0 long terme.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Comment Am\u00e9liorer la Satisfaction des Clients et R\u00e9duire le Taux de Changement de Fournisseur (r\u00e9siliations)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Jusqu&rsquo;\u00e0 pr\u00e9sent, nous avons \u00e9tabli que de nombreux fournisseurs en Europe sont confront\u00e9s \u00e0 une concurrence \u00e9lev\u00e9e et \u00e0 une pression pour<\/span><b> am\u00e9liorer la satisfaction des clients\u00a0 afin d&rsquo;\u00e9viter le ph\u00e9nom\u00e8ne de \u201cswitching\u201d<\/b><span style=\"font-weight: 400;\"> (changement de fournisseur).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C\u2019est pourquoi de nombreuses utilities se donnent pour mission de trouver de nouvelles solutions cr\u00e9atives afin de maintenir la satisfaction des clients. Cela implique d&rsquo;utiliser les nouvelles technologies qui sont actuellement d\u00e9ploy\u00e9es dans le secteur de l&rsquo;\u00e9nergie, par exemple la production d&rsquo;\u00e9nergie propre et les compteurs intelligents.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019investissement dans de nouveaux actifs technologiques propres, tels que l&rsquo;\u00e9nergie solaire, la mobilit\u00e9 \u00e9lectrique et l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, change le visage des op\u00e9rateurs d\u00e9taillants d&rsquo;\u00e9nergie qui, dans de nombreux cas, ont traditionnellement \u00e9t\u00e9 les producteurs de charbon et de gaz.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela contribue \u00e0 changer de fa\u00e7on positive l&rsquo;opinion et la perception des clients.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;utilisation de <\/span><a href=\"http:\/\/www.dexma.com\/fr\/blog-fr\/comment-le-big-data-et-la-data-science-peuvent-ameliorer-les-relations-avec-vos-clients\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>donn\u00e9es provenant de compteurs intelligents<\/b><\/a><span style=\"font-weight: 400;\"> et d&rsquo;autres sources (telles que les donn\u00e9es m\u00e9t\u00e9orologiques, les informations sur les b\u00e2timents, etc.) est \u00e9galement utilis\u00e9e par les fournisseurs dans le but d\u2019<\/span><b>am\u00e9liorer le service clients<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Par exemple, l&rsquo;utilisation d&rsquo;informations sur les clients pour <\/span><a href=\"http:\/\/www.dexma.com\/fr\/plateforme-dexma-detect\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">fournir des conseils et des recommandations visant \u00e0 am\u00e9liorer l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique<\/span><\/a><span style=\"font-weight: 400;\">, peut aider le consommateur \u00e0 r\u00e9duire sa facture \u00e9nerg\u00e9tique et \u00e0 r\u00e9tablir la confiance avec son fournisseur.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bien qu&rsquo;\u00e0 premi\u00e8re vue, cela puisse sembler d\u00e9routant puisque \u00e7a suppose une r\u00e9duction des revenus des fournisseurs, il faut juste rappeler que les marges de b\u00e9n\u00e9fices dans la vente pure d&rsquo;\u00e9nergie sont tr\u00e8s serr\u00e9es pour de nombreux op\u00e9rateurs d\u00e9taillants. De ce fait, la perte de profit dans la vente du produit \u00e9nerg\u00e9tique est facilement couverte par la fid\u00e9lisation des clients et la possibilit\u00e9 de vendre de nouveaux produits \u00e0 l&rsquo;avenir.\u00a0<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3\" class=\"hs-cta-node hs-cta-ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/ac9aa4b9-d3e9-4cc5-b75b-1a6bbb2ed4b3.png\" alt=\"Fournisseur d'\u00e9nergie le nouveau gestionnaire de l'\u00e9nergie du client\" \/><\/a><\/span><\/span><\/p>\n<h2><span style=\"color: #003b6f;\"><b><span style=\"font-weight: 400;\">Comment Offrir de Nouvelles Sources de Revenus<\/span><\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En raison de la <\/span><b>faible rentabilit\u00e9 de la vente d&rsquo;\u00e9nergie en tant que produit de base sur un march\u00e9 lib\u00e9ralis\u00e9<\/b><span style=\"font-weight: 400;\">, de nombreuses utilities europ\u00e9ennes se tournent vers des <\/span><a href=\"http:\/\/www.dexma.com\/fr\/blog-fr\/top-5-services-que-les-utilities-doivent-offrir-a-leur-clients\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">produits et des services \u00e0 valeur ajout\u00e9e suppl\u00e9mentaires pour compl\u00e9ter leurs b\u00e9n\u00e9fices<\/span><\/a><span style=\"font-weight: 400;\"> et cr\u00e9er de nouvelles sources de revenus. Cela peut se faire par une croissance organique interne ou par l&rsquo;acquisition d&rsquo;entreprises offrant d\u00e9j\u00e0 ce type de produits et de services.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parmi les exemples de ces <\/span><b>nouvelles sources de revenus<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">On peut citer les conseils en mati\u00e8re d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique et la mise en \u0153uvre de solutions,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les installations d&rsquo;infrastructures de mobilit\u00e9 \u00e9lectrique,\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les solutions d&rsquo;autoconsommation telles que les panneaux solaires et les batteries,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ainsi que l&rsquo;installation de nouvelles technologies pour assurer le suivi et l&rsquo;optimisation du fonctionnement des b\u00e2timents et des maisons.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Si les fournisseurs ont identifi\u00e9 des options technologiques matures et un int\u00e9r\u00eat suffisant de la part des consommateurs, ces solutions ont permis, \u00e0 des degr\u00e9s divers, de d\u00e9gager de nouveaux revenus importants.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, les utilities disposent de plus en plus de nouveaux outils pour r\u00e9ussir cette transition vers de nouvelles sources de revenus.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Par exemple, les fournisseurs qui ont re\u00e7u l&rsquo;autorisation r\u00e9glementaire d&rsquo;utiliser les donn\u00e9es de facturation de leurs clients, peuvent utiliser ces derni\u00e8res afin d\u2019analyser et identifier les services et produits les plus appropri\u00e9s pour le client, gr\u00e2ce \u00e0 de <\/span><a href=\"http:\/\/www.dexma.com\/fr\/plateforme-dexma-detect\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>nouveaux outils d&rsquo;intelligence artificielle<\/b><\/a><span style=\"font-weight: 400;\">.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela permet de r\u00e9duire les co\u00fbts de marketing et de vente dans le processus d&rsquo;acquisition de clients. Les m\u00eames informations, en particulier lorsqu&rsquo;elles sont utilis\u00e9es avec les donn\u00e9es des nouveaux compteurs intelligents, peuvent \u00eatre utilis\u00e9es par les \u00e9quipes de services clients et assistance pour vendre de nouveaux produits et ainsi apporter une solution plus adapt\u00e9e et plus approfondie aux probl\u00e8mes des clients.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Conclusion<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Nous avons vu que les march\u00e9s de l&rsquo;\u00e9nergie en Europe ont \u00e9t\u00e9 radicalement r\u00e9volutionn\u00e9s au cours des derni\u00e8res d\u00e9cennies, depuis que la lib\u00e9ralisation a \u00e9t\u00e9 introduite dans de nombreux pays.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cons\u00e9quence, les nouveaux fournisseurs d&rsquo;\u00e9nergie ind\u00e9pendants ont d\u00fb faire face \u00e0 une concurrence importante de la part de <\/span><b>nouveaux acteurs qui proposent des produits modernes et innovants<\/b><span style=\"font-weight: 400;\">. Cela a conduit au ph\u00e9nom\u00e8ne du \u201cswitching\u201d (r\u00e9siliation des contrats), o\u00f9 de nombreux clients choisissent fr\u00e9quemment un nouveau fournisseur qui peut offrir des services \u00e0 moindre co\u00fbt.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Afin de rester comp\u00e9titifs et de conserver une part de march\u00e9 significative, les utilities ont \u00e9t\u00e9 contraintes de r\u00e9volutionner leurs techniques de fid\u00e9lisation de la client\u00e8le. Elles proposent d\u00e9sormais une gamme de nouveaux produits et services li\u00e9s \u00e0 l&rsquo;\u00e9nergie, qui constituent de nouvelles sources de revenus pour leurs activit\u00e9s.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est essentiel, toutefois, d&rsquo;utiliser les bons outils afin de garantir la viabilit\u00e9 et la survie \u00e0 long terme de nombreux op\u00e9rateurs d\u00e9taillants en \u00e9nergie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00e9couvrez les outils qui aideront votre compagnie d&rsquo;\u00e9lectricit\u00e9 \u00e0 r\u00e9duire le taux d\u2019attrition sur les march\u00e9s B2B. T\u00e9l\u00e9chargez <\/span><a href=\"https:\/\/get.dexma.com\/devenir-gestionnaire-denergie-du-client-final\" target=\"_blank\" rel=\"noopener noreferrer\"><b>le guide sp\u00e9cialis\u00e9 pour les Utilities<\/b><\/a><span style=\"font-weight: 400;\"> et d\u00e9couvrez quels nouveaux services \u00e0 valeur ajout\u00e9e vous pouvez offrir \u00e0 vos clients !<\/span><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32966 alignleft\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1-150x150.png\" alt=\"Mio Dart\" width=\"126\" height=\"126\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1-150x150.png 150w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1-300x300.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1.png 500w\" sizes=\"auto, (max-width: 126px) 100vw, 126px\" \/><i><span style=\"font-weight: 400;\"><em><strong>Note de la R\u00e9daction:<\/strong> cet article original a \u00e9t\u00e9 publi\u00e9 ici avec l\u2019aimable autorisation de son auteur, <strong>Mio Dart<\/strong>.\u00a0<\/em><\/span><\/i><\/p>\n<p style=\"font-size: 13px;\"><i><span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/mio-dart-b746105b\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mio Dart<\/a><\/strong> a fait partie de l&rsquo;\u00e9quipe DEXMA pendant 4 ans et a apport\u00e9 son expertise dans les domaines de l&rsquo;\u00e9nergie et de la vente.\u00a0<\/span><\/i><\/p>\n<hr \/>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-1dd07dda-809b-48fb-ac55-66d8c7c1f97f\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-1dd07dda-809b-48fb-ac55-66d8c7c1f97f\" class=\"hs-cta-node hs-cta-1dd07dda-809b-48fb-ac55-66d8c7c1f97f\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/1dd07dda-809b-48fb-ac55-66d8c7c1f97f\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-1dd07dda-809b-48fb-ac55-66d8c7c1f97f\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/1dd07dda-809b-48fb-ac55-66d8c7c1f97f.png\" alt=\"Fournisseur d'\u00e9nergie, devenez le gestionnaire dont vos client on besoin\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les fournisseurs d&rsquo;\u00e9nergie sont confront\u00e9s depuis quelques ann\u00e9es \u00e0 un d\u00e9fi majeur, \u00e0 savoir un taux \u00e9lev\u00e9 d\u2019attrition ou de \u201cswitch\u201d de leurs clients B2B.\u00a0 Dans cet article, nous vous expliquons comment le taux d\u2019attrition affecte les utilities, quelle est son \u00e9volution sur le march\u00e9 de l&rsquo;\u00e9nergie et comment le r\u00e9duire.<\/p>\n","protected":false},"author":39,"featured_media":36075,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B\" \/>\n<meta property=\"og:description\" content=\"Les fournisseurs d&rsquo;\u00e9nergie sont confront\u00e9s depuis quelques ann\u00e9es \u00e0 un d\u00e9fi majeur, \u00e0 savoir un taux \u00e9lev\u00e9 d\u2019attrition ou de \u201cswitch\u201d de leurs clients B2B.\u00a0 Dans cet article, nous vous expliquons comment le taux d\u2019attrition affecte les utilities, quelle est son \u00e9volution sur le march\u00e9 de l&rsquo;\u00e9nergie et comment le r\u00e9duire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T08:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B\",\"datePublished\":\"2021-01-22T08:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/\"},\"wordCount\":2196,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Switching-Rates-for-Utilities-.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/\",\"name\":\"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Switching-Rates-for-Utilities-.png\",\"datePublished\":\"2021-01-22T08:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Switching-Rates-for-Utilities-.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Switching-Rates-for-Utilities-.png\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/","og_locale":"fr_FR","og_type":"article","og_title":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B","og_description":"Les fournisseurs d&rsquo;\u00e9nergie sont confront\u00e9s depuis quelques ann\u00e9es \u00e0 un d\u00e9fi majeur, \u00e0 savoir un taux \u00e9lev\u00e9 d\u2019attrition ou de \u201cswitch\u201d de leurs clients B2B.\u00a0 Dans cet article, nous vous expliquons comment le taux d\u2019attrition affecte les utilities, quelle est son \u00e9volution sur le march\u00e9 de l&rsquo;\u00e9nergie et comment le r\u00e9duire.","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-01-22T08:39:31+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B","datePublished":"2021-01-22T08:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/"},"wordCount":2196,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/","name":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png","datePublished":"2021-01-22T08:39:31+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/01\/Switching-Rates-for-Utilities-.png","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Commercialisation de l&amp;rsquo;\u00c9nergie : Fid\u00e9lisez vos Clients B2B"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38596"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/36075"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}