


{"id":38575,"date":"2021-02-12T10:58:14","date_gmt":"2021-02-12T09:58:14","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/"},"modified":"2021-02-12T10:58:14","modified_gmt":"2021-02-12T09:58:14","slug":"mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/","title":{"rendered":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Imaginons que vous soyez responsable de l&rsquo;offre de nouveaux produits chez un fournisseur d&rsquo;\u00e9nergie ou que vous soyez responsable de l&rsquo;efficacit\u00e9 op\u00e9rationnelle dans une grande entreprise.\u00a0 Vous et votre \u00e9quipe avez d\u00e9cid\u00e9 de <\/span><b>faire de la gestion de l&rsquo;\u00e9nergie un nouveau domaine de croissance cl\u00e9 <\/b><span style=\"font-weight: 400;\">et\/ou de r\u00e9duire votre propre consommation d&rsquo;\u00e9nergie interne.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais par o\u00f9 commencer ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Que devez-vous pr\u00e9senter \u00e0 la direction g\u00e9n\u00e9rale pour \u00eatre s\u00fbr d\u2019arriver \u00e0 vos objectifs ?\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comment pouvez-vous \u00eatre certain que l&rsquo;approche que vous choisissez soit la correcte ?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous trouverez ci-dessous la r\u00e9ponse \u00e0 toutes ces questions.\u00a0<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Comme vous le savez probablement d\u00e9j\u00e0, il existe de nombreuses options qui peuvent sembler intimidantes. Cependant, nous avons r\u00e9dig\u00e9 cet article avec des conseils bas\u00e9s sur notre propre exp\u00e9rience de travail avec de nombreuses entreprises comme la v\u00f4tre.\u00a0 Nous esp\u00e9rons que vous le trouverez utile et n&rsquo;h\u00e9sitez pas \u00e0 nous contacter &#8211; nous serions heureux de partager nos connaissances, m\u00eame si ce n&rsquo;est que dans une conversation informelle.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pourquoi une utility voudrait-elle proposer des solutions de gestion de l&rsquo;\u00e9nergie ? Si vous souhaitez en savoir plus sur le taux de changement de fournisseur des clients B2B et sur la mani\u00e8re dont les op\u00e9rateurs d\u00e9taillants en \u00e9lectricit\u00e9 peuvent prendre de l&rsquo;avance sur la concurrence, nous vous recommandons cet <\/span><strong><a href=\"http:\/\/www.dexma.com\/fr\/blog-fr\/la-commercialisation-de-lenergie-fidelisez-vos-clients-b2b\/\" target=\"_blank\" rel=\"noopener noreferrer\">article<\/a><\/strong><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003b6f;\">Quelles sont mes options en mati\u00e8re de gestion de l&rsquo;\u00e9nergie ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si vous vous \u00eates fix\u00e9 des <\/span><strong><a href=\"http:\/\/www.dexma.com\/fr\/blog-fr\/objectifs-smart-pour-la-gestion-de-lenergie-modele-gratuit\/\" target=\"_blank\" rel=\"noopener noreferrer\">objectifs<\/a><\/strong><span style=\"font-weight: 400;\"> et que vous avez lu ce qu&rsquo;implique un projet de gestion de l&rsquo;\u00e9nergie, vous savez que vous aurez besoin de trois \u00e9l\u00e9ments principaux :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Des services de conseil en \u00e9nergie <\/b><span style=\"font-weight: 400;\">pour vous aider \u00e0 fixer des objectifs, \u00e0 surveiller\/analyser la consommation et \u00e0 proposer les meilleurs changements \u00e0 apporter.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Du mat\u00e9riel suppl\u00e9mentaire<\/b><span style=\"font-weight: 400;\"> pour une surveillance approfondie, non seulement de la consommation d&rsquo;\u00e9nergie, mais aussi du confort, de la qualit\u00e9 de l&rsquo;air, de la temp\u00e9rature, de l&rsquo;occupation, etc.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\"><strong>Un logiciel SGE<\/strong> pour fournir des capacit\u00e9s de surveillance et d&rsquo;analyse.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Comment choisir la meilleure approche pour chacun ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans le cas du conseil en gestion de l&rsquo;\u00e9nergie, vous devrez choisir entre une \u00e9quipe interne ou l&rsquo;externalisation vers une agence sp\u00e9cialis\u00e9e. Les agences externes font tr\u00e8s bien ce travail (c&rsquo;est leur gagne-pain), mais les \u00e9quipes internes connaissent peut-\u00eatre mieux votre organisation.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En g\u00e9n\u00e9ral, \u00e0 moins de disposer d&rsquo;une expertise interne, il est plus rentable d&rsquo;externaliser ce travail, surtout si les consultants peuvent offrir une sorte de garantie d&rsquo;\u00e9conomies.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En ce qui concerne le mat\u00e9riel et les compteurs pour le SGE, le plus important est de garder vos options ouvertes. Ne vous attachez pas \u00e0 un contrat d&rsquo;exclusivit\u00e9 avec un seul fournisseur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans le cas du logiciel SGE, cela devient un peu plus compliqu\u00e9. Il existe plusieurs options, chacune avec ses avantages et ses inconv\u00e9nients, et nous les examinerons plus en d\u00e9tail ci-dessous.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voici les trois principales approches :<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">D\u00e9velopper un syst\u00e8me de suivi\/analyse en interne \u00e0 partir de z\u00e9ro en utilisant vos ressources de d\u00e9veloppement internes.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Externaliser \u00e0 un grand fournisseur de solutions technologiques mondiales (pensez aux grands acteurs internationaux ou aux op\u00e9rateurs technologiques nationaux) pour d\u00e9velopper une solution \u00e0 partir de z\u00e9ro pour vous.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Externaliser et travailler en partenariat avec un fournisseur leader en SGE, ayant une expertise en la mati\u00e8re.<\/span><\/li>\n<\/ol>\n<h2><span style=\"font-weight: 400; color: #003b6f;\">Ce que j&rsquo;attends d&rsquo;un logiciel SGE<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Comme nous l&rsquo;avons vu, les approches pour choisir un logiciel SGE sont un peu plus compliqu\u00e9es que les autres composants, alors examinons chaque option en d\u00e9tail, et ce \u00e0 quoi vous devez penser pour prendre la bonne d\u00e9cision.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais dans un premier temps, voyons ce que vous attendez d&rsquo;un Software de Gestion de l&rsquo;\u00c9nergie. Bien s\u00fbr, cette liste peut changer en fonction de votre organisation, mais la plupart d&rsquo;entre elles devraient \u00eatre valables :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Une grande exp\u00e9rience utilisateur :<\/b><span style=\"font-weight: 400;\"> vous souhaitez que ce SGE vous apporte de la valeur (et\/ou \u00e0 vos clients) gr\u00e2ce \u00e0 une grande exp\u00e9rience utilisateur bas\u00e9e sur des moteurs de visualisation, des rapports et des alertes, qui soit \u00e0 jour avec les r\u00e9glementations (tarifs \u00e9nerg\u00e9tiques, normes d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, etc.) et qu\u2019il soit facile \u00e0 utiliser.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>A l&rsquo;\u00e9preuve du temps :<\/b><span style=\"font-weight: 400;\"> vous voulez que votre solution soit utile non seulement maintenant, mais aussi \u00e0 l&rsquo;avenir. Un outil qui s&rsquo;am\u00e9liore avec le temps, en ajoutant de nouvelles fonctionnalit\u00e9s et en am\u00e9liorant l&rsquo;exp\u00e9rience de l&rsquo;utilisateur, est essentiel.\u00a0<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Un facteur de diff\u00e9renciation :<\/b><span style=\"font-weight: 400;\"> vous voulez que cette solution haut de gamme ressemble \u00e0 un produit que votre entreprise propose : les bonnes couleurs, les bons logos, etc.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Fiabilit\u00e9<\/b><span style=\"font-weight: 400;\"> : votre personnel et vos clients doivent savoir que votre outil est disponible 24 heures sur 24 et 7 jours sur 7 et qu&rsquo;il b\u00e9n\u00e9ficie d&rsquo;une assistance.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Contr\u00f4le :<\/b><span style=\"font-weight: 400;\"> vous devez \u00eatre en mesure d&rsquo;influencer ce que vos utilisateurs et clients voient et utilisent, et vous pouvez m\u00eame int\u00e9grer diff\u00e9rentes offres de produits et mises \u00e0 jour dans votre solution.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>S\u00e9curit\u00e9 et protection :<\/b><span style=\"font-weight: 400;\"> vous avez besoin de votre logiciel pour prot\u00e9ger vos donn\u00e9es et\/ou celles de vos clients et pour mettre en place des contr\u00f4les rigoureux afin de garantir l&rsquo;authenticit\u00e9 et la protection.<\/span><\/span><\/li>\n<\/ul>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-c97aa98d-3238-4a83-b47b-c5811430bb6b\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-c97aa98d-3238-4a83-b47b-c5811430bb6b\" class=\"hs-cta-node hs-cta-c97aa98d-3238-4a83-b47b-c5811430bb6b\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/c97aa98d-3238-4a83-b47b-c5811430bb6b\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-c97aa98d-3238-4a83-b47b-c5811430bb6b\" class=\"hs-cta-img aligncenter\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/c97aa98d-3238-4a83-b47b-c5811430bb6b.png\" alt=\"DEXMA Energy Intelligence\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"font-weight: 400; color: #003b6f;\">Quelles questions dois-je me poser pour m\u2019aider \u00e0 choisir entre le d\u00e9veloppement interne ou externe de mon SGE ?<\/span><\/h2>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">Inhouse &#8211; D\u00e9velopper votre propre solution de SGE, \u00e0 partir de z\u00e9ro\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">D\u00e9velopper votre propre solution interne devrait vous permettre d&rsquo;obtenir tout cela, n&rsquo;est-ce pas ? Peut-\u00eatre, et m\u00eame si c&rsquo;\u00e9tait le cas, vous auriez non seulement un co\u00fbt important, mais aussi un d\u00e9lai d&rsquo;attente important. Combien de temps ?\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En discutant avec nos clients, nous avons entendu \u00e0 maintes reprises que le d\u00e9lai estim\u00e9 aurait pu \u00eatre d&rsquo;environ 6 mois, mais en r\u00e9alit\u00e9, le d\u00e9veloppement du projet est pass\u00e9 \u00e0 2 ans, et le SGE n&rsquo;a pas toutes les fonctionnalit\u00e9s qu&rsquo;il \u00e9tait cens\u00e9 avoir.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, le projet de gestion de l&rsquo;\u00e9nergie n&rsquo;a m\u00eame pas encore commenc\u00e9, et <\/span><b>vous avez perdu 18 mois d&rsquo;\u00e9conomies<\/b><span style=\"font-weight: 400;\"> (sans parler du paiement de divers d\u00e9veloppeurs pendant cette p\u00e9riode), et il semble que vous n&rsquo;obtiendrez pas le produit que vous voulez. Nous estimons que cela repr\u00e9sente <\/span><b>quelques millions d&rsquo;euros <\/b><span style=\"font-weight: 400;\">avant m\u00eame que vous n&rsquo;ayez commenc\u00e9. Est-il facile de faire approuver ce type de financement dans votre organisation ?<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">Externalisation \/ Outsource &#8211; Le d\u00e9veloppement de solutions de SGE est externalis\u00e9 \u00e0 partir de z\u00e9ro \u00e0 une grande multinationale partenaire<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Alors pourquoi ne pas confier votre projet \u00e0 un grand du secteur ? Vous \u00eates s\u00fbr que votre direction n&rsquo;aura aucun probl\u00e8me \u00e0 travailler avec un partenaire aussi important, et qu\u2019il aura d\u00e9j\u00e0 r\u00e9alis\u00e9 ce type de projet (d\u00e9velopper un SGE pour une entreprise comme la v\u00f4tre), n&rsquo;est-ce pas ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C&rsquo;est une bonne question \u00e0 leur poser, puis demandez-leur quel a \u00e9t\u00e9 le d\u00e9lai d&rsquo;ex\u00e9cution, combien de temps leur client a utilis\u00e9 le logiciel con\u00e7u sur mesure, et quels objectifs\/RSI le client a pu atteindre.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si vous suivez cette approche, vous devrez \u00e9galement discuter avec votre partenaire de l&rsquo;architecture de son syst\u00e8me pour ce nouveau SGE qu&rsquo;il construit pour vous :\u00a0\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Sera-t-il construit \u00e0 partir de z\u00e9ro ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Ou peuvent-ils utiliser une partie d&rsquo;une plateforme existante qui r\u00e9pond \u00e9galement \u00e0 leurs besoins ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><span style=\"font-weight: 400;\">S&rsquo;agira-t-il d&rsquo;un service sur site ou dans le nuage (sur AWS, Google Cloud, etc.) ?\u00a0 Vous savez peut-\u00eatre d\u00e9j\u00e0 qu&rsquo;<\/span><a style=\"color: #555964;\" href=\"http:\/\/www.dexma.com\/blog-en\/cloud-vs-on-premise-saas-myths\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">une solution sur site est source d&rsquo;autres cauchemars \u00e0 l&rsquo;avenir<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais). Ce n&rsquo;est pas pour rien que <\/span><a style=\"color: #555964;\" href=\"https:\/\/www.techrepublic.com\/article\/report-95-of-businesses-have-migrated-critical-applications-to-the-cloud\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">95 % des \u00e9quipes informatiques ont d\u00e9plac\u00e9 des infrastructures critiques vers le cloud<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais).<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Qu&rsquo;en est-il du d\u00e9veloppement continu de nouveaux produits ? Combien cela co\u00fbtera-t-il et la solution initiale sera-t-elle construite de mani\u00e8re \u00e0 permettre une \u00e9volution ? Le SGE sera-t-il mis \u00e0 jour avec de nouvelles sources de donn\u00e9es et de nouvelles fonctionnalit\u00e9s en fonction des tendances du march\u00e9 (nouvelles sources de donn\u00e9es de l&rsquo;IdO, int\u00e9gration de l&rsquo;\u00e9nergie solaire, technologie de stockage de l&rsquo;\u00e9nergie, etc.)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Quelle sera votre flexibilit\u00e9 si les priorit\u00e9s changent ? Vos organisations soutiennent-elles une approche agile du d\u00e9veloppement de logiciels ou, une fois le contrat sign\u00e9, il n&rsquo;y a pas de place pour le changement ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">M\u00eame si vous disposez d&rsquo;une solution \u00ab\u00a0cloud\u00a0\u00bb, quels seront vos co\u00fbts annuels d&rsquo;h\u00e9bergement et de maintenance ?\u00a0 Assurez-vous que cela inclut les co\u00fbts du serveur ainsi que les ing\u00e9nieurs d&rsquo;administration du syst\u00e8me qui devront s&rsquo;assurer que le syst\u00e8me fonctionne 24 heures sur 24 et qu&rsquo;il r\u00e9pond aux exigences de l&rsquo;accord de niveau de services (SLA).<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">Externalisation \/ Outsource &#8211; Solution pr\u00eate \u00e0 l&#8217;emploi \u00e0 utiliser avec un fournisseur de SGE<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Explorons une autre approche : tirer parti des ann\u00e9es d&rsquo;exp\u00e9rience et de d\u00e9veloppement d&rsquo;un fournisseur de SGE en nuage existant pour utiliser sa plateforme, mais en la personnalisant pour qu&rsquo;elle devienne la v\u00f4tre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 ce stade, vous pouvez \u00e9carter cette option pour l&rsquo;une ou l&rsquo;autre des raisons suivantes :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">C&rsquo;est une petite entreprise de moins de 100 personnes qui n&rsquo;existe que depuis 10 ans ; mes patrons ne me donnent pas le feu vert pour les utiliser sur un projet aussi important.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Je ne veux pas r\u00e9utiliser une plateforme standard, je veux \u00eatre unique.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Ils n&rsquo;ont probablement jamais travaill\u00e9 avec une organisation comme la mienne : ils ne comprendront pas les int\u00e9r\u00eats divergents entre les d\u00e9partements, les niveaux de bureaucratie et la mani\u00e8re d&rsquo;aider \u00e0 atteindre nos objectifs d&rsquo;entreprise ax\u00e9s sur les actionnaires, et leur plateforme ne pourra probablement pas g\u00e9rer nos milliers de b\u00e2timents.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400; color: #555964;\">Il y aura un co\u00fbt r\u00e9current que nous pourrions \u00e9viter ou r\u00e9duire si nous d\u00e9veloppons notre propre solution interne.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Tout ce que nous pouvons dire jusque l\u00e0, c&rsquo;est \u00ab\u00a0explorons plus en d\u00e9tail\u201d !<\/span><b><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Si vous demandez \u00e0 n&rsquo;importe quel fournisseur de SGE, il aura probablement d\u00e9j\u00e0 travaill\u00e9 avec quelqu&rsquo;un comme vous.\u00a0 Dans le cas de DEXMA :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Nous travaillons d\u00e9j\u00e0 avec plusieurs des principales multinationales europ\u00e9ennes de services \u00e9nerg\u00e9tiques,<\/b><span style=\"font-weight: 400;\"> des ESCO et des soci\u00e9t\u00e9s de conseil en \u00e9nergie pour fournir \u00e0 leurs \u00e9quipes et \u00e0 leurs clients notre\u00a0 logiciel pour tous les types d&rsquo;utilisateurs. Dans la plupart des cas, nous passons par des processus d&rsquo;appel d&rsquo;offres rigoureux, avec beaucoup de diligence et de comparaisons de march\u00e9 pour \u00eatre choisi comme fournisseur.\u00a0<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><span style=\"font-weight: 400;\">Nous avons <\/span><b>plus de 100.000 b\u00e2timents <\/b><span style=\"font-weight: 400;\">qui soumettent activement des relev\u00e9s en temps r\u00e9el \u00e0 notre plateforme, et des milliers d&rsquo;utilisateurs se connectent r\u00e9guli\u00e8rement.\u00a0 Notre plateforme est \u00e9volutive bien au-del\u00e0 : nous sommes pr\u00eats pour vous.<\/span><\/span><\/li>\n<li aria-level=\"1\"><span style=\"color: #555964;\"><span style=\"font-weight: 400;\">Pour nos utilisateurs, le logiciel n\u2019est pas celui de DEXMA.<\/span><b> La marque porte les couleurs, les images et les logos de l\u2019entreprise de nos Partenaires.\u00a0\u00a0<\/b><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><b>Nous avons int\u00e9gr\u00e9 notre plateforme avec de nombreux autres outils<\/b><span style=\"font-weight: 400;\"> importants dans le nuage, et gr\u00e2ce \u00e0 notre API ouverte, vous pouvez facilement int\u00e9grer DEXMA avec votre ERP, CRM, logiciel de facturation existant, etc.<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><span style=\"font-weight: 400;\">Nous pouvons activer<\/span><b> l&rsquo;authentification unique (SSO)<\/b><span style=\"font-weight: 400;\"> pour que les membres de votre \u00e9quipe puissent utiliser leurs identifiants d&rsquo;entreprise sur notre portail.\u00a0<\/span><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"color: #555964;\"><span style=\"font-weight: 400;\">Nous travaillons avec vous pour produire de <\/span><b>nouvelles fonctionnalit\u00e9s<\/b><span style=\"font-weight: 400;\"> qui peuvent \u00eatre utilis\u00e9es comme n&rsquo;importe quelle autre partie de notre plateforme, gr\u00e2ce \u00e0 notre <\/span><strong><a style=\"color: #555964;\" href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007864894-Energy-Apps-Market\" target=\"_blank\" rel=\"noopener noreferrer\">Energy Apps Market <\/a><\/strong><span style=\"font-weight: 400;\">(en anglais).<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Mais avec cette approche, vous profiterez \u00e9galement de avantages suivants :\u00a0<\/span><\/p>\n<p><span style=\"color: #555964;\"><strong><span style=\"color: #47d7ac;\">1. <\/span><\/strong><span style=\"font-weight: 400;\">Vous pourrez<\/span><b> commencer \u00e0 utiliser imm\u00e9diatement une plateforme pleinement op\u00e9rationnelle<\/b><span style=\"font-weight: 400;\"> le jour o\u00f9 vous d\u00e9ciderez de faire appel \u00e0 un prestataire sp\u00e9cialis\u00e9 dans les Logiciels de Gestion de l\u2019\u00c9nergie ou SGE.\u00a0<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #555964;\"><strong><span style=\"color: #47d7ac;\">2.<\/span><\/strong> Pas besoin de se soucier des<strong> co\u00fbts de maintenance, d&rsquo;h\u00e9bergement, etc.<\/strong>, car tout est inclus dans le prix de la licence.<br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #555964;\"><strong><span style=\"color: #47d7ac;\">3.<\/span><\/strong> Tant que vous avez choisi un fournisseur de confiance, <strong>la s\u00e9curit\u00e9 et la protection des donn\u00e9es sont d\u00e9j\u00e0 int\u00e9gr\u00e9es dans l&rsquo;ADN de la solution<\/strong>.<br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #555964;\"><strong><span style=\"color: #47d7ac;\">4.<\/span><\/strong> Vous b\u00e9n\u00e9ficierez de l&rsquo;innovation de votre partenaire et des am\u00e9liorations continues de ses produits, souvent incluses dans le prix que vous payez. N&rsquo;oubliez pas que vous voulez<strong> \u00eatre \u00e0 la pointe de votre transformation num\u00e9rique<\/strong>.<br \/>\nDans le cas de DEXMA, nous publions des mises \u00e0 jour avec des am\u00e9liorations ou des nouvelles fonctionnalit\u00e9s presque chaque semaine. Les mises \u00e0 jour sont transmises automatiquement \u00e0 tous les utilisateurs, ce qui signifie que les mises \u00e0 jour se font sans pr\u00e9avis et sans effort de la part de l&rsquo;organisation des utilisateurs. De plus, notre offre SaaS ne n\u00e9cessite aucune \u00ab\u00a0maintenance\u00a0\u00bb ou r\u00e9glage par votre \u00e9quipe informatique.<br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #555964;\"><strong><span style=\"color: #47d7ac;\">5.<\/span> <\/strong>Vous obtiendrez plus que ce que vous avez demand\u00e9 pour commencer : avez-vous pens\u00e9 \u00e0 utiliser <strong>l&rsquo;intelligence artificielle (IA)<\/strong> pour vous aider \u00e0 trouver des anomalies dans vos milliers de b\u00e2timents (car votre \u00e9quipe ne peut certainement pas le faire manuellement) ? Une plateforme standard de fournisseur de SGE peut d\u00e9j\u00e0 en disposer.<br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400; color: #555964;\"><span style=\"color: #47d7ac;\"><strong>6.<\/strong><\/span> Vous voulez quelque chose de sp\u00e9cifique pour vos clients ? Vous pouvez enti\u00e8rement sous-traiter le d\u00e9veloppement de cette nouvelle fonctionnalit\u00e9 \u00e0 votre fournisseur de SGE. Ils ont d\u00e9j\u00e0 fait cela d&rsquo;innombrables fois et savent ce qu&rsquo;ils font. Ou, si vous choisissez un SGE avec une API ouverte, vous pouvez entreprendre un <strong>co-d\u00e9veloppement<\/strong> : en utilisant vos propres d\u00e9veloppeurs pour faire ce travail avec le soutien du fournisseur de SGE.<br \/>\n<\/span><\/p>\n<p><span style=\"color: #555964;\"><strong><span style=\"color: #47d7ac;\">7.<\/span><\/strong><b> Les priorit\u00e9s ont chang\u00e9 <\/b>et votre strat\u00e9gie d&rsquo;entreprise vous oblige d\u00e9sormais \u00e0 vous concentrer sur les tonnes de <strong>carbone \u00e9conomis\u00e9es plut\u00f4t que sur les kWh<\/strong>, mais la plateforme que vous avez choisie ne le montre pas de la bonne mani\u00e8re. Si vous travaillez avec un fournisseur de de SGE, il y a de fortes chances qu&rsquo;il ait quelque chose qui vous aidera imm\u00e9diatement et qu&rsquo;il soit plus flexible dans la red\u00e9finition de tout d\u00e9veloppement futur qui s&rsquo;\u00e9carte des dispositions pr\u00e9c\u00e9dentes pour vous permettre de mieux r\u00e9ussir.<b><br \/>\n<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #555964;\"><strong><span style=\"color: #47d7ac;\">8.<\/span><\/strong> Vous ne d\u00e9penserez pas des millions d&rsquo;euros &#8211; <strong>votre facture sera inf\u00e9rieure \u00e0 celle obtenue pour d\u00e9veloppement interne<\/strong> ou pour la cr\u00e9ation d&rsquo;une toute nouvelle plateforme \u00e0 travers un grand fournisseur informatique, et vous aurez la possibilit\u00e9 de changer de solution tant que votre contrat le permettra. Du point de vue des flux de tr\u00e9sorerie, la diff\u00e9rence est \u00e9norme.<\/span><br \/>\n<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003b6f;\">Conclusion<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Wow, nous vous avons donn\u00e9 beaucoup d&rsquo;informations, alors r\u00e9capitulons. Les projets de gestion de l&rsquo;\u00e9nergie deviennent de plus en plus une priorit\u00e9 pour les grandes entreprises, qu&rsquo;elles le fassent en interne ou qu&rsquo;elles sous-traitent les services \u00e0 une entreprise sp\u00e9cialis\u00e9e dans les \u00e9conomies d&rsquo;\u00e9nergie.\u00a0 Le mat\u00e9riel et les logiciels doivent \u00e9galement \u00eatre pris en compte, et il est essentiel de se concentrer sur la composante logicielle.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00e9velopper une solution \u00e0 partir de z\u00e9ro, soit en interne, soit avec une grande soci\u00e9t\u00e9 de conseil ou d&rsquo;informatique, peut sembler une bonne option, mais le co\u00fbt, le d\u00e9lai et la rigidit\u00e9 de ces solutions requi\u00e8rent une analyse approfondie avant de lancer le projet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D&rsquo;autre part, les fournisseurs sp\u00e9cialis\u00e9s dans les SGE comme <\/span><strong><a href=\"http:\/\/www.dexma.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">DEXMA<\/a><\/strong><span style=\"font-weight: 400;\"> deviennent les Solutions de Gestion de l\u2019\u00c9nergie des gestionnaires de l&rsquo;\u00e9nergie, tout comme Salesforce l&rsquo;est pour les commerciaux. Votre organisation sous-traite probablement d\u00e9j\u00e0 son outil de vente \u00e0 Salesforce ou \u00e0 un fournisseur similaire, alors pourquoi pas aussi votre SGE ?\u00a0 \u00c9pargnez-vous le stress et commencez d\u00e8s aujourd&rsquo;hui votre voyage vers une gestion intelligente de l&rsquo;\u00e9nergie.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-node hs-cta-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-8bfbdd5f-5507-4074-b262-d219ff3c8d7a\" class=\"hs-cta-img aligncenter\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/8bfbdd5f-5507-4074-b262-d219ff3c8d7a.png\" alt=\"Demo DEXMA Energy Intelligence\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<hr \/>\n<p><i><span style=\"font-weight: 400;\"><em><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32966 alignleft\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1.png\" alt=\"\" width=\"126\" height=\"126\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1.png 500w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1-300x300.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/01\/Mio-Dart-1-150x150.png 150w\" sizes=\"auto, (max-width: 126px) 100vw, 126px\" \/>Note de la R\u00e9daction:<\/strong> cet article original a \u00e9t\u00e9 publi\u00e9 ici avec l\u2019aimable autorisation de son auteur, <strong>Mio Dart<\/strong>.\u00a0<\/em><\/span><\/i><\/p>\n<p style=\"font-size: 13px;\"><i><span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/mio-dart-b746105b\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mio Dart<\/a><\/strong> a fait partie de l&rsquo;\u00e9quipe DEXMA pendant 4 ans et a apport\u00e9 son expertise dans les domaines de l&rsquo;\u00e9nergie et de la vente. Elle collabore toujours avec nous pour la recherche et la r\u00e9daction de contenus de grande qualit\u00e9.<\/span><\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Imaginons que vous soyez responsable de l&rsquo;offre de nouveaux produits chez un fournisseur d&rsquo;\u00e9nergie ou que vous soyez responsable de l&rsquo;efficacit\u00e9 op\u00e9rationnelle dans une grande entreprise.\u00a0 Vous et votre \u00e9quipe avez d\u00e9cid\u00e9 de faire de la gestion de l&rsquo;\u00e9nergie un nouveau domaine de croissance cl\u00e9 et\/ou de r\u00e9duire votre propre consommation d&rsquo;\u00e9nergie interne.\u00a0 Mais par [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":38576,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ? - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?\" \/>\n<meta property=\"og:description\" content=\"Imaginons que vous soyez responsable de l&rsquo;offre de nouveaux produits chez un fournisseur d&rsquo;\u00e9nergie ou que vous soyez responsable de l&rsquo;efficacit\u00e9 op\u00e9rationnelle dans une grande entreprise.\u00a0 Vous et votre \u00e9quipe avez d\u00e9cid\u00e9 de faire de la gestion de l&rsquo;\u00e9nergie un nouveau domaine de croissance cl\u00e9 et\/ou de r\u00e9duire votre propre consommation d&rsquo;\u00e9nergie interne.\u00a0 Mais par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T09:58:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?\",\"datePublished\":\"2021-02-12T09:58:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/\"},\"wordCount\":2862,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FR-Developing-EMS-for-your-Utility.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/\",\"name\":\"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ? - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FR-Developing-EMS-for-your-Utility.png\",\"datePublished\":\"2021-02-12T09:58:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FR-Developing-EMS-for-your-Utility.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/FR-Developing-EMS-for-your-Utility.png\",\"width\":840,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ? - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?","og_description":"Imaginons que vous soyez responsable de l&rsquo;offre de nouveaux produits chez un fournisseur d&rsquo;\u00e9nergie ou que vous soyez responsable de l&rsquo;efficacit\u00e9 op\u00e9rationnelle dans une grande entreprise.\u00a0 Vous et votre \u00e9quipe avez d\u00e9cid\u00e9 de faire de la gestion de l&rsquo;\u00e9nergie un nouveau domaine de croissance cl\u00e9 et\/ou de r\u00e9duire votre propre consommation d&rsquo;\u00e9nergie interne.\u00a0 Mais par [&hellip;]","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-02-12T09:58:14+00:00","og_image":[{"width":840,"height":472,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?","datePublished":"2021-02-12T09:58:14+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/"},"wordCount":2862,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/","name":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ? - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png","datePublished":"2021-02-12T09:58:14+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/02\/FR-Developing-EMS-for-your-Utility.png","width":840,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/mon-entreprise-a-besoin-dun-sge-le-developper-en-interne-ou-externaliser-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mon entreprise a besoin d&amp;rsquo;un SGE: le d\u00e9velopper en interne ou externaliser ?"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38575"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/38576"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}