


{"id":38516,"date":"2021-04-21T15:10:29","date_gmt":"2021-04-21T13:10:29","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/"},"modified":"2021-04-21T15:10:29","modified_gmt":"2021-04-21T13:10:29","slug":"10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/","title":{"rendered":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Alors que la<\/span><b> transformation digitale du secteur de l&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\"> prend de l&rsquo;ampleur, les gestionnaires de l&rsquo;\u00e9nergie sont bombard\u00e9s par un d\u00e9luge de donn\u00e9es sans fin.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En fait, les questions les plus fr\u00e9quentes que nous posent <\/span><a href=\"http:\/\/www.dexma.com\/fr\/devenez-partenaire\/\"><span style=\"font-weight: 400;\">les nouveaux partenaires DEXMA<\/span><\/a><span style=\"font-weight: 400;\"> sont les suivantes : \u00ab\u00a0Quel rapport dois-je consulter ?\u00a0\u00bb et \u00ab\u00a0Quelles sont les donn\u00e9es \u00e9nerg\u00e9tiques qui ont le plus d\u2019importance ?\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">M\u00eame si vous travaillez avec un grand nombre de clients issus de diff\u00e9rents secteurs industriels, <strong>i<\/strong><\/span><b>l existe certains indicateurs sur la consommation d&rsquo;\u00e9nergie que tout gestionnaire de l&rsquo;\u00e9nergie devrait analyser<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s tout, des indicateurs\u00a0 mal configur\u00e9s ou ignor\u00e9s auront un impact n\u00e9gatif sur les estimations de co\u00fbts ou les plans de projets de r\u00e9novation de votre client. Il est donc important d\u2019\u00e9viter toute anomalie potentielle qui pourrait surgir.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si l&rsquo;une des analyses suivantes ne semble pas tout \u00e0 fait correcte, c&rsquo;est un signal clair que quelque chose doit \u00eatre ajust\u00e9 ou modifi\u00e9.\u00a0<\/span><!--more--><br \/>\n<span id=\"hs-cta-wrapper-c722a08e-32d9-4bb2-9a85-571b326f2006\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-c722a08e-32d9-4bb2-9a85-571b326f2006\" class=\"hs-cta-node hs-cta-c722a08e-32d9-4bb2-9a85-571b326f2006\"><\/span><\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-c722a08e-32d9-4bb2-9a85-571b326f2006\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-c722a08e-32d9-4bb2-9a85-571b326f2006\" class=\"hs-cta-node hs-cta-c722a08e-32d9-4bb2-9a85-571b326f2006\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/c722a08e-32d9-4bb2-9a85-571b326f2006\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-c722a08e-32d9-4bb2-9a85-571b326f2006\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/c722a08e-32d9-4bb2-9a85-571b326f2006.png\" alt=\"New Call-to-action\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"color: #113b6f;\">1. Comparer les Co\u00fbts de la Facturation d&rsquo;\u00c9nergie avec la Consommation Mensuelle d&rsquo;\u00c9nergie Monitor\u00e9e<\/span><\/h2>\n<p><b>Retrouvez vos factures d&rsquo;\u00e9nergie des 6 derniers mois <\/b><span style=\"font-weight: 400;\">au moins et comparez-les \u00e0 votre consommation mensuelle pour voir si les chiffres correspondent. C&rsquo;est un bon point de d\u00e9part pour v\u00e9rifier si votre syst\u00e8me d\u2019alertes tout comme votre <\/span><a href=\"http:\/\/www.dexma.com\/blog-en\/solve-energy-metering\/\"><span style=\"font-weight: 400;\">syst\u00e8me de mesure de la consommation d&rsquo;\u00e9nergie<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais) est correctement configur\u00e9.\u00a0\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Petite astuce : Saviez-vous que vous pouvez r\u00e9aliser la <\/span><\/i><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007968893-\"><i><span style=\"font-weight: 400;\">simulation de la facture d&rsquo;\u00e9lectricit\u00e9<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> (support en anglais) de votre b\u00e2timent, avant m\u00eame que la facture r\u00e9elle n&rsquo;arrive ?<\/span><\/i><\/p>\n<h2><span style=\"color: #003b6f;\">2. Consommation d&rsquo;\u00c9nergie Hebdomadaire (kWh)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Alors que de nombreux gestionnaires de l\u2019\u00e9nergie se concentrent sur la surveillance de la consommation mensuelle d&rsquo;\u00e9nergie (ce qui est tout \u00e0 fait naturel puisque c&rsquo;est ce qui appara\u00eet sur votre facture chaque mois), un gestionnaire de l\u2019\u00e9nergie avis\u00e9 v\u00e9rifiera \u00e9galement la <\/span><b>consommation \u00e9nerg\u00e9tique hebdomadaire<\/b><span style=\"font-weight: 400;\">. Il faut parfois du temps pour constater une am\u00e9lioration de la performance \u00e9nerg\u00e9tique. Mais cette analyse hebdomadaire offre un aper\u00e7u rapide de l&rsquo;installation de votre client au lieu de devoir attendre un rapport mensuel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si vous utilisez <\/span><a href=\"https:\/\/get.dexma.com\/essai-gratuit\"><span style=\"font-weight: 400;\">DEXMA<\/span><\/a><span style=\"font-weight: 400;\">, vous trouverez ces informations dans votre<\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007968893-\"><span style=\"font-weight: 400;\"> rapport \u00e9nerg\u00e9tique hebdomadaire<\/span><\/a><span style=\"font-weight: 400;\"> (support en anglais). Vous y trouverez\u00a0 \u00e9galement des tableaux r\u00e9capitulatifs sur la consommation d&rsquo;\u00e9nergie et les\u00a0 co\u00fbts pour chaque semaine, organis\u00e9s par jour de la semaine. Essayez de <\/span><b>v\u00e9rifier les derni\u00e8res colonnes montrant la consommation et le co\u00fbt agr\u00e9g\u00e9s pour la semaine enti\u00e8re<\/b><span style=\"font-weight: 400;\"> et comparez-les avec les donn\u00e9es des semaines pr\u00e9c\u00e9dentes, pour voir s&rsquo;il y a une variation.<\/span><\/p>\n<h3><b><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34883\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/automate_reporting-mockup.png\" alt=\"\" width=\"520\" height=\"347\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/automate_reporting-mockup.png 825w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/automate_reporting-mockup-300x200.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/automate_reporting-mockup-768x512.png 768w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/>\u00a0<\/b><\/h3>\n<h2><span style=\"color: #003b6f;\">3. Rapport entre le Co\u00fbt de l&rsquo;\u00c9nergie et la Consommation d&rsquo;\u00c9nergie pour une p\u00e9riode donn\u00e9e (\u20ac\/kWh)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Le rapport co\u00fbt\/consommation vous permet d&rsquo;analyser en profondeur l&rsquo;un des aspects\u00a0 les plus importants d&rsquo;un projet d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique :<\/span><b> combien vous co\u00fbte votre consommation d&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si vous utilisez <\/span><a href=\"https:\/\/get.dexma.com\/essai-gratuit\"><span style=\"font-weight: 400;\">DEXMA<\/span><\/a><span style=\"font-weight: 400;\">, ces indicateurs\u00a0 se pr\u00e9sentent sous la forme d&rsquo;un rapport recto-verso, analysant le co\u00fbt par tranches tarifaires. Faites attention aux ratios indiquant le co\u00fbt moyen par kWh consomm\u00e9, le co\u00fbt moyen journalier, etc. Le prix moyen par kWh est particuli\u00e8rement utile pour \u00e9laborer des analyses et des rapports compl\u00e9mentaires ou pour quantifier rapidement le retour sur investissement d&rsquo;\u00e9ventuels projets d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique ou de mesures d&rsquo;\u00e9conomie d&rsquo;\u00e9nergie (MEEs).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Consultez \u00e9galement les diagrammes circulaires d&rsquo;analyse de la consommation par rapport au co\u00fbt pour une repr\u00e9sentation plus visuelle de l&rsquo;impact de la tarification des diff\u00e9rentes plages\u00a0 horaires sur vos co\u00fbts \u00e9nerg\u00e9tiques.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34922 aligncenter\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2023\/04\/Detect-Report-Complete-1.png\" alt=\"\" width=\"574\" height=\"403\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cet indicateur\u00a0 peut \u00e9galement vous aider \u00e0 d\u00e9cider si vous devez <\/span><b>moduler votre consommation sur des plages horaires dont la tarification est moins ch\u00e8re <\/b><span style=\"font-weight: 400;\">\u00a0(via le transfert de charge ou par la gestion active de la demande (Voir notre guide sur le <\/span><a href=\"http:\/\/www.dexma.com\/blog-en\/beyond-energy-efficiency-demand-response-guide\/\"><span style=\"font-weight: 400;\">Demand Response <\/span><\/a><span style=\"font-weight: 400;\">en anglais) si l&rsquo;installation de votre client le permet.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-80994d18-13ab-4b35-84d6-f06c5042b84e\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-80994d18-13ab-4b35-84d6-f06c5042b84e\" class=\"hs-cta-node hs-cta-80994d18-13ab-4b35-84d6-f06c5042b84e\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/80994d18-13ab-4b35-84d6-f06c5042b84e\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-80994d18-13ab-4b35-84d6-f06c5042b84e\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/80994d18-13ab-4b35-84d6-f06c5042b84e.png\" alt=\"De la Gestion efficace de l'\u00e9nergie \u00e0 la Gestion active de la demande \" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"color: #113b6f;\">4. Estimation de la Consommation et du Co\u00fbt<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Pouvoir estimer les co\u00fbts futurs et la consommation d&rsquo;\u00e9nergie, c\u2019est le r\u00eave de la plupart des gestionnaires de l&rsquo;\u00e9nergie. Gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, vous pourrez pr\u00e9dire la consommation et les co\u00fbts \u00e9nerg\u00e9tiques avec des outils comme l&rsquo;application <\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007969393-Apps-Market-Forecasting\"><b>Forecasting App <\/b><\/a><span style=\"font-weight: 400;\">(support en anglais). L\u2019application les compare \u00e9galement \u00e0 diff\u00e9rents budgets et consommations \u00e9nerg\u00e9tiques de r\u00e9f\u00e9rence d\u00e9finis dans la Plateforme DEXMA.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La premi\u00e8re chose que vous devez faire est de configurer votre estimation pour permettre au syst\u00e8me d&rsquo;effectuer certains calculs de base en utilisant des algorithmes de s\u00e9ries chronologiques. Une fois que tout est configur\u00e9, attendez quelques minutes. Le calcul math\u00e9matique s&rsquo;am\u00e9liore apr\u00e8s quelques semaines et devient de plus en plus pr\u00e9cis \u00e0 partir de trois mois. Nous recommandons \u00e9galement un <\/span><b>historique de donn\u00e9es de six mois minimum<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si vous souhaitez en savoir plus, jetez un coup d&rsquo;\u0153il \u00e0 cette <\/span><a href=\"https:\/\/get.dexma.com\/forecast-energy-cost\"><span style=\"font-weight: 400;\">vid\u00e9o<\/span><\/a><span style=\"font-weight: 400;\"> (en anglais).<\/span><\/p>\n<h2><span style=\"color: #113b6f;\">5. Consommation d&rsquo;\u00c9nergie par Surface (kWh\/m\u00b2)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La consommation d&rsquo;\u00e9nergie par surface est un exemple d\u2019indicateur basique que vous pouvez facilement et automatiquement suivre dans DEXMA. Il suffit de cliquer sur l&rsquo;onglet \u201cRatios\u201d de l&rsquo;\u00e9cran \u201cLocations\u201d, et de s\u00e9lectionner \u00ab\u00a0Ratio par param\u00e8tre\u00a0\u00bb. Pour voir la liste compl\u00e8te des param\u00e8tres r\u00e9pertori\u00e9s par DEXMA, cliquez <\/span><a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1W97Yv9UWR9iwmXzknxSQSiIzjt4capmWuaZsAwNJD0g\/pub?hl=en&amp;hl=en&amp;single=true&amp;gid=0&amp;output=html\"><span style=\"font-weight: 400;\">ici<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 l&rsquo;\u00e9chelle internationale, de nombreux pays exigent la mesure du kilowattheure par m2 pour obtenir un certificat de performance \u00e9nerg\u00e9tique ou une classe \u00e9nergie notamment dans le secteur du logement et de l&rsquo;immobilier. Notez que l&rsquo;\u00e9nergie provenant d&rsquo;autres sources que l&rsquo;\u00e9lectricit\u00e9 doit \u00eatre incluse dans cette mesure. Veillez donc \u00e0 inclure des sources telles que\u00a0 le <\/span><a href=\"http:\/\/www.dexma.com\/blog-en\/hardware-solutions-monitor-gas-and-thermal-energy\/\"><span style=\"font-weight: 400;\">gaz ou l\u2019\u00e9nergie thermique<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais) dans votre analyse.<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">6. Consommation d&rsquo;\u00c9nergie par Occupation<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">C&rsquo;est un autre exemple de ratio par param\u00e8tre qui peut \u00eatre particuli\u00e8rement utile pour les b\u00e2timents \u00e0 occupation variable comme les h\u00f4tels. Pour pouvoir suivre des ratios comme le taux d&rsquo;occupation dans la Plateforme DEXMA, assurez-vous d&rsquo;avoir les donn\u00e9es d&rsquo;occupation pertinentes. Apprenez comment importer correctement les donn\u00e9es sur le taux d\u2019occupation <\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007867954-\"><span style=\"font-weight: 400;\">ici<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais).<\/span><\/p>\n<h2><span style=\"color: #113b6f;\">7. Consommation d&rsquo;\u00c9nergie par Degr\u00e9 Jour Unifi\u00e9 (kWh\/DJU)<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">DJU fait r\u00e9f\u00e9rence <\/span><b>aux Degr\u00e9s Jours Unifi\u00e9s,<\/b><span style=\"font-weight: 400;\"> un type simplifi\u00e9 de donn\u00e9es m\u00e9t\u00e9orologiques historiques calcul\u00e9es \u00e0 partir des relev\u00e9s de temp\u00e9rature de l&rsquo;air ext\u00e9rieur. Les donn\u00e9es DJU \u00e9tant faciles d&rsquo;acc\u00e8s et d&rsquo;utilisation, de nombreux gestionnaires de l&rsquo;\u00e9nergie les utilisent pour mod\u00e9liser la relation entre la consommation d&rsquo;\u00e9nergie et la temp\u00e9rature de l&rsquo;air ext\u00e9rieur, ou pour voir si les syst\u00e8mes internes r\u00e9agissent correctement aux conditions ext\u00e9rieures.<\/span><\/p>\n<p><b>Les degr\u00e9s-jours de chauffage <\/b><span style=\"font-weight: 400;\">indiquent de combien (en degr\u00e9s) et pendant combien de temps (en jours) la temp\u00e9rature de l&rsquo;air ext\u00e9rieur a \u00e9t\u00e9 inf\u00e9rieure \u00e0 une temp\u00e9rature de base sp\u00e9cifique. Ils sont utilis\u00e9s pour les calculs relatifs \u00e0 la consommation d&rsquo;\u00e9nergie n\u00e9cessaire au chauffage des b\u00e2timents.\u00a0<\/span><\/p>\n<p><b>Les degr\u00e9s-jours de refroidissement<\/b><span style=\"font-weight: 400;\"> mesurent de combien (en degr\u00e9s) et pendant combien de temps la temp\u00e9rature de l&rsquo;air ext\u00e9rieur a \u00e9t\u00e9 sup\u00e9rieure \u00e0 une temp\u00e9rature de base sp\u00e9cifique, afin de calculer la consommation d&rsquo;\u00e9nergie n\u00e9cessaire pour refroidir les b\u00e2timents.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Plateforme DEXMA peut calculer automatiquement les degr\u00e9s-jours de chauffage et de refroidissement, ou les deux ensemble\u00a0 &#8211; d\u00e9couvrez comment <\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007969053-\"><span style=\"font-weight: 400;\">ici<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais).<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">8. Demande de Charge de Pointe<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Il est important de garder un \u0153il sur la <\/span><b>demande de pointe<\/b><span style=\"font-weight: 400;\">, en particulier dans les pays o\u00f9 vous pouvez avoir des p\u00e9nalit\u00e9s si vous d\u00e9passez la puissance souscrite. En utilisant l&rsquo;application <\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007968973-\"><span style=\"font-weight: 400;\">Load Demand<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais), vous pouvez consulter le tableau r\u00e9capitulatif avec la r\u00e9partition par p\u00e9riodes de chaque puissance souscrite, la puissance exc\u00e9dentaire et ainsi voir le co\u00fbt associ\u00e9 que vous devriez retrouver sur votre facture d&rsquo;\u00e9nergie.<\/span><\/p>\n<h2><b><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34891\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/peak-load-demand-peak-energy-demand.png\" alt=\"\" width=\"502\" height=\"252\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/peak-load-demand-peak-energy-demand.png 826w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/peak-load-demand-peak-energy-demand-300x151.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/peak-load-demand-peak-energy-demand-768x386.png 768w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/b><\/h2>\n<h2><span style=\"color: #003b6f;\">9. Puissance de R\u00e9f\u00e9rence et Facteur d&rsquo;Utilisation Hebdomadaire<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Ils figurent sur la liste des indicateurs \u00e9nerg\u00e9tiques les plus importants qu&rsquo;un gestionnaire de l&rsquo;\u00e9nergie doit v\u00e9rifier chaque semaine, afin de comprendre comment le co\u00fbt de l&rsquo;\u00e9nergie est influenc\u00e9 par la consommation de r\u00e9f\u00e9rence. Les gestionnaires de l&rsquo;\u00e9nergie doivent analyser\u00a0 le \u00ab\u00a0% de puissance de r\u00e9f\u00e9rence\u00a0\u00bb et le \u00ab\u00a0facteur d&rsquo;utilisation (KU) hebdomadaire\u00a0\u00bb qui se trouvent dans la section \u00ab\u00a0Indicateurs principaux\u00a0\u00bb du rapport hebdomadaire Pro de la Plateforme DEXMA :<\/span><\/p>\n<p><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360011959420-Weekly-Pro\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34896\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Weekly-Pro-Report-SideA.png\" alt=\"Energy Weekly report\" width=\"230\" height=\"323\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Weekly-Pro-Report-SideA.png 372w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Weekly-Pro-Report-SideA-213x300.png 213w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Le pourcentage de puissance de r\u00e9f\u00e9rence repr\u00e9sente la quantit\u00e9 d&rsquo;\u00e9nergie utilis\u00e9e en permanence par une installation, tandis que le second indique le nombre d&rsquo;heures de pleine utilisation par semaine. Le KU hebdomadaire est calcul\u00e9 en divisant l&rsquo;\u00e9nergie par la Puissance Maximale (kW).<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">10. Empreinte Carbone et \u00c9missions de Gaz \u00e0 Effet de Serre<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Selon le <\/span><a href=\"https:\/\/www.wri.org\/insights\/global-look-mandatory-greenhouse-gas-reporting-programs\"><span style=\"font-weight: 400;\">World Resources Institute<\/span><\/a><span style=\"font-weight: 400;\"> (article en anglais), <\/span><b>au moins 40 pays ont actuellement mis en place des programmes de d\u00e9claration obligatoire des \u00e9missions<\/b><span style=\"font-weight: 400;\">. Comme le changement climatique est une probl\u00e9matique croissante dans les agendas nationaux du monde entier, les gestionnaires de l&rsquo;\u00e9nergie peuvent s&rsquo;attendre \u00e0 voir davantage de <\/span><b>r\u00e9glementations sur la d\u00e9claration obligatoire des \u00e9missions.<\/b><span style=\"font-weight: 400;\"> C&rsquo;est donc une bonne id\u00e9e de ma\u00eetriser cette m\u00e9trique.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans la Plateforme DEXMA, vous pouvez utiliser l&rsquo;application <\/span><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007865514-\"><span style=\"font-weight: 400;\">Carbon App<\/span><\/a><span style=\"font-weight: 400;\"> (support en anglais) pour contr\u00f4ler jusqu&rsquo;\u00e0 9 \u00e9missions diff\u00e9rentes de gaz \u00e0 effet de serre (m\u00e9thane, oxyde nitreux&#8230;) provenant de toutes vos sources d&rsquo;\u00e9nergie et exporter les r\u00e9sultats vers une feuille de calcul Excel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est essentiel de conna\u00eetre les ratios de conversion du carbone que vous devez appliquer aux \u00e9missions que vous souhaitez calculer. Les gouvernements qui imposent des obligations de d\u00e9claration fournissent g\u00e9n\u00e9ralement sur leurs sites Web des fichiers Excel contenant tous les ratios de conversion des \u00e9missions dont vous avez besoin.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Une fois que vous avez introduit vos ratios d&rsquo;\u00e9mission et d\u00e9fini les charges et les p\u00e9riodes que vous souhaitez mesurer, vous pouvez v\u00e9rifier l&rsquo;analyse finale de chaque source d&rsquo;\u00e9nergie et de chaque type d&rsquo;\u00e9mission sur trois fr\u00e9quences disponibles : quotidienne, hebdomadaire et mensuelle :<\/span><\/p>\n<p><a href=\"https:\/\/support.dexma.com\/hc\/en-gb\/articles\/360007865514-Apps-Market-Carbon-Emissions-App\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34901\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Carbon-emissions-Screen.png\" alt=\"Carbon emissions report DEXMA\" width=\"500\" height=\"239\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Carbon-emissions-Screen.png 1464w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Carbon-emissions-Screen-300x143.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Carbon-emissions-Screen-1400x669.png 1400w, https:\/\/www.dexma.com\/wp-content\/uploads\/2017\/08\/Carbon-emissions-Screen-768x367.png 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Vous \u00eates pr\u00eat \u00e0 jouer avec des donn\u00e9es r\u00e9elles de consommation d&rsquo;\u00e9nergie et \u00e0 v\u00e9rifier certains de ces indicateurs par vous-m\u00eames par vous-m\u00eame ? Essayez <\/span><a href=\"https:\/\/get.dexma.com\/essai-gratuit\"><span style=\"font-weight: 400;\">DEXMA<\/span><\/a><span style=\"font-weight: 400;\"> gratuitement :<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-node hs-cta-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/d1d6f635-b931-46be-bbc2-3d94d0a8f9df.png\" alt=\"New Call-to-action\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alors que la transformation digitale du secteur de l&rsquo;\u00e9nergie prend de l&rsquo;ampleur, les gestionnaires de l&rsquo;\u00e9nergie sont bombard\u00e9s par un d\u00e9luge de donn\u00e9es sans fin. En fait, les questions les plus fr\u00e9quentes que nous posent les nouveaux partenaires DEXMA sont les suivantes : \u00ab\u00a0Quel rapport dois-je consulter ?\u00a0\u00bb et \u00ab\u00a0Quelles sont les donn\u00e9es \u00e9nerg\u00e9tiques qui [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":38517,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie\" \/>\n<meta property=\"og:description\" content=\"Alors que la transformation digitale du secteur de l&rsquo;\u00e9nergie prend de l&rsquo;ampleur, les gestionnaires de l&rsquo;\u00e9nergie sont bombard\u00e9s par un d\u00e9luge de donn\u00e9es sans fin. En fait, les questions les plus fr\u00e9quentes que nous posent les nouveaux partenaires DEXMA sont les suivantes : \u00ab\u00a0Quel rapport dois-je consulter ?\u00a0\u00bb et \u00ab\u00a0Quelles sont les donn\u00e9es \u00e9nerg\u00e9tiques qui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T13:10:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie\",\"datePublished\":\"2021-04-21T13:10:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/\"},\"wordCount\":1883,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/FR-10-Energy-Consumption-Red-Flags.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/\",\"name\":\"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/FR-10-Energy-Consumption-Red-Flags.png\",\"datePublished\":\"2021-04-21T13:10:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/FR-10-Energy-Consumption-Red-Flags.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/FR-10-Energy-Consumption-Red-Flags.png\",\"width\":840,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/","og_locale":"fr_FR","og_type":"article","og_title":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie","og_description":"Alors que la transformation digitale du secteur de l&rsquo;\u00e9nergie prend de l&rsquo;ampleur, les gestionnaires de l&rsquo;\u00e9nergie sont bombard\u00e9s par un d\u00e9luge de donn\u00e9es sans fin. En fait, les questions les plus fr\u00e9quentes que nous posent les nouveaux partenaires DEXMA sont les suivantes : \u00ab\u00a0Quel rapport dois-je consulter ?\u00a0\u00bb et \u00ab\u00a0Quelles sont les donn\u00e9es \u00e9nerg\u00e9tiques qui [&hellip;]","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-04-21T13:10:29+00:00","og_image":[{"width":840,"height":472,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie","datePublished":"2021-04-21T13:10:29+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/"},"wordCount":1883,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/","name":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png","datePublished":"2021-04-21T13:10:29+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/04\/FR-10-Energy-Consumption-Red-Flags.png","width":840,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/10-signaux-dalerte-a-surveiller-en-matiere-de-consommation-denergie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"10 Signaux d&amp;rsquo;Alerte \u00e0 Surveiller en mati\u00e8re de Consommation d&amp;rsquo;\u00c9nergie"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38516"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/38517"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}