


{"id":38453,"date":"2021-10-22T14:07:35","date_gmt":"2021-10-22T12:07:35","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/"},"modified":"2021-10-22T14:07:35","modified_gmt":"2021-10-22T12:07:35","slug":"comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/","title":{"rendered":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Le <\/span><b>calcul des \u00e9conomies r\u00e9alis\u00e9es dans le cadre d&rsquo;un projet de r\u00e9duction de la consommation \u00e9nerg\u00e9tique <\/b><span style=\"font-weight: 400;\">peut \u00eatre une t\u00e2che tr\u00e8s complexe, puisque les \u00e9conomies repr\u00e9sentent la diff\u00e9rence entre la situation actuelle et une <strong>situation future estim\u00e9e<\/strong> (c&rsquo;est-\u00e0-dire hypoth\u00e9tique). Pour cette raison, la <\/span><b>mesure et la v\u00e9rification des \u00e9conomies <\/b><span style=\"font-weight: 400;\">pendant le projet sont essentielles pour garantir le respect des objectifs fix\u00e9s en fonction de l&rsquo;estimation calcul\u00e9e.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous d\u00e9couvrirez ci-dessous comment, gr\u00e2ce au protocole de mesure et de v\u00e9rification des \u00e9conomies, vous pouvez <strong>am\u00e9liorer les r\u00e9sultats de votre Contrat de Performance \u00c9nerg\u00e9tique (CPE)<\/strong> :<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">La mesure et la v\u00e9rification des \u00e9conomies est une discipline complexe mais n\u00e9cessaire pour normaliser la fa\u00e7on dont vous calculez vos \u00e9conomies et pour fournir un cadre sur lequel s&rsquo;appuyer pour la mise en \u0153uvre de projets d&rsquo;\u00e9conomies de consommation.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33286\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Baseline-graphic-.png\" alt=\"\" width=\"1394\" height=\"716\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Baseline-graphic-.png 1394w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Baseline-graphic--300x154.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Baseline-graphic--768x394.png 768w\" sizes=\"auto, (max-width: 1394px) 100vw, 1394px\" \/><\/span><\/p>\n<p>Pour l&rsquo;ex\u00e9cution des projets de mesure des \u00e9conomies, les contrats de services \u00e9nerg\u00e9tiques (contrats de performance \u00e9nerg\u00e9tique, CPE, EPC ou ESPC) doivent d\u00e9finir les bases qui \u00e9tablissent les conditions de calcul et de distribution des \u00e9conomies obtenues, tant pour l&rsquo;Entreprise de Services \u00c9nerg\u00e9tiques que pour le Client. En d&rsquo;autres termes, <strong>quelle sera la rentabilit\u00e9 obtenue par chaque partie gr\u00e2ce au contrat de services \u00e9nerg\u00e9tiques<\/strong>.<\/p>\n<p><span style=\"font-weight: 400;\">Le financement des projets d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique provient toujours des \u00e9conomies g\u00e9n\u00e9r\u00e9es par ces mesures. Le co\u00fbt de l&rsquo;\u00e9nergie avant le projet est r\u00e9duit de telle sorte qu&rsquo;une partie de ces \u00e9conomies finance les mesures r\u00e9alis\u00e9es et une autre partie est per\u00e7ue comme une rentabilit\u00e9 du projet lui-m\u00eame.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37419\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1.png\" alt=\"EPC Contrato Servicios Energ\u00e9ticos\" width=\"1600\" height=\"647\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1.png 1600w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1-300x121.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1-1400x566.png 1400w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1-768x311.png 768w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/EPC-Scheme-1-1536x621.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>Selon que les mesures d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique sont financ\u00e9es par une Entreprise de Services \u00c9nerg\u00e9tiques (ESE ou ESCO en anglais) ou par le client, il s&rsquo;agira d&rsquo;un projet d&rsquo;\u00e9conomies partag\u00e9es ou d&rsquo;\u00e9conomies garanties. Quoi qu&rsquo;il en soit, pour maximiser les avantages d&rsquo;un CPE, <strong>il est essentiel de disposer d&rsquo;outils permettant d&rsquo;avoir une vue d&rsquo;ensemble claire de l&rsquo;\u00e9tat actuel des projets<\/strong>. Cela vous permettant \u00e9galement de r\u00e9agir \u00e0 temps lors de toute d\u00e9viation dans le projet d&rsquo;\u00e9conomies.\u00a0<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-69f106a6-999f-4717-9907-8ffa1d5f7136\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-69f106a6-999f-4717-9907-8ffa1d5f7136\" class=\"hs-cta-node hs-cta-69f106a6-999f-4717-9907-8ffa1d5f7136\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/69f106a6-999f-4717-9907-8ffa1d5f7136\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" id=\"hs-cta-img-69f106a6-999f-4717-9907-8ffa1d5f7136\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/69f106a6-999f-4717-9907-8ffa1d5f7136.png\" alt=\"Solution de gestion de l'\u00e9nergie - D\u00e9mo gratuite - Dexma\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, '69f106a6-999f-4717-9907-8ffa1d5f7136', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Comment Maximiser les \u00c9conomies dans votre Projet d&rsquo;Efficacit\u00e9 \u00c9nerg\u00e9tique<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Afin de pouvoir \u00e9valuer le r\u00e9sultat de votre projet, vous devez avoir une \u00e9valuation claire de l&rsquo;objectif du projet. Et dans le cas d&rsquo;un projet d&rsquo;\u00e9conomies, vous aurez besoin d&rsquo;un outil pour suivre les \u00e9conomies g\u00e9n\u00e9r\u00e9es en temps r\u00e9el.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><a href=\"https:\/\/support.dexma.com\/hc\/fr\/articles\/360007866894-Projets-de-Mesure-et-V%C3%A9rification\"><b>fonctionnalit\u00e9 M&amp;V<\/b><\/a><span style=\"font-weight: 400;\"> de Dexma Analyse vous permettra de suivre l&rsquo;\u00e9volution de votre projet en temps r\u00e9el, vous donnant une vue pr\u00e9cise de son \u00e9tat \u00e0 tout moment, et vous permettant ainsi de <strong>r\u00e9agir \u00e0 tout \u00e9cart par rapport aux attentes<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le M&amp;V de Dexma vous permet non seulement d&rsquo;\u00e9valuer l&rsquo;\u00e9tat de votre projet afin d&rsquo;avancer dans le temps, mais vous offre \u00e9galement la possibilit\u00e9 de reformuler votre contrat \u00e0 votre guise afin d&rsquo;obtenir d&rsquo;autres approches, qui n&rsquo;appartiennent pas n\u00e9cessairement \u00e0 celles du projet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous trouverez ci-dessous <\/span><b>3 actions essentielles pour maximiser les \u00e9conomies de votre contrat de services \u00e9nerg\u00e9tiques<\/b><span style=\"font-weight: 400;\">\u00a0:<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">1.\u00a0 Augmenter la Fr\u00e9quence d&rsquo;\u00c9valuation de votre Projet<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La plupart des contrats de performance \u00e9nerg\u00e9tique (CPE) sont formul\u00e9s sur la base d&rsquo;une consommation mensuelle de r\u00e9f\u00e9rence pr\u00e9vue, car ils prennent souvent les factures d&rsquo;\u00e9nergie comme donn\u00e9es historiques, qui ont cette p\u00e9riodicit\u00e9.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais le fait que votre contrat soit mensuel ne signifie pas que vous devez abandonner le suivi et le calcul des \u00e9conomies \u00e0 la fin du mois. Mais, pourquoi ne pas profiter des fonctionnalit\u00e9s en temps r\u00e9el<\/span><span style=\"font-weight: 400;\">\u00a0pour <a href=\"https:\/\/www.youtube.com\/watch?v=d6BmzA5LtFg\">suivre l&rsquo;\u00e9volution de vos \u00e9conomies de mani\u00e8re plus d\u00e9taill\u00e9e<\/a> ?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est toujours pr\u00e9f\u00e9rable d&rsquo;\u00e9valuer chaque jour si l&rsquo;objectif de 20% d&rsquo;\u00e9conomies \u00e0 \u00e9t\u00e9 atteint, plut\u00f4t qu&rsquo;en fin de mois, n&rsquo;est-ce pas ? Il est<\/span><span style=\"font-weight: 400;\"> m\u00eame possible d&rsquo;\u00e9valuer le projet sur une base horaire, pour d\u00e9tecter \u00e0 quels moments de la journ\u00e9e les \u00e9conomies sont maximales ou minimales et essayer de reproduire les circonstances id\u00e9ales aussi longtemps que possible.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">2. Comparer les \u00c9conomies R\u00e9elles aux Objectifs<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Comme nous l&rsquo;avons d\u00e9j\u00e0 mentionn\u00e9, dans un projet d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, il ne suffit pas d&rsquo;\u00e9conomiser l&rsquo;\u00e9nergie. En effet, il est toujours pr\u00e9f\u00e9rable d&rsquo;aller au-del\u00e0 de l&rsquo;\u00e9conomie d&rsquo;un certain objectif. Vous allez comprendre pourquoi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans le graphique ci-dessous, vous pouvez voir un projet d&rsquo;\u00e9conomie d&rsquo;\u00e9nergie dans lequel, a priori, la <\/span><b>consommation r\u00e9elle<\/b><span style=\"font-weight: 400;\"> (barres vertes) est inf\u00e9rieure \u00e0 la <\/span><b>consommation de r\u00e9f\u00e9rence<\/b><span style=\"font-weight: 400;\"> (ligne bleue). Cela peut sembler bon (aucune \u00e9conomie ne serait pire), mais cela ne garantit pas que les \u00e9conomies seront suffisantes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37591 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Reference-Consumption.png\" alt=\"consommation r\u00e9elle par rapport \u00e0 la r\u00e9f\u00e9rence - \u00e9lectricit\u00e9\" width=\"512\" height=\"289\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Reference-Consumption.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Reference-Consumption-300x169.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Si vous regardez \u00e9galement le graphique ci-dessous et que vous comparez la <strong>consommation r\u00e9elle avec la consommation de r\u00e9f\u00e9rence<\/strong>, vous constaterez facilement que l&rsquo;objectif d&rsquo;\u00e9conomies n&rsquo;a pas \u00e9t\u00e9 atteint sur de nombreux mois. Il n&rsquo;est donc pas \u00e9vident que le projet soit un succ\u00e8s.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37599 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Target-Consumption.png\" alt=\"consommation energ\u00e9tique r\u00e9elle par rapport \u00e0 la cons. cible - \u00e9lectricit\u00e9\" width=\"512\" height=\"295\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Target-Consumption.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-Target-Consumption-300x173.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La r\u00e9alit\u00e9 de ce projet est que <strong>32,47% de l&rsquo;\u00e9nergie est \u00e9conomis\u00e9e par rapport \u00e0 la consommation de r\u00e9f\u00e9rence<\/strong>. Mais \u00e9tant donn\u00e9 que l&rsquo;objectif d&rsquo;\u00e9conomies \u00e9tait de 30%, nous ne sommes que 2,47% au-dessus de cet objectif. Ainsi, \u00e0 plusieurs mois de la fin du contrat, nous n&rsquo;avons aucune raison de croire qu&rsquo;il y aura des \u00e9conomies \u00e0 distribuer, et m\u00eame s&rsquo;il y en avait, elles seraient infimes.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37604 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs-target-consumption.png\" alt=\"mesure et la v\u00e9rification des \u00e9conomies - consommation r\u00e9elle par rapport \u00e0 la cons. cible cumul\u00e9e - \u00e9lectricit\u00e9\" width=\"512\" height=\"293\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs-target-consumption.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs-target-consumption-300x172.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Si nous ajoutons \u00e0 cela le fait que l&rsquo;entreprise de services \u00e9nerg\u00e9tiques (ESCO) a un objectif d&rsquo;\u00e9conomies plus \u00e9lev\u00e9 de sorte que la distribution des \u00e9conomies garantit la rentabilit\u00e9 du projet au niveau de l&rsquo;entreprise (disons 40%), nous constatons que le projet n&rsquo;est plus rentable en tant qu&rsquo;entreprise.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37609 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-sec.-target-consumption.png\" alt=\"services \u00e9nerg\u00e9tiques (ESCO) a un objectif d'\u00e9conomies\" width=\"512\" height=\"292\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-sec.-target-consumption.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Real-vs-sec.-target-consumption-300x171.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En fait, nous observons que la consommation totale est sup\u00e9rieure \u00e0 l&rsquo;objectif de l&rsquo;ESE, et donc en termes commerciaux, il s&rsquo;av\u00e8re que malgr\u00e9 les \u00e9normes \u00e9conomies r\u00e9alis\u00e9es, le projet sera d\u00e9ficitaire pour celle-ci.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37614 size-full\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs.-sec.-target-consumption.png\" alt=\"consommation energ\u00e9tique re\u00e9lle cumul\u00e9e par rapport \u00e0 la cons. cible sec. cumul\u00e9e \" width=\"512\" height=\"313\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs.-sec.-target-consumption.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-Accumulated-real-vs.-sec.-target-consumption-300x183.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Il est donc<\/span><b> important de consid\u00e9rer l&rsquo;objectif r\u00e9el de tout projet, qu&rsquo;il s&rsquo;agisse de r\u00e9aliser un rapport sur le contrat ou d&rsquo;\u00e9valuer la rentabilit\u00e9 interne \u00e0 l&rsquo;entreprise de services \u00e9nerg\u00e9tiques<\/b>.<\/p>\n<h3><span style=\"font-weight: 400; color: #003b6f;\">3. \u00c9valuation des Contrats Multi-Sites<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Dans le cas de contrats multi-sites, Dexma M&amp;V vous aidera \u00e0 <\/span><b>rapporter les \u00e9conomies de tous les projets de votre contrat de mani\u00e8re agr\u00e9g\u00e9e<\/b><span style=\"font-weight: 400;\">, afin d&rsquo;avoir une vision globale du contrat total, sans se perdre dans les d\u00e9tails de chacun des sites.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37619\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyectos-1.png\" alt=\"\" width=\"512\" height=\"58\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyectos-1.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyectos-1-300x34.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Si, par exemple, nous avons des sites dont la consommation est beaucoup plus \u00e9lev\u00e9e que d&rsquo;autres, un petit pourcentage d&rsquo;\u00e9conomie r\u00e9alis\u00e9 sur ces sites peut \u00eatre plus important qu&rsquo;une grande \u00e9conomie dans un site plus petit. Il est donc important d&rsquo;avoir une vue group\u00e9e des projets qui nous permette de comprendre la situation globale.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37624\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyecto-2.png\" alt=\"\" width=\"512\" height=\"148\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyecto-2.png 512w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/FR-MV-Vista-agrupada-proyecto-2-300x87.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Et \u00e0 son tour, \u00eatre capable de trouver les projets qui sont rentables pour le projet et ceux qui doivent \u00eatre am\u00e9lior\u00e9s afin d&rsquo;atteindre les objectifs.<\/span><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/d6BmzA5LtFg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\">Ces actions de mesure et de v\u00e9rification des \u00e9conomies durant votre projet d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique sont des actions avanc\u00e9es qui vous permettront d&rsquo;acc\u00e9l\u00e9rer la prise de d\u00e9cision et le r\u00e9ajustement durant le projet. Cela permettra \u00e0 votre entreprise de services \u00e9nerg\u00e9tiques de couvrir les co\u00fbts et d&rsquo;atteindre les objectifs de rentabilit\u00e9 de votre CPE.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contactez d\u00e8s maintenant nos experts en logiciels de gestion de l&rsquo;\u00e9nergie et <\/span><a href=\"https:\/\/get.dexma.com\/essai-gratuit\"><span style=\"font-weight: 400;\">testez la fonctionnalit\u00e9 M&amp;V <\/span><\/a><span style=\"font-weight: 400;\">de la Plateforme Dexma.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-node hs-cta-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-d1d6f635-b931-46be-bbc2-3d94d0a8f9df\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/d1d6f635-b931-46be-bbc2-3d94d0a8f9df.png\" alt=\"DEMO Software de gestion de l'\u00e9nergie DEXMA\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<hr \/>\n<p><i><em><strong>Note de la r\u00e9daction<\/strong>\u00a0\u2013 Cet article a \u00e9t\u00e9 \u00e9crit par 2 experts en mati\u00e8re de logiciels de gestion de l\u2019\u00e9nergie :<\/em><\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33320 size-thumbnail alignleft\" src=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Alfonso-Mateos-150x150.png\" alt=\"Alfonso-Mateos\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Alfonso-Mateos-150x150.png 150w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/02\/Alfonso-Mateos.png 225w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<p><i><strong><a href=\"https:\/\/www.linkedin.com\/in\/alfonso-mateos-pastor-6307a53b\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alfonso Mateos,\u00a0<\/a>Product Owner chez DEXMA,<\/strong> fait partie de l\u2019\u00e9quipe depuis 2015. Il a commenc\u00e9 sa carri\u00e8re chez Dexma au sein du d\u00e9partement des Op\u00e9rations, en assurant le support mat\u00e9riel et logiciel aux clients gr\u00e2ce \u00e0 son excellent parcours en tant que responsable de projets \u00e9nerg\u00e9tiques. Il travaille actuellement dans le d\u00e9partement Produits en tant que Responsable de la partie la plus analytique de la plateforme d\u2019intelligence \u00e9nerg\u00e9tique Dexma, Dexma Analyse.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le calcul des \u00e9conomies r\u00e9alis\u00e9es dans le cadre d&rsquo;un projet de r\u00e9duction de la consommation \u00e9nerg\u00e9tique peut \u00eatre une t\u00e2che tr\u00e8s complexe, puisque les \u00e9conomies repr\u00e9sentent la diff\u00e9rence entre la situation actuelle et une situation future estim\u00e9e (c&rsquo;est-\u00e0-dire hypoth\u00e9tique). Pour cette raison, la mesure et la v\u00e9rification des \u00e9conomies pendant le projet sont essentielles pour [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":35934,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma\" \/>\n<meta property=\"og:description\" content=\"Le calcul des \u00e9conomies r\u00e9alis\u00e9es dans le cadre d&rsquo;un projet de r\u00e9duction de la consommation \u00e9nerg\u00e9tique peut \u00eatre une t\u00e2che tr\u00e8s complexe, puisque les \u00e9conomies repr\u00e9sentent la diff\u00e9rence entre la situation actuelle et une situation future estim\u00e9e (c&rsquo;est-\u00e0-dire hypoth\u00e9tique). Pour cette raison, la mesure et la v\u00e9rification des \u00e9conomies pendant le projet sont essentielles pour [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-22T12:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma\",\"datePublished\":\"2021-10-22T12:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/\"},\"wordCount\":1522,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/\",\"name\":\"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png\",\"datePublished\":\"2021-10-22T12:07:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma","og_description":"Le calcul des \u00e9conomies r\u00e9alis\u00e9es dans le cadre d&rsquo;un projet de r\u00e9duction de la consommation \u00e9nerg\u00e9tique peut \u00eatre une t\u00e2che tr\u00e8s complexe, puisque les \u00e9conomies repr\u00e9sentent la diff\u00e9rence entre la situation actuelle et une situation future estim\u00e9e (c&rsquo;est-\u00e0-dire hypoth\u00e9tique). Pour cette raison, la mesure et la v\u00e9rification des \u00e9conomies pendant le projet sont essentielles pour [&hellip;]","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-10-22T12:07:35+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma","datePublished":"2021-10-22T12:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/"},"wordCount":1522,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/","name":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png","datePublished":"2021-10-22T12:07:35+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/How-to-increase-your-EPC-Margins-using-Dexma-Measurement-and-Verification-Tool.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/comment-augmenter-vos-marges-epc-en-utilisant-loutil-mv-de-dexma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment Augmenter les Marges de vos CPEs gr\u00e2ce \u00e0 l&amp;rsquo;Outil M&amp;#038;V de Dexma"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38453"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/35934"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}