


{"id":38424,"date":"2021-11-26T13:37:02","date_gmt":"2021-11-26T12:37:02","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/"},"modified":"2021-11-26T13:37:02","modified_gmt":"2021-11-26T12:37:02","slug":"5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/","title":{"rendered":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p>L&rsquo;<strong>Enqu\u00eate 2021<\/strong> est maintenant termin\u00e9e, et nous tenons \u00e0 remercier tous les participants pour leur enthousiasme et leur int\u00e9r\u00eat !<\/p>\n<p>Le rapport avec les r\u00e9sultats est pr\u00eat, obtenez votre <a href=\"https:\/\/get.dexma.com\/rapport-energy-survey-2021\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>copie gratuite maintenant<\/strong><\/a> !<\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">En tant que professionnels de l&rsquo;\u00e9nergie nous avons des formations et des int\u00e9r\u00eats vari\u00e9s, mais nous avons tous un objectif commun : faire passer le mot et <\/span><b>motiver nos clients et nos pairs \u00e0 \u00eatre plus efficaces \u00e9nerg\u00e9tiquement et plus durables<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;\u00e9nergie est partout autour de nous et c&rsquo;est un secteur passionnant dans lequel il est important de s&rsquo;impliquer !<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Votre exp\u00e9rience en tant que professionnel de l&rsquo;\u00e9nergie est le point de d\u00e9part qui nous permettra de mieux comprendre le secteur. C&rsquo;est pourquoi nous avons \u00e9labor\u00e9 cette enqu\u00eate, afin que nous puissions tous avoir un large aper\u00e7u des <\/span><b>principales tendances, des d\u00e9fis et des besoins en mati\u00e8re d&rsquo;\u00e9nergie<\/b><span style=\"font-weight: 400;\">, notamment sur la technologie et l&rsquo;innovation, les cons\u00e9quences du lieu de travail hybride depuis le Covid, et bien d&rsquo;autres sujets d&rsquo;actualit\u00e9. Que vous soyez un professionnel exp\u00e9riment\u00e9 de l&rsquo;\u00e9nergie ou que la gestion de l&rsquo;\u00e9nergie ne repr\u00e9sente qu&rsquo;une partie de votre travail, vos r\u00e9ponses seront extr\u00eamement utiles.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voici <\/span><b>5 raisons pour lesquelles vous devriez participer<\/b><span style=\"font-weight: 400;\"> :<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003f6b;\">1. Contribuer aux Analyses Comparatives et aux \u00c9tudes du Secteur\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">L&rsquo;exp\u00e9rience de premi\u00e8re main est toujours le meilleur moyen de comprendre les sp\u00e9cificit\u00e9s d&rsquo;une industrie ou d&rsquo;un secteur. Vous vous demandez parfois, en lisant un rapport, quelles sont les sources&#8230; et ici, vous avez la possibilit\u00e9 de <strong>contribuer et de partager vos id\u00e9es<\/strong> ! Vous pourrez partager des informations importantes sur votre r\u00f4le sans fournir de d\u00e9tails personnels.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003f6b;\">2. Apprendre des Autres Acteurs du Secteur<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">De la m\u00eame mani\u00e8re que vos informations de premi\u00e8re main sont pr\u00e9cieuses, celles d&rsquo;autres experts du secteur le sont aussi. Vous voulez probablement savoir ce que font les autres, s&rsquo;ils sont confront\u00e9s \u00e0 des <strong>d\u00e9fis similaires, ou comment vous vous situez par rapport \u00e0 un proche concurrent<\/strong>. L\u00e0 encore, nous recherchons les tendances g\u00e9n\u00e9rales et les points communs, nous ne citerons pas de noms.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003f6b;\">3. Cr\u00e9er une Communaut\u00e9 au sein du Secteur<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Cette enqu\u00eate ne porte pas sur des informations confidentielles ou des secrets d&rsquo;\u00c9tat, il n&rsquo;y a donc aucun risque \u00e0 partager largement et vous pouvez aider d&rsquo;autres personnes du secteur ! <strong>Partagez l&rsquo;enqu\u00eate en ligne, par courrier \u00e9lectronique ou simplement par le bouche-\u00e0-oreille avec des coll\u00e8gues et des personnes susceptibles d&rsquo;\u00eatre int\u00e9ress\u00e9es \u00e0 participer<\/strong>. Plus nous aurons de participants, plus le rapport sera complet.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003f6b;\">4. Pour Recevoir un Excellent Rapport<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Nous vous rappelons que toutes les informations recueillies serviront de base \u00e0 un rapport qui sera lanc\u00e9 en janvier. Il s&rsquo;agira <strong>d&rsquo;une ressource de r\u00e9f\u00e9rence pour les professionnels de l&rsquo;\u00e9nergie comme vous<\/strong>, qui pourront commencer l&rsquo;ann\u00e9e en \u00e9tant parfaitement inform\u00e9s, en r\u00e9fl\u00e9chissant \u00e0 l&rsquo;ann\u00e9e \u00e9coul\u00e9e et en planifiant l&rsquo;avenir.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #003f6b;\">5. Commencer \u00e0 Participer \u00e0 l&rsquo;Enqu\u00eate<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Si vous avez besoin d&rsquo;une raison de plus pour participer, l&rsquo;enqu\u00eate ne vous demandera aucune information personnelle et vous n&rsquo;aurez qu&rsquo;\u00e0 nous laisser une adresse \u00e9lectronique pour <strong>participer \u00e0 un tirage au sort<\/strong> (\u00e0 rendre comme un geste de remerciements, pas comme un pot-de-vin!).<\/span><\/p>\n<hr \/>\n<p>L&rsquo;<strong>Enqu\u00eate 2021<\/strong> est maintenant termin\u00e9e, et nous tenons \u00e0 remercier tous les participants pour leur enthousiasme et leur int\u00e9r\u00eat !<\/p>\n<p>Les r\u00e9sultats sont pr\u00eats ! Obtenez votre copie gratuite du <a href=\"https:\/\/get.dexma.com\/rapport-sur-le-secteur-de-l-energie-2021\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Rapport sur les Tendances du Secteur de l&rsquo;\u00c9nergie 2022 ici<\/strong> <\/a>:<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071\" class=\"hs-cta-node hs-cta-df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071.png\" alt=\"rapport de l'enqu\u00eate sur la gestion de l'\u00e9nergie 2021 - DEXMA\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, 'df5bb6e6-eaa8-47c2-b5c8-66a1cb1c3071', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Enqu\u00eate 2021 est maintenant termin\u00e9e, et nous tenons \u00e0 remercier tous les participants pour leur enthousiasme et leur int\u00e9r\u00eat ! Le rapport avec les r\u00e9sultats est pr\u00eat, obtenez votre copie gratuite maintenant !<\/p>\n","protected":false},"author":39,"featured_media":38425,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021 - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;Enqu\u00eate 2021 est maintenant termin\u00e9e, et nous tenons \u00e0 remercier tous les participants pour leur enthousiasme et leur int\u00e9r\u00eat ! Le rapport avec les r\u00e9sultats est pr\u00eat, obtenez votre copie gratuite maintenant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-26T12:37:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021\",\"datePublished\":\"2021-11-26T12:37:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/\",\"name\":\"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021 - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png\",\"datePublished\":\"2021-11-26T12:37:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021 - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021","og_description":"L&rsquo;Enqu\u00eate 2021 est maintenant termin\u00e9e, et nous tenons \u00e0 remercier tous les participants pour leur enthousiasme et leur int\u00e9r\u00eat ! Le rapport avec les r\u00e9sultats est pr\u00eat, obtenez votre copie gratuite maintenant !","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-11-26T12:37:02+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021","datePublished":"2021-11-26T12:37:02+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/"},"wordCount":675,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/","name":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021 - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png","datePublished":"2021-11-26T12:37:02+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/11\/FR-Survey-State-of-Energy-Management-2021-LP-Feature.png","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/5-raisons-de-lire-lenquete-sur-letat-de-la-gestion-de-lenergie-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"5 Raisons de Lire l&amp;rsquo;Enqu\u00eate sur l&amp;rsquo;\u00c9tat de la Gestion de l&amp;rsquo;\u00c9nergie 2021"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38424"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/38425"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}