


{"id":38355,"date":"2022-11-04T10:00:20","date_gmt":"2022-11-04T09:00:20","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/"},"modified":"2022-11-04T10:00:20","modified_gmt":"2022-11-04T09:00:20","slug":"decret-tertiaire-les-5-points-cles-a-retenir-article-1","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/","title":{"rendered":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Entr\u00e9 en vigueur le 1er octobre 2019, <\/span><span style=\"font-weight: 400;\">le <\/span><b>D\u00e9cret Tertiaire aussi appel\u00e9 \u00ab D\u00e9cret de R\u00e9novation Tertiaire \u00bb<\/b><span style=\"font-weight: 400;\">, pr\u00e9cise les modalit\u00e9s d&rsquo;application de l&rsquo;article 175 de la<\/span> <a href=\"https:\/\/www.gouvernement.fr\/action\/elan-une-loi-pour-l-evolution-du-logement-de-l-amenagement-et-du-numerique\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">loi ELAN<\/span><\/a><span style=\"font-weight: 400;\"> (\u00c9volution du Logement, de l\u2019Am\u00e9nagement et du Num\u00e9rique), et impose une r\u00e9duction r\u00e9elle et importante de la consommation d\u2019\u00e9nergie du parc immobilier.\u00a0<\/span><\/p>\n<p><!--more--><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-76954194-3c8a-49de-b505-242fb67fefda\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-76954194-3c8a-49de-b505-242fb67fefda\" class=\"hs-cta-node hs-cta-76954194-3c8a-49de-b505-242fb67fefda\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/76954194-3c8a-49de-b505-242fb67fefda\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-76954194-3c8a-49de-b505-242fb67fefda\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/76954194-3c8a-49de-b505-242fb67fefda.png\" alt=\"real estate et facility management\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<p><span style=\"font-weight: 400;\">Il s\u2019agit en effet d\u2019un texte \u00e0 vis\u00e9e environnementale qui promeut l\u2019am\u00e9nagement du territoire et <\/span><span style=\"font-weight: 400;\">l\u2019am\u00e9lioration de la performance \u00e9nerg\u00e9tique des b\u00e2timents \u00e0 usage tertiaire. Un v\u00e9ritable bouleversement dans le secteur puisqu\u2019il focalise les efforts sur l\u2019obligation de r\u00e9sultats et non plus sur l\u2019obligation de moyens.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans ce premier article (1er d\u2019une <a href=\"https:\/\/www.dexma.com\/fr\/?s=D%C3%A9cret+Tertiaire&amp;submit=Recherche\">s\u00e9rie de 3<\/a>), nous vous expliquons <\/span><b>en quoi consiste le D\u00e9cret Tertiaire et comment il affecte la conformit\u00e9 r\u00e9glementaire de votre patrimoine<\/b><span style=\"font-weight: 400;\">. <\/span><\/p>\n<p><strong>Voici donc les 5 points \u00e0 retenir:<\/strong><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">1. Qui est Concern\u00e9 ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En quelques mots, <strong>tous les ensembles fonciers livr\u00e9s apr\u00e8s le 23\/11\/2018 int\u00e9grant une activit\u00e9 tertiaire de plus de 1000m\u00b2<\/strong>. Il s&rsquo;applique aussi bien aux b\u00e2timents publics que priv\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Par ensemble foncier, il faut comprendre<\/strong> :<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-24408\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2020\/02\/correct-symbol.png\" alt=\"\" width=\"14\" height=\"14\" \/> <\/b>Les b\u00e2timents h\u00e9bergeant exclusivement des activit\u00e9s tertiaires sur une surface de plancher de 1 000 m\u00b2 ou plus (y compris les surfaces accessoires aux activit\u00e9s tertiaires);<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-24408\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2020\/02\/correct-symbol.png\" alt=\"\" width=\"14\" height=\"14\" \/> <\/b>Les b\u00e2timents \u00e0 usage mixte qui h\u00e9bergent des activit\u00e9s tertiaires sur une surface de plancher cumul\u00e9e d&rsquo;au moins 1 000 m\u00b2;<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-24408\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2020\/02\/correct-symbol.png\" alt=\"\" width=\"14\" height=\"14\" \/> <\/b>Les ensembles de b\u00e2timents d&rsquo;une m\u00eame unit\u00e9 fonci\u00e8re ou site d\u00e8s lors que ces b\u00e2timents h\u00e9bergent des activit\u00e9s tertiaires sur une surface de plancher cumul\u00e9e de \u00e0 1 000 m\u00b2 ou plus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><em><strong>Quelques exceptions sont \u00e0 noter :<\/strong><\/em><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les constructions \u00e0 titre pr\u00e9caire selon permis de construire;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les b\u00e2timents, parties de b\u00e2timents ou ensembles de b\u00e2timents destin\u00e9s au culte;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les activit\u00e9s op\u00e9rationnelles \u00e0 des fins de d\u00e9fense, de s\u00e9curit\u00e9 civile ou de s\u00fbret\u00e9 int\u00e9rieure du territoire.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Les bailleurs et les preneurs sont concern\u00e9s selon les responsabilit\u00e9s respectives d\u00e9crites dans les baux.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">2. Quels sont les Objectifs et Obligations ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Le <\/span><b>D\u00e9cret Tertiaire s&rsquo;inscrit dans la<\/b><b> <\/b><a href=\"https:\/\/www.ecologique-solidaire.gouv.fr\/strategie-nationale-bas-carbone-snbc\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Strat\u00e9gie Nationale Bas Carbone<\/b><\/a><b> (SNBC)<\/b><span style=\"font-weight: 400;\">, qui vise la neutralit\u00e9 carbone de la France pour 2050. Le secteur du b\u00e2timent \u00e9tant responsable de 40% de la consommation \u00e9nerg\u00e9tique et de 24% des \u00e9missions de CO<\/span><span style=\"font-weight: 400;\">2<\/span><span style=\"font-weight: 400;\">, il s&rsquo;agit d&rsquo;un axe majeur de cette strat\u00e9gie.<\/span><\/p>\n<p style=\"text-align: left;\">Les objectifs de r\u00e9duction de la consommation sont \u00e9chelonn\u00e9s sur 30 ans<span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><strong>Deux m\u00e9thodologies de d\u00e9finition des objectifs cohabitent :\u00a0<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La comparaison \u00e0 une consommation de r\u00e9f\u00e9rence qui correspond \u00e0 une ann\u00e9e pleine d&rsquo;exploitation qui ne peut \u00eatre ant\u00e9rieure \u00e0 2010,<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ou l&rsquo;atteinte d&rsquo;une valeur absolue selon la typologie de b\u00e2timent d\u00e9finie par un arr\u00eat\u00e9 \u00e0 para\u00eetre.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\"><strong>Les objectifs suivent une progression par palier tous les 10 ans<\/strong> :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">-40% en 2030<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">-50% en 2040<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">-60% en 2050<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28373\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/decret-tertiaire.png\" alt=\"decret tertiaire - DEXMA\" width=\"1065\" height=\"227\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/decret-tertiaire.png 1065w, https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/decret-tertiaire-300x64.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/decret-tertiaire-768x164.png 768w\" sizes=\"auto, (max-width: 1065px) 100vw, 1065px\" \/><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">3. Quelles sont les Modalit\u00e9s de Calcul ?<\/span><\/h2>\n<p><strong>Les calculs des objectifs reposent sur :<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Le type d&rsquo;activit\u00e9 tertiaire du b\u00e2timent<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">La surface<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les consommations par usage et par type d&rsquo;\u00e9nergie<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Toutes ces donn\u00e9es devront \u00eatre d\u00e9pos\u00e9es sur la <\/span><a href=\"https:\/\/operat.ademe.fr\/#\/public\/accueil\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">plateforme OPERAT <\/span><\/a><span style=\"font-weight: 400;\">(Observatoire de la performance \u00e9nerg\u00e9tique, de la r\u00e9novation et des actions du tertiaire) avant le 30 septembre de l&rsquo;ann\u00e9e suivante. \u00c0 noter qu\u2019une tol\u00e9rance a \u00e9t\u00e9 accord\u00e9e jusqu\u2019au 31 d\u00e9cembre 2022 pour la premi\u00e8re \u00e9ch\u00e9ance initialement pr\u00e9vue le 30 septembre 2022.<\/span><\/p>\n<p><strong>Les objectifs peuvent \u00eatre modul\u00e9s selon plusieurs facteurs :<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Un co\u00fbt excessif des travaux au regard des \u00e9conomies et baisse de consommation r\u00e9alis\u00e9es (ROI trop important)<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Le volume d&rsquo;activit\u00e9<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Un incompatibilit\u00e9 avec les r\u00e8gles et prescriptions architecturales (par exemple pour les monuments historiques)\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Un dossier technique devra \u00eatre r\u00e9dig\u00e9 pour d\u00e9finir la situation de r\u00e9f\u00e9rence, identifier les contraintes techniques \u00e0 m\u00eame d&rsquo;influer sur les obligations, d\u00e9finir le plan d&rsquo;actions et les impacts \u00e9conomiques. Le dossier technique devra \u00eatre r\u00e9dig\u00e9 par un acteur ayant les comp\u00e9tences requises \u00e0 la r\u00e9alisation d&rsquo;audits \u00e9nerg\u00e9tiques.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">4. Quelles sont les Sanctions ?<\/span><\/h2>\n<p><strong>Les sanctions pr\u00e9vues sont de 2 types: financi\u00e8res et d&rsquo;image<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Amende pouvant aller jusqu\u2019\u00e0 7.500\u20ac<\/span><\/li>\n<li style=\"font-weight: 400;\"><i><span style=\"font-weight: 400;\">Name and Shame<\/span><\/i><span style=\"font-weight: 400;\">: Publication des noms des r\u00e9calcitrants sur un site public<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Si la sanction financi\u00e8re restera anecdotique pour une grande majorit\u00e9 d&rsquo;acteurs, le risque d&rsquo;image sera en revanche bien plus \u00e9lev\u00e9. Avec les politiques RSE et les contraintes de conformit\u00e9, l&rsquo;enjeu est v\u00e9ritablement de prendre une part active dans la r\u00e9ponse aux enjeux environnementaux.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">5. Pourquoi Agir d\u00e8s Maintenant ?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Les objectifs vis\u00e9s sont tr\u00e8s ambitieux, et pr\u00e9supposent une action \u00e0 long terme, anticip\u00e9e. <strong>Un plan d&rsquo;action d\u00e9fini et mis en place r\u00e9guli\u00e8rement produira des r\u00e9sultats efficaces<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Une strat\u00e9gie globale r\u00e9fl\u00e9chie permettra d&rsquo;optimiser les investissements<\/strong>, de planifier les op\u00e9rations n\u00e9cessaires et de r\u00e9aliser des \u00e9conomies au plus t\u00f4t, am\u00e9liorant ainsi les bilans financiers.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">T\u00e9l\u00e9chargez d\u00e8s \u00e0 pr\u00e9sent notre <strong><a href=\"https:\/\/get.dexma.com\/hubfs\/Checklists\/Checklist-De%CC%81cret%20Tertiaire.pdf\" rel=\"noopener noreferrer\">Checklist Sp\u00e9ciale D\u00e9cret Tertiaire<\/a><\/strong>, pour faire le point sur votre situation.\u00a0\u00a0<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-392c500c-ca51-4f1f-84ea-42af9ed438af\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-392c500c-ca51-4f1f-84ea-42af9ed438af\" class=\"hs-cta-node hs-cta-392c500c-ca51-4f1f-84ea-42af9ed438af\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/392c500c-ca51-4f1f-84ea-42af9ed438af\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-392c500c-ca51-4f1f-84ea-42af9ed438af\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/392c500c-ca51-4f1f-84ea-42af9ed438af.png\" alt=\"D\u00e9cret Tertiaire DEXMA\" \/><\/a><\/span><\/span><br \/>\n<span id=\"hs-cta-wrapper-b105ba29-49a4-4aa1-9a07-cc89da98db6f\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-b105ba29-49a4-4aa1-9a07-cc89da98db6f\" class=\"hs-cta-node hs-cta-b105ba29-49a4-4aa1-9a07-cc89da98db6f\"><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<hr \/>\n<p><i><span style=\"font-weight: 400;\"><em><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-28378 alignleft\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/Guest-Bloggers-1.png\" alt=\"Fran\u00e7ois Jaouen\" width=\"119\" height=\"119\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/Guest-Bloggers-1.png 500w, https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/Guest-Bloggers-1-300x300.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2020\/05\/Guest-Bloggers-1-150x150.png 150w\" sizes=\"auto, (max-width: 119px) 100vw, 119px\" \/><\/strong><\/em><\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\"><em><strong>Note de la r\u00e9daction :<\/strong> cet article a \u00e9t\u00e9 co-r\u00e9dig\u00e9 par <a href=\"https:\/\/www.dexma.com\/fr\/\" rel=\"noopener noreferrer\">Dexma<\/a> et <a href=\"https:\/\/www.eneor.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Eneor<\/a>, publi\u00e9 ici avec l&rsquo;aimable autorisation de son co-auteur, <strong>Fran\u00e7ois Jaouen<\/strong>.\u00a0<\/em><\/span><\/i><\/p>\n<p style=\"font-size: 13px;\"><i><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.eneor.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">ENEOR<\/a> est\u00a0soci\u00e9t\u00e9 ind\u00e9pendante d\u2019ing\u00e9nierie \u00e9nerg\u00e9tique qui axe sa strat\u00e9gie sur la performance r\u00e9elle mesur\u00e9e et v\u00e9rifi\u00e9e, tout en montrant que la performance \u00e9nerg\u00e9tique est un levier de productivit\u00e9 et de confort.<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entr\u00e9 en vigueur le 1er octobre 2019, le D\u00e9cret Tertiaire aussi appel\u00e9 \u00ab D\u00e9cret de R\u00e9novation Tertiaire \u00bb, pr\u00e9cise les modalit\u00e9s d&rsquo;application de l&rsquo;article 175 de la loi ELAN (\u00c9volution du Logement, de l\u2019Am\u00e9nagement et du Num\u00e9rique), et impose une r\u00e9duction r\u00e9elle et importante de la consommation d\u2019\u00e9nergie du parc immobilier.\u00a0<\/p>\n","protected":false},"author":39,"featured_media":38356,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-38355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1] - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]\" \/>\n<meta property=\"og:description\" content=\"Entr\u00e9 en vigueur le 1er octobre 2019, le D\u00e9cret Tertiaire aussi appel\u00e9 \u00ab D\u00e9cret de R\u00e9novation Tertiaire \u00bb, pr\u00e9cise les modalit\u00e9s d&rsquo;application de l&rsquo;article 175 de la loi ELAN (\u00c9volution du Logement, de l\u2019Am\u00e9nagement et du Num\u00e9rique), et impose une r\u00e9duction r\u00e9elle et importante de la consommation d\u2019\u00e9nergie du parc immobilier.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T09:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]\",\"datePublished\":\"2022-11-04T09:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/\"},\"wordCount\":976,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blog-Posts-Covers-3-SEMI-OLD.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/\",\"name\":\"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1] - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blog-Posts-Covers-3-SEMI-OLD.png\",\"datePublished\":\"2022-11-04T09:00:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blog-Posts-Covers-3-SEMI-OLD.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Blog-Posts-Covers-3-SEMI-OLD.png\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1] - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]","og_description":"Entr\u00e9 en vigueur le 1er octobre 2019, le D\u00e9cret Tertiaire aussi appel\u00e9 \u00ab D\u00e9cret de R\u00e9novation Tertiaire \u00bb, pr\u00e9cise les modalit\u00e9s d&rsquo;application de l&rsquo;article 175 de la loi ELAN (\u00c9volution du Logement, de l\u2019Am\u00e9nagement et du Num\u00e9rique), et impose une r\u00e9duction r\u00e9elle et importante de la consommation d\u2019\u00e9nergie du parc immobilier.\u00a0","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2022-11-04T09:00:20+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"GR DEV","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]","datePublished":"2022-11-04T09:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/"},"wordCount":976,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/","name":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1] - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png","datePublished":"2022-11-04T09:00:20+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2022\/11\/Blog-Posts-Covers-3-SEMI-OLD.png","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/decret-tertiaire-les-5-points-cles-a-retenir-article-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9cret Tertiaire : Les 5 Points Cl\u00e9s \u00e0 Retenir [Article 1]"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/fr\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=38355"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/38355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/38356"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=38355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=38355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=38355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}