


{"id":28229,"date":"2021-04-02T15:15:00","date_gmt":"2021-04-02T13:15:00","guid":{"rendered":"https:\/\/spacewell.com\/non-classifiee\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/"},"modified":"2023-11-29T13:33:41","modified_gmt":"2023-11-29T12:33:41","slug":"la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive","status":"publish","type":"post","link":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/","title":{"rendered":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?"},"content":{"rendered":"<div class=\"gb-container gb-container-d440ee0d gb-container-5731d80c\">\n\n<p class=\"wp-block-paragraph\">La maintenance pr\u00e9dictive se d\u00e9veloppe dans un nombre croissant de secteurs d\u2019activit\u00e9. D\u2019abord appliqu\u00e9e surtout dans le domaine de l\u2019industrie, elle peut aujourd\u2019hui \u00eatre adopt\u00e9e dans d\u2019autres activit\u00e9s comme la maintenance immobili\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 l\u2019apparition de <a href=\"https:\/\/spacewell.com\/fr\/solutions\/maintenance-batiment\/\">solutions de GMAO de plus en plus performantes et adapt\u00e9es<\/a> \u00e0 leur domaine d\u2019exploitation, la maintenance devient plus pr\u00e9cise et plus efficace, ce qui favorise \u00e0 la fois la productivit\u00e9 des techniciens et la dur\u00e9e de vie des biens qu\u2019ils entretiennent.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-f3ae9fa2 gb-headline-text\">Qu\u2019est-ce que la maintenance pr\u00e9dictive&nbsp;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus \u00e9labor\u00e9e et la plus efficace, qui tend \u00e0 remplacer les autres types de plans de maintenance.<\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-81d760ee gb-headline-text\">Les diff\u00e9rents types de maintenance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe diff\u00e9rents types de plans de maintenance, dont la d\u00e9nomination varie parfois selon la langue et les auteurs.<\/p>\n\n\n\n<h4 class=\"gb-headline gb-headline-a1fa4ed7 gb-headline-text\">La maintenance curative<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/gmao-pour-optimiser-maintenance-curative\/\">maintenance curative<\/a> consiste \u00e0 intervenir sur un \u00e9quipement lorsque celui-ci pr\u00e9sente un dysfonctionnement. Les interventions de maintenance consistent alors \u00e0 corriger rapidement, mais provisoirement cette d\u00e9faillance, ou \u00e0 r\u00e9aliser une r\u00e9paration d\u00e9finitive, pour r\u00e9tablir son \u00e9tat normal. Cette strat\u00e9gie de maintenance est parfois dite palliative, dans le premier cas, ou corrective curative, dans le second.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La maintenance curative est la plus anciennement r\u00e9pandue et elle est encore aujourd\u2019hui tr\u00e8s utilis\u00e9e, car elle est la plus facile \u00e0 appliquer. Elle ne requiert pas, en effet, de mettre en place un plan de maintenance \u00e9labor\u00e9 : lorsqu\u2019un incident se produit, comme une fuite d\u2019eau ou une panne de climatisation, un technicien intervient et y rem\u00e9die.<\/p>\n\n\n\n<h4 class=\"gb-headline gb-headline-43328912 gb-headline-text\">La maintenance pr\u00e9ventive<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/le-role-de-la-gmao-dans-la-maintenance-preventive\/\">maintenance pr\u00e9ventive<\/a> est une d\u00e9marche qui a pour objectif de favoriser la productivit\u00e9 des \u00e9quipements \u00e0 entretenir et de prolonger leur dur\u00e9e de vie. Pour ce faire, elle pr\u00e9voit la mise en place d\u2019op\u00e9rations de maintenance \u00e0 intervalles r\u00e9guliers avant l\u2019apparition de pannes ou de dysfonctionnements, pour r\u00e9duire la probabilit\u00e9 que ceux-ci ne surviennent. La fr\u00e9quence et les modalit\u00e9s des interventions sont parfois d\u00e9termin\u00e9es par des dispositions r\u00e9glementaires sur certains types d\u2019\u00e9quipements, dans d\u2019autres cas par les recommandations du constructeur, qui sont parfois une condition d\u2019application de la garantie ou de l\u2019assurance qualit\u00e9, ou parfois aussi par l\u2019observation et l\u2019analyse du fonctionnement du bien concern\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les deux premiers cas, on parle de maintenance pr\u00e9ventive syst\u00e9matique, alors que le troisi\u00e8me cas de figure correspond \u00e0 la maintenance pr\u00e9ventive conditionnelle.<\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-d0c2d7b0 gb-headline-text\">La maintenance pr\u00e9dictive ou pr\u00e9visionnelle<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aussi appel\u00e9e maintenance pr\u00e9visionnelle, la maintenance pr\u00e9dictive, qui est parfois consid\u00e9r\u00e9e comme une forme de maintenance pr\u00e9ventive, reprend les principes de la maintenance conditionnelle pour les appliquer de plus pouss\u00e9e gr\u00e2ce aux nouvelles technologies qui sont aujourd\u2019hui disponibles (<a href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/quest-ce-que-le-smart-building\/\">smart building<\/a>, <a href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/demystifier-le-bim-pour-la-gestion-des-services-generaux\/\">BIM<\/a>\u2026). Gr\u00e2ce \u00e0 celles-ci, elle cherche \u00e0 pr\u00e9voir les pannes par l\u2019observation attentive de l\u2019\u00e9tat et du fonctionnement des biens immobiliers et des \u00e9quipements qu\u2019ils int\u00e8grent, pour \u00e0 la fois \u00e9viter des op\u00e9rations de maintenance inutile tout en permettant aux techniciens d\u2019intervenir avant que des d\u00e9gradations ou des dysfonctionnements ne surviennent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appliquer ce type de plan de maintenance n\u2019est cependant pas envisageable sans disposer des outils informatiques et technologiques appropri\u00e9s, car cela implique de surveiller constamment l\u2019\u00e9tat des biens et d\u2019\u00eatre en mesure d\u2019analyser rapidement et efficacement leurs besoins d\u2019entretien. C\u2019est pourquoi la GMAO est devenue un outil incontournable pour les entreprises qui cherchent \u00e0 optimiser la maintenance de leurs actifs immobiliers.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-d9372552 gb-headline-text\">Appliquer la maintenance pr\u00e9dictive gr\u00e2ce \u00e0 la GMAO<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Adopter une strat\u00e9gie de maintenance pr\u00e9dictive ou pr\u00e9visionnelle n\u2019est possible qu\u2019en recourant \u00e0 la GMAO et \u00e0 l\u2019utilisation de capteurs dispos\u00e9s au sein des biens immobiliers ou sur les \u00e9quipements. Son efficacit\u00e9 est en effet tributaire d\u2019une forte capacit\u00e9 d\u2019analyse de leur \u00e9tat de fonctionnement que seules les solutions les plus r\u00e9centes proposent.<\/p>\n\n\n\n<h3 class=\"gb-headline gb-headline-a646e1df gb-headline-text\"><br>Les 3 \u00e9tapes de la maintenance pr\u00e9dictive<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019application d\u2019un plan de maintenance pr\u00e9dictive peut \u00eatre divis\u00e9e en trois \u00e9tapes.<\/p>\n\n\n\n<h4 class=\"gb-headline gb-headline-9a970db3 gb-headline-text\">\u00c9tape 1 : la collecte des donn\u00e9es des \u00e9quipements<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re \u00e9tape correspond \u00e0 la collecte des donn\u00e9es, gr\u00e2ce \u00e0 des capteurs plac\u00e9s en diff\u00e9rents points strat\u00e9giques d\u2019un bien immobilier ou sur un \u00e9quipement, pour recueillir des informations sur son fonctionnement (temp\u00e9rature, vibrations, consommation d\u2019\u00e9nergie\u2026). Ces capteurs sont le fruit de l\u2019apparition et des progr\u00e8s de l\u2019IoT, l\u2019Internet of Things ou Internet des Objets.<\/p>\n\n\n\n<h4 class=\"gb-headline gb-headline-491cc77d gb-headline-text\">\u00c9tape 2 : l\u2019analyse des donn\u00e9es<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La deuxi\u00e8me \u00e9tape consiste \u00e0 analyser les donn\u00e9es recueillies, ce que seul un logiciel de GMAO est capable de faire. En se basant notamment sur l\u2019historique du fonctionnement du bien ou d\u2019un autre actif immobilier de m\u00eame type, une GMAO peut identifier des signes avant-coureurs d\u2019un dysfonctionnement et d\u00e9terminer les besoins de maintenance du bien concern\u00e9, avant qu\u2019un incident ne se produise.<\/p>\n\n\n\n<h4 class=\"gb-headline gb-headline-01871975 gb-headline-text\">\u00c9tape 3 : les op\u00e9rations de maintenance<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La troisi\u00e8me \u00e9tape est donc celle de l\u2019intervention de maintenance pr\u00e9conis\u00e9e par la GMAO, qui pourra potentiellement \u00eatre planifi\u00e9e \u00e0 un moment qui ne perturbera pas l\u2019utilisation normale du bien, ce qui r\u00e9duit les co\u00fbts indirects de la maintenance.<\/p>\n\n<\/div><div class=\"gb-container gb-container-a1cdfa75\">\n\n<figure class=\"gb-block-image gb-block-image-367b326a\"><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"653\" class=\"gb-image gb-image-367b326a gb-image-b19acb23\" src=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/AdobeStock_298820469_small-980x653-1.jpg\" alt=\"services\" srcset=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/AdobeStock_298820469_small-980x653-1.jpg 980w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/AdobeStock_298820469_small-980x653-1-500x333.jpg 500w, https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/AdobeStock_298820469_small-980x653-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/figure>\n\n<\/div><div class=\"gb-container gb-container-2741c9c6 gb-container-5731d80c\">\n\n<h3 class=\"gb-headline gb-headline-d7f66fc9 gb-headline-text\">Comment la GMAO rend possible la maintenance pr\u00e9dictive&nbsp;?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seul un logiciel de GMAO adapt\u00e9 \u00e0 la maintenance immobili\u00e8re est en mesure de recueillir et d\u2019analyser les donn\u00e9es renseignant l\u2019\u00e9tat d\u2019un actif immobilier, et de les traduire en indicateurs permettant d\u2019\u00e9valuer ses besoins de maintenance. Pour rendre possible la mise en \u0153uvre d\u2019un plan de maintenance pr\u00e9dictive, il faut en effet \u00eatre en mesure de collecter les donn\u00e9es aupr\u00e8s des capteurs, de s\u00e9lectionner les informations utiles et de les croiser entre elles. C\u2019est ainsi que les comportements standards des b\u00e2timents et \u00e9quipements sont identifi\u00e9s et les anomalies d\u00e9tect\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contrairement aux id\u00e9es re\u00e7ues, l\u2019adoption d\u2019un <a href=\"https:\/\/spacewell.com\/fr\/solutions\/maintenance-batiment\/\">logiciel de GMAO adapt\u00e9 \u00e0 l\u2019IoT<\/a> pour g\u00e9rer sa maintenance et la mise en place d\u2019un syst\u00e8me de capteurs ne sont pas extr\u00eamement co\u00fbteuses compar\u00e9es aux solutions de GMAO classiques, et surtout le ROI est notable et rapide. De plus, les logiciels r\u00e9cents sont beaucoup plus faciles et rapides \u00e0 installer, \u00e0 s\u2019approprier et \u00e0 utiliser que les pr\u00e9d\u00e9cesseurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La maintenance pr\u00e9dictive repr\u00e9sente une v\u00e9ritable avanc\u00e9e pour toutes les entreprises dont l\u2019activit\u00e9 implique de maintenir un parc d\u2019actifs immobiliers et d\u2019\u00e9quipements dans un \u00e9tat optimal de fonctionnement tout en ma\u00eetrisant et en limitant les co\u00fbts li\u00e9s \u00e0 cette maintenance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est pourquoi se doter d\u2019un <a href=\"https:\/\/spacewell.com\/fr\/solutions\/maintenance-batiment\/\">logiciel de GMAO<\/a> capable de g\u00e9rer ce type de plan de maintenance immobili\u00e8re est g\u00e9n\u00e9ralement un excellent moyen d\u2019am\u00e9liorer la productivit\u00e9 d\u2019une entreprise.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-643c55aa gb-headline-text\">Questions fr\u00e9quentes<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1696253161323\"><strong class=\"schema-faq-question\">Quels sont les diff\u00e9rents types de maintenances pr\u00e9ventives ?<\/strong> <p class=\"schema-faq-answer\">On \u00e9voque habituellement 3 types de maintenances pr\u00e9ventives :<br><br>La maintenance pr\u00e9visionnelle (aussi appel\u00e9e maintenance pr\u00e9dictive) consiste \u00e0 observer attentivement l\u2019\u00e9tat et le fonctionnement du bien immobilier et de ses \u00e9quipements pour pr\u00e9voir les pannes<br><br>La maintenance conditionnelle est un type de maintenance pr\u00e9ventive bas\u00e9e sur la surveillance des op\u00e9rations du bien immobilier et\/ou des param\u00e8tres importants de cette op\u00e9ration, y compris les op\u00e9rations qui en r\u00e9sultent<br><br>La maintenance syst\u00e9matique est aussi un type de maintenance pr\u00e9ventive, cette fois-ci d\u00e9signant les op\u00e9rations \u00e0 effectuer syst\u00e9matiquement, soit avec une fr\u00e9quence horaire fixe, soit selon une p\u00e9riodicit\u00e9 li\u00e9e \u00e0 l\u2019usage.<\/p> <\/div> <\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La maintenance pr\u00e9dictive se d\u00e9veloppe dans un nombre croissant de secteurs d\u2019activit\u00e9. D\u2019abord appliqu\u00e9e surtout dans le domaine de l\u2019industrie, elle peut aujourd\u2019hui \u00eatre adopt\u00e9e dans d\u2019autres activit\u00e9s comme la maintenance immobili\u00e8re. Gr\u00e2ce \u00e0 l\u2019apparition de solutions de GMAO de plus en plus performantes et adapt\u00e9es \u00e0 leur domaine d\u2019exploitation, la maintenance devient plus pr\u00e9cise &#8230; <a title=\"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\" class=\"read-more\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/\" aria-label=\"En savoir plus sur La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\">Lire plus<\/a><\/p>\n","protected":false},"author":29,"featured_media":20603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-28229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?<\/title>\n<meta name=\"description\" content=\"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\" \/>\n<meta property=\"og:description\" content=\"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-02T13:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T12:33:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/\"},\"author\":{\"name\":\"Marketing Team\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\"},\"headline\":\"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\",\"datePublished\":\"2021-04-02T13:15:00+00:00\",\"dateModified\":\"2023-11-29T12:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/\"},\"wordCount\":1326,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/predictive-alert-1200x630-1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/\",\"name\":\"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/predictive-alert-1200x630-1.jpg\",\"datePublished\":\"2021-04-02T13:15:00+00:00\",\"dateModified\":\"2023-11-29T12:33:41+00:00\",\"description\":\"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#faq-question-1696253161323\"}],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/predictive-alert-1200x630-1.jpg\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/predictive-alert-1200x630-1.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Alerte pr\u00e9dictive\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\",\"name\":\"Marketing Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"caption\":\"Marketing Team\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/author\\\/marketing-team\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#faq-question-1696253161323\",\"position\":1,\"url\":\"https:\\\/\\\/spacewell.com\\\/fr\\\/ressources\\\/blog\\\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\\\/#faq-question-1696253161323\",\"name\":\"Quels sont les diff\u00e9rents types de maintenances pr\u00e9ventives ?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"On \u00e9voque habituellement 3 types de maintenances pr\u00e9ventives\u00a0:<br\\\/><br\\\/>La maintenance pr\u00e9visionnelle (aussi appel\u00e9e maintenance pr\u00e9dictive) consiste \u00e0 observer attentivement l\u2019\u00e9tat et le fonctionnement du bien immobilier et de ses \u00e9quipements pour pr\u00e9voir les pannes<br\\\/><br\\\/>La maintenance conditionnelle est un type de maintenance pr\u00e9ventive bas\u00e9e sur la surveillance des op\u00e9rations du bien immobilier et\\\/ou des param\u00e8tres importants de cette op\u00e9ration, y compris les op\u00e9rations qui en r\u00e9sultent<br\\\/><br\\\/>La maintenance syst\u00e9matique est aussi un type de maintenance pr\u00e9ventive, cette fois-ci d\u00e9signant les op\u00e9rations \u00e0 effectuer syst\u00e9matiquement, soit avec une fr\u00e9quence horaire fixe, soit selon une p\u00e9riodicit\u00e9 li\u00e9e \u00e0 l\u2019usage.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?","description":"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/","og_locale":"fr_FR","og_type":"article","og_title":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?","og_description":"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.","og_url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-04-02T13:15:00+00:00","article_modified_time":"2023-11-29T12:33:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg","type":"image\/jpeg"}],"author":"Marketing Team","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"\u00c9crit par":"Marketing Team","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/"},"author":{"name":"Marketing Team","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a"},"headline":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?","datePublished":"2021-04-02T13:15:00+00:00","dateModified":"2023-11-29T12:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/"},"wordCount":1326,"publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/","url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/","name":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?","isPartOf":{"@id":"https:\/\/spacewell.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg","datePublished":"2021-04-02T13:15:00+00:00","dateModified":"2023-11-29T12:33:41+00:00","description":"La maintenance pr\u00e9dictive est la strat\u00e9gie de maintenance la plus avanc\u00e9e, rendue possible par les nouvelles solutions de GMAO.","breadcrumb":{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#faq-question-1696253161323"}],"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/10\/predictive-alert-1200x630-1.jpg","width":1200,"height":630,"caption":"Alerte pr\u00e9dictive"},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La GMAO est-elle indispensable pour faire de la maintenance pr\u00e9dictive ?"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/fr\/#website","url":"https:\/\/spacewell.com\/fr\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/fr\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/fr\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a","name":"Marketing Team","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","caption":"Marketing Team"},"url":"https:\/\/spacewell.com\/fr\/author\/marketing-team\/"},{"@type":"Question","@id":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#faq-question-1696253161323","position":1,"url":"https:\/\/spacewell.com\/fr\/ressources\/blog\/la-gmao-est-elle-indispensable-pour-faire-de-la-maintenance-predictive\/#faq-question-1696253161323","name":"Quels sont les diff\u00e9rents types de maintenances pr\u00e9ventives ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"On \u00e9voque habituellement 3 types de maintenances pr\u00e9ventives\u00a0:<br\/><br\/>La maintenance pr\u00e9visionnelle (aussi appel\u00e9e maintenance pr\u00e9dictive) consiste \u00e0 observer attentivement l\u2019\u00e9tat et le fonctionnement du bien immobilier et de ses \u00e9quipements pour pr\u00e9voir les pannes<br\/><br\/>La maintenance conditionnelle est un type de maintenance pr\u00e9ventive bas\u00e9e sur la surveillance des op\u00e9rations du bien immobilier et\/ou des param\u00e8tres importants de cette op\u00e9ration, y compris les op\u00e9rations qui en r\u00e9sultent<br\/><br\/>La maintenance syst\u00e9matique est aussi un type de maintenance pr\u00e9ventive, cette fois-ci d\u00e9signant les op\u00e9rations \u00e0 effectuer syst\u00e9matiquement, soit avec une fr\u00e9quence horaire fixe, soit selon une p\u00e9riodicit\u00e9 li\u00e9e \u00e0 l\u2019usage.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/28229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/comments?post=28229"}],"version-history":[{"count":11,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/28229\/revisions"}],"predecessor-version":[{"id":28230,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/posts\/28229\/revisions\/28230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media\/20603"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/media?parent=28229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/categories?post=28229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/fr\/wp-json\/wp\/v2\/tags?post=28229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}