


{"id":38155,"date":"2015-02-19T11:14:55","date_gmt":"2015-02-19T10:14:55","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/facturas-electricas-elevadas\/"},"modified":"2015-02-19T11:14:55","modified_gmt":"2015-02-19T10:14:55","slug":"facturas-electricas-elevadas","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/","title":{"rendered":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p>\u00bfHas tenido la sensaci\u00f3n que las <strong>facturas el\u00e9ctricas<\/strong> de su empresa son demasiado altas?<\/p>\n<p>\u00bfTe repites siempre a ti\u00a0mismo que no hay nada que puedas hacer para reducir los costes energ\u00e9ticos de en tu\u00a0empresa?<\/p>\n<p>\u00bfHas pensado en formas de reducir los costes de energ\u00eda pero no tienes ni idea de por d\u00f3nde empezar?<b> <\/b><\/p>\n<p><!--more--><\/p>\n<p><b>Siendo la electricidad cada vez m\u00e1s cara y con la dependencia absoluta de las sociedades hacia esta, es normal sentirse impotente en la gesti\u00f3n energ\u00e9tica.<\/b> Hasta ahora, las empresas contrataban una compa\u00f1\u00eda el\u00e9ctrica y usaban tanta energ\u00eda como fuera necesario. Al final, pagaban la factura sin comprender la informaci\u00f3n que hab\u00eda en ella. Esta falta de detalles en las factura el\u00e9ctrica no permite que los administradores vean si est\u00e1n siendo eficientes o si pueden tomar medidas para serlo y reducir costes.<\/p>\n<p>Teniendo esto en mente, tenemos buenas noticias para ti:<\/p>\n<p>S\u00ed, <b>existe la posibilidad que las facturas reflejen una falta de correspondencia con la carga contratada. <\/b>Sucede, pero estos errores se pueden corregir y as\u00ed ahorrar costes innecesarios en tu empresa. Primero debes detectar las anomal\u00edas en las facturas y luego ponerte en contacto con tu\u00a0compa\u00f1\u00eda el\u00e9ctrica para obtener la compensaci\u00f3n correspondiente.<\/p>\n<p><b>Podr\u00edas estar pagando una multa por exceso de potencia reactiva<\/b> (de la cual no haber tenido conocimiento). Los gobiernos han aplicado medidas como cargos adicionales para fomentar el uso eficiente de la electricidad junto con la reducci\u00f3n de CO2 y las emisiones de carbono. Para evitar estas sanciones, debes estar atento al factor de potencia m\u00ednimo requerido o comprobar el rendimiento de las instalaciones de correcci\u00f3n del factor de potencia.<\/p>\n<p><b>La electricidad es fundamental para las operaciones de su empresa, pero hay formas de optimizarla.<\/b>\u00a0El resultado: <b>la reducci\u00f3n del valor de la factura el\u00e9ctrica de tu\u00a0empresa.<\/b> As\u00ed que, aqu\u00ed va una idea sobre c\u00f3mo empezar a recortar costes de energ\u00eda: controla tu uso. Obt\u00e9n una imagen clara de tu\u00a0situaci\u00f3n actual de consumo energ\u00e9tico para establecer un plan de acci\u00f3n concreto y bajar esos n\u00fameros. Ha llegado el momento de tomar este recurso esencial y hacer que trabaje para ti\u00a0lo m\u00e1ximo posible.<\/p>\n<p>Ahora que sabes que no est\u00e1s completamente indefenso en el \u00e1rea de la monitorizaci\u00f3n\u00a0de la energ\u00eda, ha llegado el momento de informarte acerca de una herramienta que te\u00a0pondr\u00e1 en control. Te dar\u00e1 una visi\u00f3n en tiempo real de lo que est\u00e1s pagando y por qu\u00e9. El administrador de energ\u00eda <a href=\"https:\/\/get.dexma.com\/demo-gratuita\">Dexma<\/a>\u00a0es un software que permite ver todos los datos energ\u00e9ticos en sus cuadros de mando personalizables. Con esta plataforma, podr\u00e1s ver toda la informaci\u00f3n necesaria para tomar las medidas correctivas y mejorar tu\u00a0uso de energ\u00eda. Adem\u00e1s, podr\u00e1s comprender el impacto de las acciones que has tomado mediante el estudio de la evoluci\u00f3n del consumo en el tiempo. Otras ventajas importantes incluyen <b>comprender los aumentos de precios, as\u00ed como la informaci\u00f3n err\u00f3nea en sus facturas y mucho m\u00e1s.<\/b><\/p>\n<p>Deja que la Plataforma <a href=\"https:\/\/get.dexma.com\/demo-gratuita\">Dexma<\/a>\u00a0funcione para ti. Ser\u00e1s\u00a0notificado por correo electr\u00f3nico o SMS si algo sale mal o no se est\u00e1n alcanzando los objetivos de ahorro de energ\u00eda.<\/p>\n<p>No separes tus costes energ\u00e9ticos como si fueran intocables. Haz un seguimiento del consumo energ\u00e9tico de tu empresa. Podr\u00e1s descubrir oportunidades para ser m\u00e1s eficientes pagando la cantidad justa: <a href=\"http:\/\/www.dexma.com\/es\/que-es-la-plataforma-dexma\/\">Descubre m\u00e1s sobre la Plataforma Dexma<\/a>.<span id=\"hs-cta-wrapper-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-node hs-cta-9ba040d5-0466-43ad-a555-1ad1732f85e7\"><br \/>\n<!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><br \/>\n<a href=\"http:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/9ba040d5-0466-43ad-a555-1ad1732f85e7\"><img decoding=\"async\" id=\"hs-cta-img-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/9ba040d5-0466-43ad-a555-1ad1732f85e7.png\" alt=\"New Call-to-action\" \/><\/a><\/span><\/span><br \/>\n<!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHas tenido la sensaci\u00f3n que las facturas el\u00e9ctricas de su empresa son demasiado altas? \u00bfTe repites siempre a ti\u00a0mismo que no hay nada que puedas hacer para reducir los costes energ\u00e9ticos de en tu\u00a0empresa? \u00bfHas pensado en formas de reducir los costes de energ\u00eda pero no tienes ni idea de por d\u00f3nde empezar?<\/p>\n","protected":false},"author":39,"featured_media":36815,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-38155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan? - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?\" \/>\n<meta property=\"og:description\" content=\"\u00bfHas tenido la sensaci\u00f3n que las facturas el\u00e9ctricas de su empresa son demasiado altas? \u00bfTe repites siempre a ti\u00a0mismo que no hay nada que puedas hacer para reducir los costes energ\u00e9ticos de en tu\u00a0empresa? \u00bfHas pensado en formas de reducir los costes de energ\u00eda pero no tienes ni idea de por d\u00f3nde empezar?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-19T10:14:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?\",\"datePublished\":\"2015-02-19T10:14:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/\"},\"wordCount\":623,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/\",\"name\":\"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan? - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png\",\"datePublished\":\"2015-02-19T10:14:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/facturas-electricas-elevadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan? - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?","og_description":"\u00bfHas tenido la sensaci\u00f3n que las facturas el\u00e9ctricas de su empresa son demasiado altas? \u00bfTe repites siempre a ti\u00a0mismo que no hay nada que puedas hacer para reducir los costes energ\u00e9ticos de en tu\u00a0empresa? \u00bfHas pensado en formas de reducir los costes de energ\u00eda pero no tienes ni idea de por d\u00f3nde empezar?","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2015-02-19T10:14:55+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?","datePublished":"2015-02-19T10:14:55+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/"},"wordCount":623,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/","name":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan? - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png","datePublished":"2015-02-19T10:14:55+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2016\/05\/Reduce-Peak-Demand-in-Electricity-Bill-Flat.png","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/facturas-electricas-elevadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfLas Facturas El\u00e9ctricas en tu Compa\u00f1\u00eda son M\u00e1s Elevadas de lo que Deber\u00edan?"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=38155"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/36815"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=38155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=38155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=38155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}