


{"id":38138,"date":"2015-04-28T09:34:37","date_gmt":"2015-04-28T07:34:37","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/dexma-apuesta-por-la-tecnologia-de-twitter\/"},"modified":"2015-04-28T09:34:37","modified_gmt":"2015-04-28T07:34:37","slug":"dexma-apuesta-por-la-tecnologia-de-twitter","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/","title":{"rendered":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p style=\"text-align: left;\">Estas lecturas\u00a0incluyen electricidad, gas, temperatura y la lista contin\u00faa. Gracias al \u00e9xito de la monitorizaci\u00f3n de energ\u00eda en tiempo real y al incremento en el n\u00famero de proyectos que gestionamos, nuestros servidores estaban recibiendo una extensa y creciente cantidad de datos. Por lo anterior, nos pareci\u00f3 adecuado<b> redise\u00f1ar nuestro sistema existente con una nueva arquitectura para el almacenamiento e inserci\u00f3n de datos. <\/b>La misma tecnolog\u00eda de Twitter y Spotify se llama \u00abStorm\u00bb.<b>\u00a0<\/b>El nuevo dise\u00f1o nos ayudar\u00eda a acomodar para el crecimiento sostenido y para hacer al sistema completamente escalable.<\/p>\n<p>Despu\u00e9s de un per\u00edodo de 6 meses de arduo trabajo y dedicaci\u00f3n por parte de nuestro equipo de desarrollo, la nueva arquitectura se puso en funcionamiento el 15 de enero de este a\u00f1o. <b>La arquitectura resultante contiene tres elementos principales: Storm, RabbitMQ y Redis.<\/b> A continuaci\u00f3n, explicaremos las implicaciones de esto \u00faltimo y de c\u00f3mo nuestro sistema se ha mejorado para ofrecer a nuestros clientes un mejor servicio.<\/p>\n<p>Las tres acciones principales que el sistema de inserci\u00f3n hace son:<\/p>\n<ul>\n<li>Calcular valores delta (por ejemplo, el c\u00e1lculo de la energ\u00eda que se consume en una hora o un d\u00eda),<\/li>\n<li>Comprobaci\u00f3n de alertas y<\/li>\n<li>Almacenamiento de datos.<\/li>\n<\/ul>\n<p>Para realizar esas acciones de la manera m\u00e1s eficiente y escalable posible, <b>el nuevo producto ten\u00eda que ser de naturaleza Open-source, adecuado para el stream processing y con el m\u00e1ximo rendimiento.<\/b> Aqu\u00ed es donde el sistema de computaci\u00f3n distribuida en tiempo real, Storm, entra en juego. <b>Storm se integr\u00f3 en el sistema de <a href=\"http:\/\/www.dexma.com\/es\/\">DEXMA<\/a> para completar las tareas mencionadas de la manera requerida.<\/b><\/p>\n<h3 style=\"text-align: center;\"><strong><a href=\"http:\/\/www.dexma.com\/es\/\">DEXMA<\/a> ya recoge m\u00e1s de 12 millones de nuevas lecturas\u00a0al\u00a0d\u00eda<\/strong><br \/>\n<strong> procedentes de 30.000 medidores.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Backtype, una plataforma de marketing intelligence adquirida por Twitter, implement\u00f3 Storm en 2011. Fue entonces cuando lanzaron el sistema de computaci\u00f3n como un proyecto Open-source. Storm, permite dividir el proceso en tareas peque\u00f1as y decidir cu\u00e1ntos recursos se asignan a cada tarea. Esto es posible ya que los \u00abbolts\u00bb dentro del sistema realizan tareas individuales y exactas. <b>Esta divisi\u00f3n nos permite escalar de manera inteligente.<\/b> Para ilustrar sus capacidades, Twitter, Spotify, Groupon, y ahora <a href=\"http:\/\/www.dexma.com\/es\/\">DEXMA<\/a>, \u00a0lo utilizan para procesar millones de datos todos los d\u00edas.<\/p>\n<p><b>El uso de componentes de software Open-source es una garant\u00eda para nuestros clientes de que controlamos todo el proceso de desarrollo.<\/b> Que no hay ninguna caja negra que dependa de una empresa externa. Las licencias Open-source permiten a nuestro equipo de desarrollo controlar y comprender el comportamiento de componentes de software y as\u00ed, ajustar su rendimiento al l\u00edmite. De esta manera, nuestros desarrolladores pueden aprender t\u00e9cnicas para aplicar en <a href=\"http:\/\/get.dexmatech.com\/free-energy-management-software\">DEXCell Energy Manager<\/a>. Adicionalmente, este tipo de licencia nos permite, en ciertos momentos, corregir errores y contribuir a la comunidad.<\/p>\n<p>Otros componentes Open-source utilizados por <a href=\"http:\/\/www.dexma.com\/es\/\">DEXMA<\/a> incluyen: PostgreSQL, Redis y bases de datos MongoDB. Sistema de gesti\u00f3n de colas RabbitMQ, servidores web Apache y Nginx, la plataforma de desarrollo continuo Jenkins y el sistema operativo Linux.<\/p>\n<h2>Tecnolog\u00eda de Twitter y Spotify<\/h2>\n<p>Adem\u00e1s de ser Open-source, <b>Storm es perfecto para el stream processing,<\/b> es por eso que esta tecnolog\u00eda es ideal\u00a0para Twitter y\u00a0Spotify.\u00a0Esto es debido a que los datos son capturados desde una cola (que act\u00faa como un buffer temporal) y se procesan cuando pasan por cada uno de los \u201cbolts\u201d. <b>RabbitMQ y RedisDB son utilizados dentro del proceso como sistema de colas y cache (almacenamiento temporal) respectivamente. <\/b>RabbitMQ es una de las plataformas de gesti\u00f3n de colas de mensajes m\u00e1s flexibles y robustas. \u00a0RedisDB por su parte, es una de las bases de datos m\u00e1s r\u00e1pidas para el almacenamiento de clave-valor.<\/p>\n<h4><b>\u00bfPor qu\u00e9 necesitamos stream processing?<\/b><\/h4>\n<p>En Big data hay dos tipos de procesamiento de datos: batch y stream. En comparaci\u00f3n con Batch, donde los datos pasan a trav\u00e9s de m\u00e1s etapas, en stream los datos fluyen continuamente. <b>Puesto que los dataloggers (las pasarelas que env\u00edan datos de los medidores) nunca dejan de enviar datos, el procesamiento de datos en stream es una necesidad.<\/b> Este mecanismo m\u00e1s r\u00e1pido de procesamiento es esencial para el rendimiento de primera clase de <a href=\"http:\/\/get.dexmatech.com\/free-energy-management-software\">DEXCell Energy Manager<\/a>.<\/p>\n<p>Ahora que hemos explicado la nueva arquitectura de <a href=\"http:\/\/www.dexma.com\/es\/\">DEXMA<\/a> de inserci\u00f3n y almacenamiento de datos, <b>es momento de hablar de c\u00f3mo esto beneficia a nuestros clientes<\/b>. \u00a0Con la plataforma renovada, cada cliente tiene su propia cola (anteriormente eran colas compartidas). Esto permite que cada cliente reciba un tratamiento individual de sus datos sin riesgo de ser afectados por los flujos masivos de datos de otros clientes. As\u00ed mismo,<b> el producto junto con la inserci\u00f3n de datos tienen una mayor estabilidad.<\/b> Por \u00faltimo, <b>nuestros clientes experimentar\u00e1n un procesamiento de datos m\u00e1s r\u00e1pido y una mayor escalabilidad.<\/b><\/p>\n<p>Con todo esto aclarado, esperamos que disfrut\u00e9is de nuestro mejorado <a href=\"http:\/\/get.dexmatech.com\/free-energy-management-software\">DEXCell Energy Manager<\/a>!<\/p>\n<p><span id=\"hs-cta-wrapper-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-node hs-cta-9ba040d5-0466-43ad-a555-1ad1732f85e7\"><br \/>\n<!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><br \/>\n<a href=\"http:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/9ba040d5-0466-43ad-a555-1ad1732f85e7\"><img decoding=\"async\" id=\"hs-cta-img-9ba040d5-0466-43ad-a555-1ad1732f85e7\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/9ba040d5-0466-43ad-a555-1ad1732f85e7.png\" alt=\"New Call-to-action\" \/><\/a><br \/>\n<\/span><br \/>\n<\/span><br \/>\n<!-- end HubSpot Call-to-Action Code -->\t\t<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estas lecturas\u00a0incluyen electricidad, gas, temperatura y la lista contin\u00faa. Gracias al \u00e9xito de la monitorizaci\u00f3n de energ\u00eda en tiempo real y al incremento en el n\u00famero de proyectos que gestionamos, nuestros servidores estaban recibiendo una extensa y creciente cantidad de datos. Por lo anterior, nos pareci\u00f3 adecuado redise\u00f1ar nuestro sistema existente con una nueva arquitectura [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":34,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-38138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos\" \/>\n<meta property=\"og:description\" content=\"Estas lecturas\u00a0incluyen electricidad, gas, temperatura y la lista contin\u00faa. Gracias al \u00e9xito de la monitorizaci\u00f3n de energ\u00eda en tiempo real y al incremento en el n\u00famero de proyectos que gestionamos, nuestros servidores estaban recibiendo una extensa y creciente cantidad de datos. Por lo anterior, nos pareci\u00f3 adecuado redise\u00f1ar nuestro sistema existente con una nueva arquitectura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-28T07:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos\",\"datePublished\":\"2015-04-28T07:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/\"},\"wordCount\":849,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/\",\"name\":\"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"datePublished\":\"2015-04-28T07:34:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/dexma-apuesta-por-la-tecnologia-de-twitter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/","og_locale":"es_ES","og_type":"article","og_title":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos","og_description":"Estas lecturas\u00a0incluyen electricidad, gas, temperatura y la lista contin\u00faa. Gracias al \u00e9xito de la monitorizaci\u00f3n de energ\u00eda en tiempo real y al incremento en el n\u00famero de proyectos que gestionamos, nuestros servidores estaban recibiendo una extensa y creciente cantidad de datos. Por lo anterior, nos pareci\u00f3 adecuado redise\u00f1ar nuestro sistema existente con una nueva arquitectura [&hellip;]","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2015-04-28T07:34:37+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos","datePublished":"2015-04-28T07:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/"},"wordCount":849,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/","name":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","datePublished":"2015-04-28T07:34:37+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/dexma-apuesta-por-la-tecnologia-de-twitter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"DEXMA apuesta por la tecnolog\u00eda de Twitter y Spotify en inserci\u00f3n de datos"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=38138"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/34"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=38138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=38138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=38138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}