


{"id":38061,"date":"2016-02-29T07:24:46","date_gmt":"2016-02-29T06:24:46","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/tendencias-edificios-eficientes-2016\/"},"modified":"2016-02-29T07:24:46","modified_gmt":"2016-02-29T06:24:46","slug":"tendencias-edificios-eficientes-2016","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/","title":{"rendered":"Tendencias de Edificios Eficientes 2016"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p>\t\t\t\tLos llamemos edificios sostenibles, edificios eficientes o edificios \u00abverdes\u00bb lo cierto es que esta forma de edificaci\u00f3n\u00a0est\u00e1 siendo ampliamente aceptada en todo el mundo, y tiene\u00a0perspectivas de crecimiento en casi todos los pa\u00edses, pero principalmente en los m\u00e1s desarrollados. Hoy hablamos de tendencias de edificios inteligentes a ra\u00edz de la \u00faltima encuesta World Green Buildings Trends.<\/p>\n<p><!--more--><br \/>\n<!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-node hs-cta-5d3f3588-e21d-4193-b122-c43715071698\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/5d3f3588-e21d-4193-b122-c43715071698\"><img decoding=\"async\" id=\"hs-cta-img-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/5d3f3588-e21d-4193-b122-c43715071698.png\" alt=\"\u00a1Consigue tu copia! \" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, '5d3f3588-e21d-4193-b122-c43715071698', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"font-weight: 400;\">La encuesta World Green Building Trends 2016 SmartMarket Report<\/span><\/h2>\n<p><b><a href=\"http:\/\/analyticsstore.construction.com\/2016WorldGreen-9408.html\">World Green Building Trends 2016 SmartMarket Report<\/a>\u00a0<\/b>es un estudio que explica las tendencias m\u00e1s destacadas para 2016 de construcci\u00f3n eficiente o edificios \u00abverdes\u00bb. El inter\u00e9s que est\u00e1 despertando esta manera de construir est\u00e1 suponiendo una influencia continua, en especial en los pa\u00edses desarrollados.<\/p>\n<p>Hoy queremos repasar en el Blog de la Eficiencia Energ\u00e9tica los resultados de este informe creado por\u00a0 <b>Dodge Data &amp; Analytics and United Technologies<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: right;\"><i><\/i><em><strong><a href=\"http:\/\/get.dexmatech.com\/encuesta-empresas-eficientes-2016?utm_campaign=Energy%20Efficiency%20Survey%20-%202016&amp;utm_medium=dexmablog&amp;utm_source=Referral\">Participa en nuestra Encuesta de Eficiencia Energ\u00e9tica 2016&gt;&gt;<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: left;\">El informe se centra en el crecimiento de construcci\u00f3n eficiente\u00a0y ha sido posible gracias a la colaboraci\u00f3n de 1.000 participantes en una encuesta en m\u00e1s de 69 pa\u00edses. Lo puedes descargar gratuitamente en la p\u00e1gina oficial de Doge Data &amp; Analytics.<\/p>\n<h2><span style=\"font-weight: 400;\">El Futuro de los Edificios Eficientes\u00a0<\/span><\/h2>\n<p>Uno de los principales mensajes del estudio es que \u00e9ste pronostica que la construcci\u00f3n de edificios eficientes se duplica cada tres a\u00f1os. Las econom\u00edas emergentes como Brasil, India, Arabia Saud\u00ed o Sud\u00e1frica ser\u00e1n los motores de este crecimiento continuo en los pr\u00f3ximos tres a\u00f1os, con un desarrollo variable: en algunos casos doblar\u00e1n su presencia y en otros hasta la multiplicar\u00e1n por seis respecto a la presencia actual de edificios verdes.\u00a0<a href=\"http:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/adb5a8c3-d5be-4959-9716-b40e803fbe55\"><img decoding=\"async\" id=\"hs-cta-img-adb5a8c3-d5be-4959-9716-b40e803fbe55\" class=\"hs-cta-img alignright\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/adb5a8c3-d5be-4959-9716-b40e803fbe55.png\" alt=\"New Call-to-action\" \/><\/a><span id=\"hs-cta-wrapper-adb5a8c3-d5be-4959-9716-b40e803fbe55\" class=\"hs-cta-wrapper\"><br \/>\n<\/span><\/p>\n<p>Los resultados tambi\u00e9n revelan que esa expansi\u00f3n seguir\u00e1 adelante en pa\u00edses desarrollados como Estados Unidos, Alemania o Reino Unido. En todas las regiones, muchos de los participantes de la encuesta pronosticaron que el 60% de sus proyectos ser\u00e1n ecol\u00f3gicos en 2018.<\/p>\n<p>Es crucial, por lo tanto, poder demostrar el retorno financiero y el impacto en los planes de negocio de contar con un edificio eficiente. El estudio ha encontrado que los edificios verdes ofrecen interesantes cifras de ahorro operativo frente a los edificios tradicionales:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">Los encuestados esperaban obtener un <strong>14% de ahorro en costes operativos<\/strong> en 5 a\u00f1os para nueva construcci\u00f3n.<\/li>\n<li style=\"font-weight: 400;\">Los due\u00f1os de edificios, ya sean nuevos o renovados, destacaban que hab\u00edan visto un <strong>aumento en el valor de la propiedad del 7%<\/strong> frente al edificio tradicional.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<blockquote>\n<h3><b><i>\u201cEl compromiso global con la construcci\u00f3n eficiente est\u00e1 cambiando el sector de la edificaci\u00f3n.\u201d<\/i><\/b><\/h3>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, las <strong>prioridades<\/strong> de qu\u00e9 supone eficiencia dentro del edificio var\u00edan ampliamente en funci\u00f3n de la geograf\u00eda. Por ejemplo, reforzar pr\u00e1cticas sostenibles es una t\u00e1ctica que casi todos los pa\u00edses destacan como muy importante, pero Arabia Saud\u00ed parece que le da poca importancia. En este pa\u00eds intentan que el foco principal sea el aumento de la productividad de cada trabajador.\u00a0<\/span><\/p>\n<p>De la misma manera, conservar la energ\u00eda es una clave a nivel global, pero en algunos pa\u00edses como Brasil, Colombia, Australia y China, proteger el medio natural es una prioridad casi igual de importante para la mayor\u00eda de los encuestados.<\/p>\n<p>Si accedes al informe podr\u00e1s ver una lista detallada de c\u00f3mo cada pa\u00eds gestiona o gestionar\u00e1 la implementaci\u00f3n de programas de edificaci\u00f3n inteligente. Te lo recomendamos porque cada pa\u00eds tiene su propio plan con diferentes indicadores y entornos que ayudar\u00e1n o podr\u00e1n suponer obst\u00e1culos para las empresas que quieran apostar por los edificios sostenibles.<\/p>\n<h2><b>\u00bfCu\u00e1ntos Edificios Eficientes hay?\u00a0<\/b><\/h2>\n<p>Para responder a la pregunta, hay que tener en cuenta que Dodge Data &amp; Analytics llev\u00f3 a cabo este estudio mundial sobre el compromiso con la edificaci\u00f3n sostenible en 2012 y 2015. Con ambos informes, se han extra\u00eddo interesantes conclusiones de la evoluci\u00f3n del edificio verde en el sector de la construcci\u00f3n.<\/p>\n<p>Y, entre otras cosas, debemos destacar que se ha medido el nivel de edificaci\u00f3n eficiente que hay en cada pa\u00eds. Los resultados puede que te sorprendan. \u00bfSabes cu\u00e1les son los pa\u00edses con mayor penetraci\u00f3n de edificios eficientes? <strong>Sud\u00e1frica, Singapur, La India y M\u00e9xico.\u00a0<\/strong><\/p>\n<p>A nivel global,\u00a0los edificios verdes suponen en 2015 el <strong>24% del total de la construcci\u00f3n.\u00a0<\/strong><\/p>\n<p>Y se espera que, <strong>en 2018, este porcentaje sea del 60%.\u00a0<\/strong><\/p>\n<p>Los pa\u00edses que se espera que tengan el mayor crecimiento son Brasil, China y Arabia Saud\u00ed. Quiz\u00e1 te interese empezar a posicionarte en esos mercados si eres un experto en gesti\u00f3n energ\u00e9tica&#8230;<\/p>\n<h2><b>Top Sectores de Futuro<\/b><\/h2>\n<p>Sigamos desgranando las tendencias y pron\u00f3sticos, porque hay otro dato muy interesante que se puede extraer del mismo, y es en qu\u00e9 sectores se espera que crezca m\u00e1s la demanda de edificios eficientes.<\/p>\n<p>Esta demanda se traducir\u00e1 tanto en nueva construcci\u00f3n (a nivel p\u00fablico y privado) pero tambi\u00e9n en necesidades de mejoras y de implementaci\u00f3n de sistemas de gesti\u00f3n energ\u00e9tica:<\/p>\n<ul>\n<li>Sector comercio. El 46% de los encuestados esperaban tener proyectos de edificios eficientes en este sector en los pr\u00f3ximos 3 a\u00f1os.<\/li>\n<li>Administraciones p\u00fablicas. Estados Unidos tiene el mayor porcentaje de encuestados (46%) que esperan tener un proyecto de edificio verde en el sector, probablemente debido a nuevos requisitos legales y de certificaciones.<\/li>\n<li>Edificios ya construidos. El 40% de los encuestados cree que llevar\u00e1n a cabo proyectos de mejoras. Este porcentaje destaca especialmente en Reino Unido, Sud\u00e1frica y Singapur.<\/li>\n<\/ul>\n<h2><b>Claves que Incrementan el N\u00famero de Edificios Eficientes<\/b><\/h2>\n<ul>\n<li style=\"font-weight: 400;\">La <strong>demanda por parte del cliente,<\/strong> es consistente y es un primer paso importante.<\/li>\n<li style=\"font-weight: 400;\">La demanda del mercado, que, sin embargo, ha ido disminuyendo ligeramente a nivel global<\/li>\n<li style=\"font-weight: 400;\">El mayor crecimiento desde 2012 de acuerdo con el estudio es el <strong>regulativo.<\/strong> Parece uno de los factores de crecimiento m\u00e1s relevantes.<\/li>\n<li style=\"font-weight: 400;\">Sin embargo el \u00abhacer las cosas bien\u00bb no es uno de los motivos que los encuestados aceptan como impulso para apostar por eficiencia en construcci\u00f3n.<\/li>\n<li style=\"font-weight: 400;\">Tampoco parece que vean la transformaci\u00f3n del mercado como un aliciente para el desarrollo \u00abverde\u00bb.<\/li>\n<li style=\"font-weight: 400;\">La <strong>imagen de marca<\/strong> y las relaciones p\u00fablicas parecen haber aumentado su importancia como motivo para ser m\u00e1s ecol\u00f3gico y sostenible en el estudio de 2015 frente al de 2012.<\/li>\n<\/ul>\n<p>Cada pa\u00eds tiene sus propias caracter\u00edsticas en este sentido, por lo tanto es muy recomendable, de nuevo, leer el estudio completo para comprobar diferencias y adaptar tu trabajo en el \u00e1mbito de la eficiencia energ\u00e9tica a los pa\u00edses en los que trabajes en el momento.<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-node hs-cta-5d3f3588-e21d-4193-b122-c43715071698\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/5d3f3588-e21d-4193-b122-c43715071698\"><img decoding=\"async\" id=\"hs-cta-img-5d3f3588-e21d-4193-b122-c43715071698\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/5d3f3588-e21d-4193-b122-c43715071698.png\" alt=\"\u00a1Consigue tu copia! \" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, '5d3f3588-e21d-4193-b122-c43715071698', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\t\t<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los llamemos edificios sostenibles, edificios eficientes o edificios \u00abverdes\u00bb lo cierto es que esta forma de edificaci\u00f3n\u00a0est\u00e1 siendo ampliamente aceptada en todo el mundo, y tiene\u00a0perspectivas de crecimiento en casi todos los pa\u00edses, pero principalmente en los m\u00e1s desarrollados. Hoy hablamos de tendencias de edificios inteligentes a ra\u00edz de la \u00faltima encuesta World Green Buildings [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":34,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-38061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tendencias de Edificios Eficientes 2016 - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tendencias de Edificios Eficientes 2016\" \/>\n<meta property=\"og:description\" content=\"Los llamemos edificios sostenibles, edificios eficientes o edificios \u00abverdes\u00bb lo cierto es que esta forma de edificaci\u00f3n\u00a0est\u00e1 siendo ampliamente aceptada en todo el mundo, y tiene\u00a0perspectivas de crecimiento en casi todos los pa\u00edses, pero principalmente en los m\u00e1s desarrollados. Hoy hablamos de tendencias de edificios inteligentes a ra\u00edz de la \u00faltima encuesta World Green Buildings [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-29T06:24:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Tendencias de Edificios Eficientes 2016\",\"datePublished\":\"2016-02-29T06:24:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/\"},\"wordCount\":1109,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/\",\"name\":\"Tendencias de Edificios Eficientes 2016 - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"datePublished\":\"2016-02-29T06:24:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/tendencias-edificios-eficientes-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tendencias de Edificios Eficientes 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tendencias de Edificios Eficientes 2016 - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/","og_locale":"es_ES","og_type":"article","og_title":"Tendencias de Edificios Eficientes 2016","og_description":"Los llamemos edificios sostenibles, edificios eficientes o edificios \u00abverdes\u00bb lo cierto es que esta forma de edificaci\u00f3n\u00a0est\u00e1 siendo ampliamente aceptada en todo el mundo, y tiene\u00a0perspectivas de crecimiento en casi todos los pa\u00edses, pero principalmente en los m\u00e1s desarrollados. Hoy hablamos de tendencias de edificios inteligentes a ra\u00edz de la \u00faltima encuesta World Green Buildings [&hellip;]","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2016-02-29T06:24:46+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Tendencias de Edificios Eficientes 2016","datePublished":"2016-02-29T06:24:46+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/"},"wordCount":1109,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/","name":"Tendencias de Edificios Eficientes 2016 - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","datePublished":"2016-02-29T06:24:46+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/tendencias-edificios-eficientes-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tendencias de Edificios Eficientes 2016"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=38061"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/34"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=38061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=38061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=38061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}