


{"id":38011,"date":"2016-06-21T06:30:34","date_gmt":"2016-06-21T04:30:34","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/hardware-de-eficiencia-energetica-formacion\/"},"modified":"2016-06-21T06:30:34","modified_gmt":"2016-06-21T04:30:34","slug":"hardware-de-eficiencia-energetica-formacion","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/","title":{"rendered":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Medidores, concentradores, sondas\u2026 los dispositivos de <strong>hardware de\u00a0eficiencia energ\u00e9tica son la asignatura pendiente de muchos profesionales de la energ\u00eda.<\/strong> <\/span><span style=\"font-weight: 400;\">Y, sin embargo, son esenciales para empezar con buen pie un proyecto de eficiencia energ\u00e9tica o para intentar potenciar el ahorro en proyectos con un cierto tiempo de vida. <\/span><\/p>\n<p><!--more--><br \/>\n<!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-node hs-cta-eaf29681-d40d-4932-bb06-25b6bfecddfd\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/eaf29681-d40d-4932-bb06-25b6bfecddfd\"><img decoding=\"async\" id=\"hs-cta-img-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/eaf29681-d40d-4932-bb06-25b6bfecddfd.png\" alt=\"\u00a1Consigue tu kit gratuito de aprendizaje!\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"font-weight: 400;\">Hardware para Eficiencia Energ\u00e9tica <\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Como sab\u00e9is, en DEXMA el hardware no es el centro de nuestro negocio, nosotros nos dedicamos a desarrollar para ti<\/span><b> el software de an\u00e1lisis energ\u00e9tico m\u00e1s completo del mercado. <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo,<\/span><b> desde el principio, hemos tenido muy en cuenta<\/b><span style=\"font-weight: 400;\"> la parte f\u00edsica de la tecnolog\u00eda de gesti\u00f3n energ\u00e9tica, <\/span><b>el hardware. <\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfC\u00f3mo lo hemos hecho? B\u00e1sicamente, cumpliendo a rajatabla tres preceptos importantes: <\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\"><b>Proponiendo una plataforma \u201chardware-neutral\u201d. <\/b><span style=\"font-weight: 400;\">Esto significa que tenemos cientos de dispositivos integrados ya en ella, por lo que en cuanto crees tu cuenta en DEXCell Energy Manager, es probable que puedas empezar a recibir datos. <\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Proponiendo una plataforma abierta.<\/b><span style=\"font-weight: 400;\"> Con nuestra API, puedes o podemos integrar cualquier nuevo dispositivo que necesites. <\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Contando con partners de hardware de excepci\u00f3n,<\/b><span style=\"font-weight: 400;\"> como Carlo Gavazzi (ya os presentamos alguno de sus productos <a href=\"http:\/\/www.dexma.com\/es\/blog\/datalogger-vmu-c-em-dexcell\/\">aqu\u00ed<\/a>), Socomec o Satel. <\/span><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">De esta manera, <strong>estamos listos para integrarnos con cualquier medidor o concentrador del mercado, de forma f\u00e1cil y r\u00e1pida. <\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nuestro equipo de <\/span><a href=\"http:\/\/support.dexmatech.com\/\"><span style=\"font-weight: 400;\">soporte<\/span><\/a><span style=\"font-weight: 400;\"> atiende a diario much\u00edsimas preguntas con respecto al hardware, ya que no es f\u00e1cil por completo el ecosistema del hardware de eficiencia energ\u00e9tica. <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Por eso, os proponemos que en julio todos nos pongamos al d\u00eda<\/strong> con este \u201casunto pendiente\u201d en una sesi\u00f3n con nuestro experto en hardware, Alfonso Mateos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alfonso es uno de los t\u00e9cnicos que atiende a diario vuestras preguntas sobre hardware de medici\u00f3n y control de la energ\u00eda.\u00a0Antes de su llegada a DEXMA, Alfonso trabaj\u00f3 como muchos de vosotros: como gestor energ\u00e9tico. En esa etapa profesional comenz\u00f3 su trabajo con el hardware, con especial hincapie en el trabajo sobre el terreno.\u00a0<\/span><br \/>\n<span id=\"hs-cta-wrapper-0a6dda05-7ab1-4256-8d07-e3e4b915df84\" class=\"hs-cta-wrapper\"><br \/>\n<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Webinar Gratuito: Hardware de Eficiencia Energ\u00e9tica<\/span><\/h2>\n<p><span style=\"font-weight: 400;\"><a href=\"http:\/\/get.dexmatech.com\/hardware-eficiencia-energetica\">En esta formaci\u00f3n grabada en v\u00eddeo compartimos<\/a> con todos vosotros toda nuestra \u201csabidur\u00eda\u201d sobre hardware en una sesi\u00f3n completamente gratuita en la que revisaremos:\u00a0<\/span><\/p>\n<ul>\n<li>Conceptos esenciales sobre hardware, que tienes que entender y manejar sin problemas. Desde c\u00f3mo se mide cada fuente energ\u00e9tica, hasta las diferencias entre una sonda y un concentrador.<\/li>\n<li><strong>\u00bfC\u00f3mo s\u00e9 qu\u00e9 hardware necesito?<\/strong> Veremos qu\u00e9 evaluar en los c<strong>asos en los que no hay ning\u00fan dispositivo de medici\u00f3n y los casos en los que ya se cuenta con datos<\/strong> y medidores<\/li>\n<li><strong>Precios<\/strong>: sabemos que es algo que os preocupa a todos, as\u00ed que os orientaremos tambi\u00e9n sobre qu\u00e9 implicaciones tiene, a nivel de costes, cada dispositivo.<\/li>\n<li><strong>Comunicaciones.<\/strong> Con Alfonso revisaremos mejores pr\u00e1cticas a la hora de c\u00f3mo configurar el env\u00edo de datos de nuestro hardware a nuestra plataforma de an\u00e1lisis energ\u00e9tico.<\/li>\n<\/ul>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-node hs-cta-eaf29681-d40d-4932-bb06-25b6bfecddfd\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/eaf29681-d40d-4932-bb06-25b6bfecddfd\"><img decoding=\"async\" id=\"hs-cta-img-eaf29681-d40d-4932-bb06-25b6bfecddfd\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/eaf29681-d40d-4932-bb06-25b6bfecddfd.png\" alt=\"\u00a1Consigue tu kit gratuito de aprendizaje!\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<p>Y pronto dedicaremos m\u00e1s art\u00edculos del blog (y alg\u00fan que otro material sorpresa) al mundo del hardware. \u00bfQuieres ser el primero o primera en leerlos? Suscr\u00edbete hoy mismo a nuestro blog:<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-935127d1-fff8-42b0-a1d0-992c306abf05\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-935127d1-fff8-42b0-a1d0-992c306abf05\" class=\"hs-cta-node hs-cta-935127d1-fff8-42b0-a1d0-992c306abf05\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/935127d1-fff8-42b0-a1d0-992c306abf05\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-935127d1-fff8-42b0-a1d0-992c306abf05\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/935127d1-fff8-42b0-a1d0-992c306abf05.png\" alt=\"New Call-to-action\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Medidores, concentradores, sondas\u2026 los dispositivos de hardware de\u00a0eficiencia energ\u00e9tica son la asignatura pendiente de muchos profesionales de la energ\u00eda. Y, sin embargo, son esenciales para empezar con buen pie un proyecto de eficiencia energ\u00e9tica o para intentar potenciar el ahorro en proyectos con un cierto tiempo de vida.<\/p>\n","protected":false},"author":39,"featured_media":34,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-38011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online] - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]\" \/>\n<meta property=\"og:description\" content=\"Medidores, concentradores, sondas\u2026 los dispositivos de hardware de\u00a0eficiencia energ\u00e9tica son la asignatura pendiente de muchos profesionales de la energ\u00eda. Y, sin embargo, son esenciales para empezar con buen pie un proyecto de eficiencia energ\u00e9tica o para intentar potenciar el ahorro en proyectos con un cierto tiempo de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-21T04:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]\",\"datePublished\":\"2016-06-21T04:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/\"},\"wordCount\":540,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/\",\"name\":\"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online] - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"datePublished\":\"2016-06-21T04:30:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-spacewell-avatar-512x512-1.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/hardware-de-eficiencia-energetica-formacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online] - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/","og_locale":"es_ES","og_type":"article","og_title":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]","og_description":"Medidores, concentradores, sondas\u2026 los dispositivos de hardware de\u00a0eficiencia energ\u00e9tica son la asignatura pendiente de muchos profesionales de la energ\u00eda. Y, sin embargo, son esenciales para empezar con buen pie un proyecto de eficiencia energ\u00e9tica o para intentar potenciar el ahorro en proyectos con un cierto tiempo de vida.","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2016-06-21T04:30:34+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]","datePublished":"2016-06-21T04:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/"},"wordCount":540,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/","name":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online] - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","datePublished":"2016-06-21T04:30:34+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/cropped-spacewell-avatar-512x512-1.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/hardware-de-eficiencia-energetica-formacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hardware de Eficiencia Energ\u00e9tica [Formaci\u00f3n Online]"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=38011"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/38011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/34"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=38011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=38011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=38011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}