


{"id":37457,"date":"2021-09-23T11:35:41","date_gmt":"2021-09-23T09:35:41","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/"},"modified":"2021-09-23T11:35:41","modified_gmt":"2021-09-23T09:35:41","slug":"data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/","title":{"rendered":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Hist\u00f3ricamente, el \u00fanico conocimiento por parte de los consumidores sobre su uso energ\u00e9tico ha sido a trav\u00e9s de su factura en papel de su comercializadora. Seg\u00fan las estad\u00edsticas solo <\/span><a href=\"https:\/\/www.ocu.org\/vivienda-y-energia\/gas-luz\/consejos\/como-descifrar-la-factura-de-la-luz\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">el 11% de los usuarios entiende su factura<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La llegada de plataformas de datos como los Data Hubs de energ\u00eda, est\u00e1n revolucionando el papel del consumidor respecto a la transici\u00f3n energ\u00e9tica. Descubre que es un Data Hub Energ\u00e9tico y cu\u00e1les son los beneficios de estas plataformas de datos para los consumidores:<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Todos somos conscientes de que la digitalizaci\u00f3n est\u00e1 cambiando nuestro d\u00eda a d\u00eda, y en el caso del sector energ\u00e9tico, esta transformaci\u00f3n digital est\u00e1 marcando un precedente. A nivel mundial, se estima que <\/span><a href=\"https:\/\/www.mincotur.gob.es\/Publicaciones\/Publicacionesperiodicas\/EconomiaIndustrial\/RevistaEconomiaIndustrial\/406\/SEGUNDA%20NOTA.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><b>desde el a\u00f1o 2014 las inversiones en infraestructuras el\u00e9ctricas digitales y software est\u00e1n creciendo a un ritmo anual del 20%<\/b><\/a>.<b>\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Este cambio de paradigma impulsado ampliamente por el \u2018 <\/span><a href=\"https:\/\/ec.europa.eu\/info\/news\/action-plan-digitalisation-energy-sector-roadmap-launched-2021-jul-27_en\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">European Green Deal<\/span><\/a><span style=\"font-weight: 400;\">\u2019 persigue un mercado el\u00e9ctrico democr\u00e1tico, transparente y neutral en el que todas las partes involucradas (producci\u00f3n, distribuci\u00f3n, comercializaci\u00f3n, otros agentes involucrados y sobre todo los consumidores y organizaciones) hablen el mismo idioma y formen parte de un n\u00facleo energ\u00e9tico m\u00e1s abierto y competitivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La clave para alcanzar con \u00e9xito este objetivo reside en gran parte en ofrecer un acceso abierto y neutro de los datos energ\u00e9ticos que permita dar el protagonismo al consumidor. Esto permite al consumidor evolucionar hacia un <\/span><b>rol cliente-proveedor digital <\/b><span style=\"font-weight: 400;\">que adem\u00e1s de consumir productos y servicios participa activamente, teniendo m\u00e1s poder respecto a sus consumos energ\u00e9ticos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37103 \" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3.png\" alt=\"Qu\u00e9 es un Data Hub de Energ\u00eda\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3.png 900w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3-300x300.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3-150x150.png 150w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3-768x768.png 768w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/ES-Data-Hub-Illustration-DEXMA-Branding-v3-700x700.png 700w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una de las herramientas que ya son una realidad y permiten esta transici\u00f3n del mercado energ\u00e9tico son los <\/span><b>\u201cdata hubs\u201d<\/b><span style=\"font-weight: 400;\"> o plataformas neutras que permiten al usuario tener el control digital de sus propios datos de consumo y generaci\u00f3n energ\u00e9tica.<\/span><\/p>\n<h2><span style=\"color: #003b6f;\">6 Beneficios del \u201cData Hub\u201d Energ\u00e9tico para el Consumidor\u00a0<\/span><\/h2>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Innovaci\u00f3n. <\/b><span style=\"font-weight: 400;\">Los datos procedentes del despliegue de contadores inteligentes de telegesti\u00f3n se ponen al alcance del consumidor para ayudarle en la toma de decisiones b\u00e1sicas, como por ejemplo, en la elecci\u00f3n de la mejor tarifa de acceso.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Conocimiento. <\/b><span style=\"font-weight: 400;\">Acercar los consumos energ\u00e9ticos pr\u00e1cticamente en tiempo real al consumidor\/organizaci\u00f3n le permite entender mejor sus h\u00e1bitos energ\u00e9ticos y en consecuencia su factura.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Ahorro. <\/b><span style=\"font-weight: 400;\">Una vez que el cliente entiende sus usos energ\u00e9ticos, puede optimizar la toma de decisiones relativas a sostenibilidad y abrir la puerta a la eficiencia energ\u00e9tica con el objetivo de ahorrar y reducir su factura.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Integraci\u00f3n. <\/b><span style=\"font-weight: 400;\">El consumidor es consciente de que puede jugar un papel m\u00e1s activo en su relaci\u00f3n con los agentes del sistema energ\u00e9tico, como por ejemplo, gestionando su demanda e incorporando su flexibilidad al mercado mediante el autoconsumo, la acumulaci\u00f3n, el veh\u00edculo el\u00e9ctrico, etc.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Transparencia. <\/b><span style=\"font-weight: 400;\">Los datos que se comparten en la plataforma pertenecen al consumidor y como tal contar\u00e1 con un acceso universal, neutro y\u00a0 seguro.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Valor a\u00f1adido. <\/b><span style=\"font-weight: 400;\">Bajo el consentimiento del consumidor, este puede poner a disposici\u00f3n de nuevos agentes del mercado sus datos energ\u00e9ticos. Como por ejemplo, empresas proveedoras de servicios energ\u00e9ticos digitales como <\/span><a href=\"http:\/\/www.dexma.com\/es\/\"><span style=\"font-weight: 400;\">Dexma<\/span><\/a><span style=\"font-weight: 400;\">, que le ayuden en su transici\u00f3n energ\u00e9tica hacia el ahorro y la descarbonizaci\u00f3n.<\/span><\/li>\n<\/ol>\n<h2><span style=\"color: #003b6f;\">5 Ejemplos de Data Hubs Energ\u00e9ticos<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Existen en la actualidad m\u00faltiples plataformas o \u201cData Hubs\u201d a nivel mundial desarrolladas por los diferentes agentes el\u00e9ctricos (operadores de la red de transporte, empresas distribuidoras, comercializadoras) que ya ponen los datos de consumo el\u00e9ctrico a disposici\u00f3n del consumidor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A continuaci\u00f3n repasamos algunos ejemplos de Data Hub de energ\u00eda:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Green Button &#8211; EE. UU. <\/b><span style=\"font-weight: 400;\">\u00a0Promovido por la Casa Blanca en 2012 (pioneros a nivel mundial), <\/span><a href=\"https:\/\/www.greenbuttondata.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">green button<\/span><\/a><span style=\"font-weight: 400;\"> da acceso a datos energ\u00e9ticos (luz, gas y agua) a los clientes finales mediante la alianza de diferentes agentes (8 comercializadoras, 19 proveedores de servicios energ\u00e9ticos y 9 gobiernos y asociaciones de diferentes \u00e1mbitos).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>ElHub &#8211; Noruega<\/b><span style=\"font-weight: 400;\"><strong>.<\/strong> El data hub noruego (<\/span><a href=\"https:\/\/elhub.no\/en\/about-elhub\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Elhub<\/span><\/a><span style=\"font-weight: 400;\">) cuenta con 3 millones de consumidores que pueden usar la plataforma incluso para cambiar de comercializadora autom\u00e1ticamente sin tener que seguir la v\u00eda tradicional.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Energinet &#8211; Dinamarca. <\/b><span style=\"font-weight: 400;\">La plataforma danesa (<\/span><a href=\"https:\/\/en.energinet.dk\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Energinet<\/span><\/a><span style=\"font-weight: 400;\">) dispone de datos de consumo energ\u00e9tico de 3.3 millones de consumidores., Primera precursora\u00a0 en Europa, ha hecho p\u00fablico su <\/span><b>know-how t\u00e9cnico<\/b><span style=\"font-weight: 400;\"> para que otros pa\u00edses se animen a crear su propio Data Hub<\/span><span style=\"font-weight: 400;\">.<\/span><b><\/b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-36992\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Energinet.png\" alt=\"Energinet\" width=\"828\" height=\"322\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Energinet.png 828w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Energinet-300x117.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Energinet-768x299.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><b>Estfeed &#8211; Estonia.\u00a0 <\/b><span style=\"font-weight: 400;\">Siendo uno de los pa\u00edses l\u00edderes en la digitalizaci\u00f3n europea, su plataforma (<\/span><a href=\"https:\/\/www.estfeed.eu\/en\/home\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Estfeed<\/span><\/a><span style=\"font-weight: 400;\">) ha liderado la integraci\u00f3n de proveedores externos que den valor a\u00f1adido al consumidor. DEXMA ha sido una de las organizaciones que ha participado en esta fase inicial para demostrar <\/span><a href=\"https:\/\/elering.ee\/en\/european-energy-data-access-pilots-2020\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">como contar con un datahub europeo puede acercar la eficiencia energ\u00e9tica al consumidor final<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0 <\/span><\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><b>Datadis &#8211; Espa\u00f1a. <\/b><span style=\"font-weight: 400;\">En 2020 todas las empresas de distribuci\u00f3n espa\u00f1olas lanzaron al mercado una interfaz com\u00fan, <\/span><a href=\"https:\/\/datadis.es\/\"><span style=\"font-weight: 400;\">Datadis<\/span><\/a><span style=\"font-weight: 400;\">, donde m\u00e1s de 29 millones de consumidores pueden acceder a todos sus puntos de suministro independientemente de la distribuidora que tengan. Los consumidores pueden consultar tanto informaci\u00f3n p\u00fablica agregada estad\u00edstica (por ejemplo informes) como informaci\u00f3n privada de su consumo con un hist\u00f3rico de 2 a\u00f1os (de la cual son propietarios) pudiendo dar acceso a terceros, v\u00eda su <\/span><a href=\"http:\/\/www.dexma.com\/es\/blog-es\/api-software-gestion-energetica\/\"><span style=\"font-weight: 400;\">API<\/span><\/a><span style=\"font-weight: 400;\">, como por ejemplo a Dexma.<\/span><\/li>\n<\/ul>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-82e2ca78-34cf-4bd2-b53d-2ef502e316bb\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-82e2ca78-34cf-4bd2-b53d-2ef502e316bb\" class=\"hs-cta-node hs-cta-82e2ca78-34cf-4bd2-b53d-2ef502e316bb\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/82e2ca78-34cf-4bd2-b53d-2ef502e316bb\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-82e2ca78-34cf-4bd2-b53d-2ef502e316bb\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/82e2ca78-34cf-4bd2-b53d-2ef502e316bb.png\" alt=\"DEXMA Software de Gesti\u00f3n de Energ\u00eda\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"color: #003b6f;\">Caso de \u00c9xito Datadis &#8211; DEXMA<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Hasta ahora, el acceso a los datos energ\u00e9ticos por parte de los consumidores y gestores energ\u00e9ticos se ha llevado a cabo mediante m\u00faltiples v\u00edas: datos de factura, recogida manual de datos de contador, instalaci\u00f3n de concentradores y medidores, sensores, etc. Constituyendo todos ellos la fuente de datos para plataformas que dan valor a\u00f1adido como <\/span><a href=\"http:\/\/www.dexma.com\/es\/que-es-la-plataforma-dexma\/\"><b>la Plataforma de Gesti\u00f3n Energ\u00e9tica Dexma<\/b><\/a>\u00a0<span style=\"font-weight: 400;\">(Dexma Detect, Dexma Analyse &amp; Dexma Optimise).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La dificultad de implementar dichas fuentes de datos, ha supuesto una fricci\u00f3n importante a la hora de acercar la digitalizaci\u00f3n en el sector energ\u00e9tico al consumidor final. &#8211;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Afortunadamente, gracias al lanzamiento de Datadis en el a\u00f1o 2020 y posterior apertura mediante API en 2021, el proceso de obtenci\u00f3n de datos de consumo de los contadores inteligentes, por parte de plataformas como Dexma, se ha simplificado notablemente. Esto ha permitido la integraci\u00f3n autom\u00e1tica de Dexma con Datadis, sin necesidad de recurrir a los m\u00e9todos anteriores de obtenci\u00f3n de datos (facturas, instalaci\u00f3n de medidores, etc.).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta integraci\u00f3n ya permite que los consumidores\/organizaciones espa\u00f1oles puedan disponer de sus datos en tiempo real e hist\u00f3rico de 2 a\u00f1os en nuestra plataforma, ayud\u00e1ndoles a ser m\u00e1s sostenibles, siguiendo nuestro camino de la eficiencia propuesto: Detectar, Analizar y Optimizar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para <\/span><b>disponer de tus datos de consumo en nuestra plataforma,<\/b><span style=\"font-weight: 400;\"> solo hay que llevar a cabo estos 2 pasos (que puedes completar en menos de 5 minutos):\u00a0<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Registrarte en la plataforma <\/span><a href=\"https:\/\/datadis.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Datadis<\/span><\/a><span style=\"font-weight: 400;\"> y rellena el formulario de registro.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Da de alta el\/los puntos de suministro en la plataforma de Dexma usando las mismas credenciales de Datadis.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37025 alignnone\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting.png\" alt=\"\" width=\"618\" height=\"252\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting.png 1895w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting-300x123.png 300w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting-1400x572.png 1400w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting-768x314.png 768w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Datadis-DEXMA-setting-1536x627.png 1536w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una vez completado este proceso, si ya eres usuario de Dexma, dispondr\u00e1s de los datos en nuestra plataforma y podr\u00e1s beneficiarte de un acceso neutro y abierto a tus datos energ\u00e9ticos pudiendo participar activamente en la toma de decisiones para ahorrar energ\u00eda y poder as\u00ed reducir tus facturas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tal y como exponemos en este art\u00edculo, la transici\u00f3n del mercado energ\u00e9tico espa\u00f1ol est\u00e1 en marcha, y <\/span><b>Datadis es una de las iniciativas pensadas para acercar la transformaci\u00f3n digital al consumidor final<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dexma es ya una parte importante del proceso, que ayudar\u00e1 a dar el protagonismo que se merece al prosumidor como agente activo del sistema energ\u00e9tico. La idea es que lo siga siendo en futuros data hubs a nivel mundial.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si quieres saber m\u00e1s sobre la <strong>Plataforma<\/strong> avanzada de <strong>Gesti\u00f3n Energ\u00e9tica de Dexma<\/strong> y c\u00f3mo trabajar con Datadis, <a href=\"https:\/\/get.dexma.com\/demo-gratuita\"><strong>cont\u00e1ctanos aqu\u00ed y echa un vistazo a la demo<\/strong><\/a>.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-250cdbf8-0369-49c1-beea-76f44236ca3c\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-250cdbf8-0369-49c1-beea-76f44236ca3c\" class=\"hs-cta-node hs-cta-250cdbf8-0369-49c1-beea-76f44236ca3c\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/250cdbf8-0369-49c1-beea-76f44236ca3c\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-250cdbf8-0369-49c1-beea-76f44236ca3c\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/250cdbf8-0369-49c1-beea-76f44236ca3c.png\" alt=\"New Call-to-action\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<hr \/>\n<p><b><i>Nota del Editor<\/i><\/b><i> \u2013 Este art\u00edculo ha sido redactado por una de nuestras expertas en gesti\u00f3n energ\u00e9tica avanzada:<\/i><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/lauramartinezrodriguez\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37118 alignleft\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/09\/Laura-Martinez-Photo-green.png\" alt=\"\" width=\"150\" height=\"150\" \/>Laura Mart\u00ednez<\/strong><\/a><i>, <strong>Product Owner y Product Marketing de DEXMA Detect,<\/strong> forma parte del equipo de DEXMA desde 2015. Con un pasado en proyectos de investigaci\u00f3n y desarrollo, en la actualidad es la persona responsable de DEXMA Detect. Su objetivo es liderar la estrategia del producto para ayudar a aquellos usuarios, mercados y\u00a0 futuros clientes que persiguen potenciar el\u00a0 ahorro y\u00a0 la eficiencia energ\u00e9tica.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hist\u00f3ricamente, el \u00fanico conocimiento por parte de los consumidores sobre su uso energ\u00e9tico ha sido a trav\u00e9s de su factura en papel de su comercializadora. Seg\u00fan las estad\u00edsticas solo el 11% de los usuarios entiende su factura.\u00a0 La llegada de plataformas de datos como los Data Hubs de energ\u00eda, est\u00e1n revolucionando el papel del consumidor [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":37458,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-37457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor\" \/>\n<meta property=\"og:description\" content=\"Hist\u00f3ricamente, el \u00fanico conocimiento por parte de los consumidores sobre su uso energ\u00e9tico ha sido a trav\u00e9s de su factura en papel de su comercializadora. Seg\u00fan las estad\u00edsticas solo el 11% de los usuarios entiende su factura.\u00a0 La llegada de plataformas de datos como los Data Hubs de energ\u00eda, est\u00e1n revolucionando el papel del consumidor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T09:35:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor\",\"datePublished\":\"2021-09-23T09:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/\"},\"wordCount\":1438,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Data-Hubs.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/\",\"name\":\"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Data-Hubs.png\",\"datePublished\":\"2021-09-23T09:35:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Data-Hubs.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Data-Hubs.png\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/","og_locale":"es_ES","og_type":"article","og_title":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor","og_description":"Hist\u00f3ricamente, el \u00fanico conocimiento por parte de los consumidores sobre su uso energ\u00e9tico ha sido a trav\u00e9s de su factura en papel de su comercializadora. Seg\u00fan las estad\u00edsticas solo el 11% de los usuarios entiende su factura.\u00a0 La llegada de plataformas de datos como los Data Hubs de energ\u00eda, est\u00e1n revolucionando el papel del consumidor [&hellip;]","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-09-23T09:35:41+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor","datePublished":"2021-09-23T09:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/"},"wordCount":1438,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/","name":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png","datePublished":"2021-09-23T09:35:41+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/09\/Data-Hubs.png","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/data-hubs-de-energia-y-la-digitalizacion-del-consumidor-de-energia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cu\u00e1l es el Papel de los Data Hubs en el nuevo Rol Digital del Consumidor"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=37457"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/37458"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=37457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=37457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=37457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}