


{"id":37436,"date":"2021-10-15T12:30:25","date_gmt":"2021-10-15T10:30:25","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/"},"modified":"2021-10-15T12:30:25","modified_gmt":"2021-10-15T10:30:25","slug":"contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/","title":{"rendered":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p>El Contrato de Rendimiento Energ\u00e9tico (CRE), tambi\u00e9n conocido por sus siglas en ingl\u00e9s EPC,\u00a0 es una de las modalidades de contrataci\u00f3n de servicios energ\u00e9ticos. En este art\u00edculo explicamos <b>qu\u00e9 es el Contrato de Rendimiento Energ\u00e9tico<\/b> y qu\u00e9 herramienta puede ayudar a tu compa\u00f1\u00eda a garantizar la reducci\u00f3n del consumo de energ\u00eda sea cual sea su sector de actividad: industria, sector servicios, administraci\u00f3n p\u00fablica, transporte, etc.<\/p>\n<p><!--more--><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-8d00a0c2-0a73-47e4-a52b-3f57e0703d19\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-8d00a0c2-0a73-47e4-a52b-3f57e0703d19\" class=\"hs-cta-node hs-cta-8d00a0c2-0a73-47e4-a52b-3f57e0703d19\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/8d00a0c2-0a73-47e4-a52b-3f57e0703d19\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-8d00a0c2-0a73-47e4-a52b-3f57e0703d19\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/8d00a0c2-0a73-47e4-a52b-3f57e0703d19.png\" alt=\"DEMO de la Plataforma DEXMA\" \/><\/a><\/span><\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Qu\u00e9 es un Contrato de Rendimiento Energ\u00e9tico o EPC<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El ahorro y la eficiencia energ\u00e9tica juegan un papel esencial en la estrategia energ\u00e9tica de los pa\u00edses occidentales para lograr los objetivos de transici\u00f3n energ\u00e9tica. Las Directivas 2006\/32\/CE, <\/span><a href=\"http:\/\/www.dexma.com\/es\/blog-es\/4-puntos-clave-de-la-directiva-europea-de-eficiencia-energetica\/#more-20022\"><span style=\"font-weight: 400;\">2012\/27\/UE de Eficiencia Energ\u00e9tica<\/span><\/a><span style=\"font-weight: 400;\"> a nivel europeo, y el <\/span><a href=\"http:\/\/www.dexma.com\/es\/blog-es\/rd-56-2016-jornada-barcelona-ceec\/\"><span style=\"font-weight: 400;\">RD 56\/2016<\/span><\/a><span style=\"font-weight: 400;\"> a nivel nacional son algunas de las herramientas implementadas por las distintas Administraciones para fomentar el desarrollo del sector de la Eficiencia Energ\u00e9tica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lanzados por la Uni\u00f3n Europea (UE) en 2006 &#8211; inicialmente para el sector de la construcci\u00f3n &#8211; los Contratos de Rendimiento Energ\u00e9tico (CRE) tienen como objetivo mejorar la eficiencia energ\u00e9tica de los edificios. Es un v\u00ednculo entre un cliente y un operador especializado en servicios energ\u00e9ticos con el que se adquiere un compromiso interno para implantar sistemas de optimizaci\u00f3n de los consumos de energ\u00eda. Es decir, el <\/span><b>objetivo principal de un EPC es reducir el consumo energ\u00e9tico de los edificios<\/b><span style=\"font-weight: 400;\">, ya sean p\u00fablicos o privados (viviendas, terciarios, industriales, autoridades locales), y garantizar este esfuerzo a lo largo del tiempo.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conseguir que una empresa o un edificio consuman menos energ\u00eda no es una tarea sencilla: el an\u00e1lisis es complejo y requiere cierta experiencia. A menudo, la empresa ni siquiera es capaz de identificar la forma m\u00e1s adecuada de reducir las emisiones contaminantes de sus edificios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El contrato de rendimiento energ\u00e9tico permite a cada empresa gestionar todo su rendimiento energ\u00e9tico con la ayuda de un especialista. La empresa puede as\u00ed delegar la gesti\u00f3n de la energ\u00eda, amortizando su coste gracias al ahorro generado.\u00a0<\/span><\/p>\n<p><b>El EPC se diferencia de otros servicios energ\u00e9ticos en que combina una inversi\u00f3n para mejorar la eficiencia energ\u00e9tica de un edificio con una garant\u00eda de reducci\u00f3n del consumo energ\u00e9tico<\/b>. <span style=\"font-weight: 400;\">Por eso, se denomina contrato de garant\u00eda de rendimiento energ\u00e9tico (EPC).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al garantizar una reducci\u00f3n del consumo (y, por tanto, a menudo de la factura energ\u00e9tica), el operador de servicios energ\u00e9ticos (ESE) se compromete con el impacto de las medidas en el consumo de la industria o del parque inmobiliario. Si no se alcanza el objetivo, el operador paga una penalizaci\u00f3n (malus) a su cliente. Si se alcanza y supera el objetivo, los beneficios (bonificaci\u00f3n) se reparten entre las dos partes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En definitiva, un EPC o CRE debe:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Definir una situaci\u00f3n de partida,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Definir las acciones de rendimiento energ\u00e9tico para lograr el ahorro de energ\u00eda,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Garantizar el ahorro de energ\u00eda a lo largo del tiempo y reducir la huella de carbono de su edificio o grupo de edificios.<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400; color: #41659e;\">\u00bfQui\u00e9nes son los actores en un Contrato de Rendimiento Energ\u00e9tico (CRE)?<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Por un lado tenemos, cualquier <\/span>empresa<span style=\"font-weight: 400;\"> del sector servicios o industrial, que tengan que implementar EPCs:<\/span><\/p>\n<ol>\n<li><b>El sector Servicios.<\/b><span style=\"font-weight: 400;\"> Es uno de los sectores con mayor consumo, en los que el coste energ\u00e9tico tiene un gran impacto en su actividad econ\u00f3mica. Mucho de los sectores dentro de los servicios a veces cuentan con m\u00e1rgenes muy bajos que deben compensar con la reducci\u00f3n de costes. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">En su caso, reducir el consumo energ\u00e9tico es una de las mejores opciones, ya que mejoran tanto en costes como en eficiencia energ\u00e9tica, manteniendo la productividad de sus servicios. Por esta raz\u00f3n, los contratos EPC con muy beneficiosos para ellos.<br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"2\"><b>Sector Industrial.<\/b><span style=\"font-weight: 400;\"> Como gran consumidor de energ\u00eda, la industria tambi\u00e9n se beneficia de los CREs. Cualquier empresa con objetivos de rendimiento energ\u00e9tico se ve afectada por el EPC. Si tiene proyectos de eficiencia energ\u00e9tica, el EPC puede acelerar los proyectos, encontrar soluciones de financiaci\u00f3n y facilitar la experiencia de un proveedor de servicios energ\u00e9ticos.\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Y por el otro lado, los proveedores de servicios energ\u00e9ticos o <\/span><b>ESEs<\/b><span style=\"font-weight: 400;\"> que necesitan ser cada vez m\u00e1s digitales para crear servicios competitivos.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Qu\u00e9 Herramienta Ayudar\u00e1 a Cumplir la Hoja de Ruta de tu EPC<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Cuando se define un Contrato de Rendimiento Energ\u00e9tico, no es m\u00e1s que una hoja de ruta a seguir para lograr los objetivos de ahorro y eficiencia energ\u00e9tica de tus clientes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero, \u00bfqu\u00e9 herramienta puede ayudarte a seguir esta hoja de ruta?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trabajar con soluciones de monitorizaci\u00f3n y an\u00e1lisis energ\u00e9tico como la <a href=\"http:\/\/www.dexma.com\/es\/que-es-la-plataforma-dexma\/\">Plataforma DEXMA<\/a> te permitir\u00e1:<\/span><\/p>\n<p><b>1. Acceder a los datos energ\u00e9ticos mediante la integraci\u00f3n con los equipos existentes<\/b><\/p>\n<p><span style=\"font-weight: 400;\">DEXMA se conecta a m\u00faltiples fuentes de datos y luego automatiza su recogida. Pueden ser condiciones externas (meteorolog\u00eda, \u00edndices de ocupaci\u00f3n), lecturas autom\u00e1ticas de los operadores de la red (contratos de energ\u00eda, facturas, BMS, sensores IoT, sistemas de gesti\u00f3n interna, CRM&#8230;.).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A continuaci\u00f3n, los datos se analizan y se presentan en cuadros de mando personalizables que evolucionan en tiempo real.<\/span><\/p>\n<p><b>2. Cuantificar las ganancias: an\u00e1lisis y verificaci\u00f3n (Protocolo IPMVP)\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Para poder verificar y cuantificar el ahorro energ\u00e9tico conseguido, es fundamental comparar el consumo teniendo en cuenta todas las variables (clima, densidad de ocupaci\u00f3n o cualquier otra variable que influya en el consumo). Esta es la funci\u00f3n del Protocolo IPMVP (International Performance Measurement and Verification Protocol), que permite medir y controlar el consumo de energ\u00eda de un edificio que se ha beneficiado de medidas de ahorro energ\u00e9tico (rehabilitaci\u00f3n energ\u00e9tica, etc.).<\/span><\/p>\n<p><b>3. Reducir considerablemente el consumo de energ\u00eda<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Una soluci\u00f3n de gesti\u00f3n de la energ\u00eda te permite digitalizar los contratos de rendimiento energ\u00e9tico para controlar la evoluci\u00f3n de tu consumo. Esta visualizaci\u00f3n del impacto del carbono te permite identificar las prioridades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><a href=\"http:\/\/www.dexma.com\/es\/que-es-la-plataforma-dexma\/\"><span style=\"font-weight: 400;\">Plataforma de Gesti\u00f3n Energ\u00e9tica Avanzada DEXMA<\/span><\/a><span style=\"font-weight: 400;\">, adem\u00e1s de monitorizar las acciones llevadas a cabo durante el contrato, tambi\u00e9n te permitir\u00e1 obtener informes personalizados para tus clientes, an\u00e1lisis avanzados, e incluso estimaciones de consumo energ\u00e9tico.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\">\u00bfQu\u00e9 beneficios obtienes tras utilizar una Soluci\u00f3n de Gesti\u00f3n Energ\u00e9tica?\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Estos son algunos de los beneficios que obtendr\u00e1s al trabajar con una SGE durante tu Contrato de Rendimiento Energ\u00e9tico:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Cuantificaci\u00f3n f\u00e1cil y automatizada de la eficiencia de los edificios,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comparaci\u00f3n de proyectos, estudios de impacto energ\u00e9tico y financiero,\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beneficios econ\u00f3micos inmediatos por la optimizaci\u00f3n de los contratos de energ\u00eda.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En el art\u00edculo de la semana que viene, analizaremos m\u00e1s a fondo c\u00f3mo se puede utilizar la Plataforma <a href=\"http:\/\/www.dexma.com\/es\/que-es-la-plataforma-dexma\/\">DEXMA<\/a> para gestionar los contratos de rendimiento energ\u00e9tico.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La energ\u00eda estructura el mundo que nos rodea. Nuestra misi\u00f3n en DEXMA es ayudar a las personas y a las empresas a entender y optimizar su uso de la energ\u00eda.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si quieres conocer el potencial de DEXMA para los contratos EPC, contacta con nuestro equipo y <a href=\"https:\/\/get.dexma.com\/demo-gratuita\">reserva una demostraci\u00f3n gratuita personalizada<\/a>.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e\" class=\"hs-cta-node hs-cta-c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e\"><img decoding=\"async\" id=\"hs-cta-img-c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/c6d9c06a-e4b0-4c0c-9f07-8e05f0629d8e.png\" alt=\"Solicitar DEMO personalizada\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<hr \/>\n<p><span id=\"hs-cta-wrapper-56c30892-38aa-48d7-9abf-13751262fbaa\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-56c30892-38aa-48d7-9abf-13751262fbaa\" class=\"hs-cta-node hs-cta-56c30892-38aa-48d7-9abf-13751262fbaa\"><b><i>Nota del Editor<\/i><\/b><i> \u2013 Este art\u00edculo ha sido redactado por una de nuestras expertas en gesti\u00f3n energ\u00e9tica avanzada:<\/i><\/span><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37344 alignleft\" src=\"http:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/Team-Profile-Photos-2.png\" alt=\"Caroline Grisel\" width=\"162\" height=\"162\" srcset=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/Team-Profile-Photos-2.png 225w, https:\/\/www.dexma.com\/wp-content\/uploads\/2021\/10\/Team-Profile-Photos-2-150x150.png 150w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/p>\n<p><em>Caroline Grisel, forma parte del <strong>Equipo de Desarrollo Internacional<\/strong>\u00a0de DEXMA desde mayo de 2021.<br \/>\n<\/em><em>Actualmente trabaja en el equipo de ventas, asesorando a nuevos socios potenciales y clientes que buscan optimizar su consumo de energ\u00eda.<\/em><\/p>\n<p><span id=\"hs-cta-wrapper-56c30892-38aa-48d7-9abf-13751262fbaa\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-56c30892-38aa-48d7-9abf-13751262fbaa\" class=\"hs-cta-node hs-cta-56c30892-38aa-48d7-9abf-13751262fbaa\"><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/56c30892-38aa-48d7-9abf-13751262fbaa\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-56c30892-38aa-48d7-9abf-13751262fbaa\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/56c30892-38aa-48d7-9abf-13751262fbaa.png\" alt=\"DEMO soluci\u00f3n gesti\u00f3n energ\u00e9tica DEXMA personalizada\" \/><\/a><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Contrato de Rendimiento Energ\u00e9tico (CRE), tambi\u00e9n conocido por sus siglas en ingl\u00e9s EPC,\u00a0 es una de las modalidades de contrataci\u00f3n de servicios energ\u00e9ticos. En este art\u00edculo explicamos qu\u00e9 es el Contrato de Rendimiento Energ\u00e9tico y qu\u00e9 herramienta puede ayudar a tu compa\u00f1\u00eda a garantizar la reducci\u00f3n del consumo de energ\u00eda sea cual sea su [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":37437,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-37436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta\" \/>\n<meta property=\"og:description\" content=\"El Contrato de Rendimiento Energ\u00e9tico (CRE), tambi\u00e9n conocido por sus siglas en ingl\u00e9s EPC,\u00a0 es una de las modalidades de contrataci\u00f3n de servicios energ\u00e9ticos. En este art\u00edculo explicamos qu\u00e9 es el Contrato de Rendimiento Energ\u00e9tico y qu\u00e9 herramienta puede ayudar a tu compa\u00f1\u00eda a garantizar la reducci\u00f3n del consumo de energ\u00eda sea cual sea su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T10:30:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta\",\"datePublished\":\"2021-10-15T10:30:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/\"},\"wordCount\":1287,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ES-EPC-Follow-your-roadmap.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/\",\"name\":\"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ES-EPC-Follow-your-roadmap.png\",\"datePublished\":\"2021-10-15T10:30:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ES-EPC-Follow-your-roadmap.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ES-EPC-Follow-your-roadmap.png\",\"width\":1120,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/","og_locale":"es_ES","og_type":"article","og_title":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta","og_description":"El Contrato de Rendimiento Energ\u00e9tico (CRE), tambi\u00e9n conocido por sus siglas en ingl\u00e9s EPC,\u00a0 es una de las modalidades de contrataci\u00f3n de servicios energ\u00e9ticos. En este art\u00edculo explicamos qu\u00e9 es el Contrato de Rendimiento Energ\u00e9tico y qu\u00e9 herramienta puede ayudar a tu compa\u00f1\u00eda a garantizar la reducci\u00f3n del consumo de energ\u00eda sea cual sea su [&hellip;]","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2021-10-15T10:30:25+00:00","og_image":[{"width":1120,"height":630,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta","datePublished":"2021-10-15T10:30:25+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/"},"wordCount":1287,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/","name":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png","datePublished":"2021-10-15T10:30:25+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2021\/10\/ES-EPC-Follow-your-roadmap.png","width":1120,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/contrato-de-rendimiento-energetico-que-herramienta-utilizar-para-seguir-su-hoja-de-ruta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Contrato de Rendimiento Energ\u00e9tico: Qu\u00e9 Herramienta Utilizar para Seguir su Hoja de Ruta"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=37436"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/37437"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=37436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=37436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=37436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}