


{"id":37155,"date":"2024-02-23T10:30:37","date_gmt":"2024-02-23T09:30:37","guid":{"rendered":"https:\/\/spacewell.com\/sin-categorizar\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/"},"modified":"2024-02-23T10:30:37","modified_gmt":"2024-02-23T09:30:37","slug":"comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024","status":"publish","type":"post","link":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/","title":{"rendered":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024"},"content":{"rendered":"<div class=\"gb-container gb-container-d807e79e gb-container-5731d80c\">\n<p><span style=\"font-weight: 400;\">Las comercializadoras de energ\u00eda son un actor con el que casi todas las personas o empresas deben interaccionar. Las organizaciones requieren de energ\u00eda para poder desarrollar su actividad empresarial y por ello buscan las comercializadoras que mejor servicio les proporcionen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el art\u00edculo de la semana pasada nos adentramos en el contexto de las <\/span><a href=\"https:\/\/www.dexma.com\/es\/blog-es\/las-empresas-de-servicios-energeticos-y-sus-principales-retos-y-prioridades-en-2024\/\"><span style=\"font-weight: 400;\">Empresas de Servicios Energ\u00e9ticos, vimos sus retos, prioridades y tendencias<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><b> Hoy pasamos el foco a las comercializadoras de energ\u00eda<\/b><span style=\"font-weight: 400;\">. \u00bfQuieres descubrir la <\/span><b>situaci\u00f3n del mercado en Espa\u00f1a y el rol protag\u00f3nico de las comercializadoras en relaci\u00f3n con la eficiencia energ\u00e9tica<\/b><span style=\"font-weight: 400;\">? Entonces sigue leyendo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si formas parte de una comercializadora, este art\u00edculo puede abordar varios de los desaf\u00edos que enfrentas en tu d\u00eda a d\u00eda. Puedes comparar los puntos tratados con tu propia experiencia. \u00bfEncuentras coincidencias?<\/span><\/p>\n<p><!--more--><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Las Comercializadoras de Energ\u00eda en Espa\u00f1a<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Empecemos por el principio. <\/span><b>En el pasado<\/b><span style=\"font-weight: 400;\">, la fijaci\u00f3n de precios estaba exclusivamente en manos del<\/span><b> Gobierno.<\/b><span style=\"font-weight: 400;\"> Operando \u00fanicamente bajo<\/span><b> el sistema de mercado regulado<\/b><span style=\"font-weight: 400;\">. En el a\u00f1o 1997, se inici\u00f3 un <\/span><b>proceso de liberalizaci\u00f3n que se implement\u00f3 plenamente en 2009<\/b><span style=\"font-weight: 400;\">. A partir de entonces, los consumidores obtuvieron la libertad de seleccionar entre las distintas comercializadoras el\u00e9ctricas. Sin embargo, a pesar de los esfuerzos, la liberalizaci\u00f3n no se complet\u00f3 del todo y el mercado regulado a\u00fan persiste.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\">Comercializadoras de Energ\u00eda en la Actualidad<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">En la actualidad, es muy probable que al pensar en comercializadoras de energ\u00eda, <strong>te vengan a la mente los nombres de las 4 o 5 m\u00e1s grandes<\/strong>, como podr\u00edan ser Iberdrola, Endesa o Naturgy. Sin embargo,<\/span><b> existen cientos de comercializadoras de energ\u00eda en nuestro pa\u00eds<\/b><span style=\"font-weight: 400;\">, de diversos tama\u00f1os.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2024\/02\/Captura-de-pantalla-2024-02-19-a-las-15.37.24.png\" alt=\"Ranking comercializadoras de energ\u00eda 2023\" \/><\/p>\n<p><i><span style=\"font-weight: 400;\">Fuente:<\/span><\/i><a href=\"https:\/\/www.naturelek.com\/ranking-comercializadoras-de-electricidad-espana\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\"> Ranking Comercializadoras de Electricidad espa\u00f1olas para este 2023<\/span><\/i><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Es posible que incluso t\u00fa, como profesional del sector, te sorprendas con la cantidad. \u00bfSab\u00edas que hay casi<\/span><a href=\"https:\/\/sede.cnmc.gob.es\/listado\/censo\/2\" target=\"_blank\" rel=\"noopener\"><b> 800 comercializadoras de energ\u00eda registradas<\/b><\/a><span style=\"font-weight: 400;\">? De estas, m\u00e1s de 500 a\u00fan se encuentran en activo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Encontramos desde<\/span><a href=\"https:\/\/www.naturelek.com\/ranking-comercializadoras-de-electricidad-espana\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\"> comercializadoras consolidadas en el sector energ\u00e9tico<\/span><\/a><span style=\"font-weight: 400;\"> con millones de clientes, hasta nuevas cooperativas y comercializadoras locales con apenas unas decenas de clientes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aun as\u00ed, con la <\/span><b>subida de las tarifas de la electricidad y el gas en 2022,<\/b><span style=\"font-weight: 400;\"> muchos proveedores de energ\u00eda han dejado de ofrecer sus servicios o no pueden aceptar nuevos clientes.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-0ba350ba-bee9-4513-ac4f-080ba72411b3\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-0ba350ba-bee9-4513-ac4f-080ba72411b3\" class=\"hs-cta-node hs-cta-0ba350ba-bee9-4513-ac4f-080ba72411b3\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/0ba350ba-bee9-4513-ac4f-080ba72411b3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" id=\"hs-cta-img-0ba350ba-bee9-4513-ac4f-080ba72411b3\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/0ba350ba-bee9-4513-ac4f-080ba72411b3.png\" alt=\"Descarga el Informe Completo sobre el Estado de la Energ\u00eda 2024 - Spacewell Energy\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, '0ba350ba-bee9-4513-ac4f-080ba72411b3', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Los Servicios Energ\u00e9ticos de las Comercializadoras de Energ\u00eda<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si te desempe\u00f1as en una comercializadora, seguro que eres consciente de que simplemente vender energ\u00eda y entregarla al usuario ya no es suficiente. En el actual panorama energ\u00e9tico, <\/span><b>las comercializadoras tienen un papel importante en la promoci\u00f3n de la eficiencia energ\u00e9tica.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Nos encontramos en una \u00e9poca de <\/span><b>mayor conciencia sobre el consumo energ\u00e9tico<\/b><span style=\"font-weight: 400;\">. Las comercializadoras han implementado una variedad de servicios destinados a satisfacer las demandas cambiantes de sus clientes. Ahora profundizaremos en los<\/span><b> servicios energ\u00e9ticos que priorizan las comercializadoras de energ\u00eda.<\/b><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\">Servicios de Eficiencia Energ\u00e9tica y Soluciones Tecnol\u00f3gicas Avanzadas<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Como hemos comentado, las comercializadoras han implementado una variedad de servicios dise\u00f1ados para satisfacer las demandas cambiantes de sus clientes. Seg\u00fan el<\/span><b> 53.4 % de los encuestados, <\/b><span style=\"font-weight: 400;\">estos servicios <\/span><b>no se limitan \u00fanicamente a medidas convencionales de eficiencia, sino que tambi\u00e9n exploran la integraci\u00f3n de soluciones tecnol\u00f3gicas avanzadas.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Para muchos podr\u00eda ser inesperado descubrir que las <\/span><b>empresas de servicios energ\u00e9ticos ofrecen servicios destinados a promover la eficiencia energ\u00e9tica y reducir el consumo.<\/b><span style=\"font-weight: 400;\"> Puede parecer parad\u00f3jico que una empresa que obtiene ganancias suministrando energ\u00eda abogue por un menor uso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como comercializadora de energ\u00eda, te enfrentas a un delicado acto de equilibrio. Pero todo tiene un lado positivo. Veamos qu\u00e9 2 ideas puedes realizar para encontrar este equilibrio:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Puedes ayudar a los consumidores a reducir su consumo energ\u00e9tico mientras sigues <\/span><b>facturando por los servicios adicionales<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Puedes considerar un crecimiento m\u00e1s lento al ayudar a los clientes a consumir menos. Aunque esto no genere ingresos directos adicionales, <\/span><b>aumentar\u00e1 su fidelidad y evitar\u00e1 que se vayan a la competencia<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Las opciones son muchas y diversas, y su elecci\u00f3n <\/span><b>depender\u00e1 en gran medida de las capacidades y servicios ya ofrecidos por tu comercializadora de energ\u00eda<\/b><span style=\"font-weight: 400;\">. Es fundamental explorar las distintas alternativas con detenimiento, considerando aspectos como la factibilidad del servicio, las tarifas y posibles ofertas para el consumidor, &#8230; Al evaluar estas variables, podr\u00e1s tomar una decisi\u00f3n informada que se ajuste mejor a los retos de tu comercializadora.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\">Consultor\u00eda Especializada y Uso de Energ\u00edas Limpias<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Con miras al futuro, las comercializadoras proporcionan <\/span><b>asesoramiento especializado para<\/b> <b>la instalaci\u00f3n de infraestructuras que respalden la generaci\u00f3n y el uso de energ\u00edas limpias. <\/b><span style=\"font-weight: 400;\">Adem\u00e1s, el<\/span><b> 43.1 % de los encuestados<\/b><span style=\"font-weight: 400;\"> destaca la recomendaci\u00f3n de <\/span><b>proyectos que incorporen <\/b><a href=\"https:\/\/www.dexma.com\/es\/blog-es\/el-rol-de-la-comercializadora-de-electricidad-en-el-autoconsumo-para-empresas\/\"><b>tecnolog\u00edas solares<\/b><\/a><b> y e\u00f3licas,<\/b><span style=\"font-weight: 400;\"> allanando el camino hacia una mayor autonom\u00eda y resistencia energ\u00e9tica.<\/span><\/p>\n<p><b>En el despliegue de energ\u00edas renovables a nivel mundial<\/b><span style=\"font-weight: 400;\">, es evidente que <\/span><b>la pen\u00ednsula Ib\u00e9rica, y Espa\u00f1a en particular, poseen una ventaja significativa en t\u00e9rminos de horas de sol<\/b><span style=\"font-weight: 400;\"> en comparaci\u00f3n con otras regiones de Europa.<\/span><b> Solo en 2022, la instalaci\u00f3n de energ\u00eda solar se duplic\u00f3 en Espa\u00f1a<\/b><span style=\"font-weight: 400;\">, lo que refleja su alto potencial y creciente popularidad. Es claro que aprovechar este potencial requiere una considerable inversi\u00f3n y que la instalaci\u00f3n de placas solares no constituye la \u00fanica soluci\u00f3n. Sin embargo, es innegable que el ritmo de instalaci\u00f3n y adopci\u00f3n del autoconsumo solar sigue aumentando.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, es importante destacar que el <\/span><b>6 de septiembre de 2023<\/b><span style=\"font-weight: 400;\">, seg\u00fan las proyecciones de Red El\u00e9ctrica,<\/span><b> la electricidad generada a trav\u00e9s de la <\/b><a href=\"https:\/\/www.energias-renovables.com\/fotovoltaica\/ocho-meses-de-2023-han-bastado-para-20231227#:~:text=Son%20datos%20provisionales%20de%20Red%20El%C3%A9ctrica%20de%20Espa%C3%B1a%20(REE).&amp;text=Hoy%2C%206%20de%20septiembre%2C%20seg%C3%BAn,r%C3%A9cord%20en%20los%20%C3%BAltimos%20meses.\" target=\"_blank\" rel=\"noopener\"><b>energ\u00eda fotovoltaica ya hab\u00eda superado la producci\u00f3n total del a\u00f1o 2022<\/b><\/a><span style=\"font-weight: 400;\"> (27.902 GWh), llegando a los 27.968 GWh. Estos datos evidencian el creciente uso de esta fuente de energ\u00eda renovable.<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2024\/02\/generacion-enero-dic-23_2.png\" alt=\"Generaci\u00f3n el\u00e9ctrica 2023\" width=\"1072\" height=\"634\" \/><\/p>\n<p><i><span style=\"font-weight: 400;\">Fuente: <\/span><\/i><a href=\"https:\/\/amaranzero.es\/academia\/blog\/el-impacto-de-las-energias-renovables-y-limpias-en-el-mix-energetico-espanol-en-2023\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Amaranzero<\/span><\/i><\/a><\/p>\n<p><b>En lo que respecta a la energ\u00eda e\u00f3lica,<\/b> <b>Espa\u00f1a se ubica como el quinto pa\u00eds del mundo en t\u00e9rminos de potencia e\u00f3lica instalada<\/b><span style=\"font-weight: 400;\">, despu\u00e9s de China, Estados Unidos, Alemania e India, y ocupa el segundo lugar en Europa, despu\u00e9s de Alemania. Con m\u00e1s de 30,000 MW de potencia acumulada, la energ\u00eda e\u00f3lica se convirti\u00f3 en la <\/span><b>principal fuente de generaci\u00f3n el\u00e9ctrica en Espa\u00f1a en 2023, cubriendo m\u00e1s del 24 % de la demanda<\/b><span style=\"font-weight: 400;\">. Todo indica que los resultados de 2024 ser\u00e1n similares, consolidando su posici\u00f3n como la tecnolog\u00eda l\u00edder en la generaci\u00f3n de electricidad en nuestro pa\u00eds.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\">Estrategias para la Gesti\u00f3n de la Demanda<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">El \u00e1mbito de los servicios tambi\u00e9n se ha enriquecido con la incorporaci\u00f3n de <\/span><b>estrategias para la gesti\u00f3n de la demanda<\/b><span style=\"font-weight: 400;\">. Los clientes son ahora m\u00e1s conscientes de la importancia de <\/span><b>medir y verificar los ahorros energ\u00e9ticos<\/b><span style=\"font-weight: 400;\">. En este sentido, un servicio que ofrece auditor\u00edas y reportes detallados se ha vuelto indispensable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En una era en la que todo se eval\u00faa y se cuantifica, poder calcular con precisi\u00f3n los ahorros y analizar la efectividad de las medidas de eficiencia energ\u00e9tica es un objetivo crucial. Sin embargo, <\/span><b>esto requiere contar con el conocimiento, la tecnolog\u00eda adecuada y el tiempo de los profesionales para realizar un seguimiento detallado<\/b><span style=\"font-weight: 400;\">. Por ello, soluciones de <\/span><a href=\"https:\/\/www.dexma.com\/es\/blog-es\/medida-y-verificacion-como-lograr-los-mejores-resultados-webinar\/\"><span style=\"font-weight: 400;\">Medida y Verificaci\u00f3n (M&amp;V)<\/span><\/a><span style=\"font-weight: 400;\"> como la ofrecida por Spacewell Energy, <\/span><a href=\"https:\/\/www.dexma.com\/es\/plataforma-spacewell-energy-dexma-analyse\/\"><span style=\"font-weight: 400;\">Analyse<\/span><\/a><span style=\"font-weight: 400;\">, pueden ser de gran ayuda para que los profesionales gestionen y analicen los datos de consumo energ\u00e9tico de manera eficiente.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Los Retos de las Comercializadoras de Energ\u00eda<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A\u00f1o tras a\u00f1o,<\/span><a href=\"https:\/\/www.dexma.com\/es\/blog-es\/6-retos-de-las-comercializadoras-de-energia\/\"><span style=\"font-weight: 400;\"> las comercializadoras de energ\u00eda enfrentan distintos retos<\/span><\/a><span style=\"font-weight: 400;\"> a los cuales deben hacer frente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el contexto de un mercado energ\u00e9tico vol\u00e1til y desafiante como el que experimentamos en 2023, <\/span><b>las tasas de cambio de clientes y los precios de la energ\u00eda<\/b><span style=\"font-weight: 400;\"> emergen como dos variables cr\u00edticas para las organizaciones. En este contexto, en la Encuesta Energ\u00e9tica de este a\u00f1o exploramos c\u00f3mo estas din\u00e1micas est\u00e1n afectando la gesti\u00f3n energ\u00e9tica y la relaci\u00f3n con el cliente.<\/span><\/p>\n<h3><span style=\"font-weight: 400; color: #41659e;\"> Alta Tasa de Rotaci\u00f3n de Clientes y Precios en las Comercializadoras<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La Encuesta Energ\u00e9tica 2023 destaca que el <\/span><b>50 % de las organizaciones encuestadas ha experimentado cambios en su base de clientes debido a los altos precios de la energ\u00eda<\/b><span style=\"font-weight: 400;\">. Los clientes est\u00e1n en la b\u00fasqueda de la reducci\u00f3n de costos y tambi\u00e9n buscan servicios y asesoramiento para disminuir su consumo energ\u00e9tico.<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.dexma.com\/wp-content\/uploads\/2024\/02\/ES-Energy-Survey-Report-Infographics-.png\" alt=\"Cambios en la base de clientes de las comercializadoras de energ\u00eda 2023\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Este fen\u00f3meno <\/span><b>refleja el impacto econ\u00f3mico de la crisis energ\u00e9tica<\/b><span style=\"font-weight: 400;\">, lo que ha llevado a las empresas a ajustar contratos y buscar estrategias para minimizar costos. Algunas empresas han aprovechado esta situaci\u00f3n como una <\/span><b>oportunidad para fortalecer la fidelizaci\u00f3n. <\/b><strong>O<\/strong><b>frecen servicios adicionales como la gesti\u00f3n de eficiencia energ\u00e9tica,<\/b><span style=\"font-weight: 400;\"> mientras que <\/span><b>otras enfrentan ajustes en contratos por parte de clientes que buscan alivio financiero.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En sectores de actividad altamente din\u00e1micos y competitivos, es com\u00fan que los consumidores cambien r\u00e1pidamente de un proveedor a otro. Lo vemos en la banca, en la telefon\u00eda, y tambi\u00e9n en el suministro energ\u00e9tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este panorama en evoluci\u00f3n demanda que las organizaciones comprendan la importancia de los cambios en las tasas de clientes y los precios de la energ\u00eda. No solo para la sustentabilidad operativa, sino tambi\u00e9n para la innovaci\u00f3n y la oferta de propuestas de valor eficientes y proactivas.<\/span><\/p>\n<p><b>La tasa de rotaci\u00f3n<\/b><span style=\"font-weight: 400;\">, switching o churn en ingl\u00e9s, <\/span><b>a nivel nacio<\/b><strong>nal difiere de la<\/strong><b> tasa de rotaci\u00f3n de clientes de cada comercializadora<\/b><span style=\"font-weight: 400;\">. La tasa de switching recopila datos de todos los contratos vigentes con las comercializadoras. Puede utilizarse como punto de referencia para comparar tu propia tasa de rotaci\u00f3n de clientes.<\/span><\/p>\n<h2><span style=\"font-weight: 400; color: #003f6b;\">Tasa de Rotaci\u00f3n o de Switching en Europa<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En Espa\u00f1a, el mercado energ\u00e9tico est\u00e1 abierto a la competencia. Lo que implica que los consumidores tienen la capacidad de seleccionar sus proveedores de electricidad y gas. De acuerdo con un estudio realizado en 2021, las<\/span><a href=\"https:\/\/www.acer.europa.eu\/sites\/default\/files\/documents\/Publications\/MMR_2021_Energy_Retail_Consumer_Protection_Volume.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\"> tasas de rotaci\u00f3n m\u00e1s altas <\/span><\/a><span style=\"font-weight: 400;\">se observan en Holanda, B\u00e9lgica y Noruega, superando el 20 %. Aunque Espa\u00f1a no alcanza estos niveles, ya supera la media tanto en el sector el\u00e9ctrico como en el del gas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al mismo tiempo, debemos considerar que una tasa alta de rotaci\u00f3n puede ser beneficiosa para el mercado. Esto <\/span><b>indica que el proceso de cambio entre proveedores es relativamente simple y flexible para el consumidor<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde la \u00f3ptica de un profesional en una comercializadora, la p\u00e9rdida de clientes no se percibe como algo especialmente positivo. Por lo tanto, es crucial tener en consideraci\u00f3n los puntos mencionados en este art\u00edculo. <\/span><b>Ofrecer servicios de valor a\u00f1adido a tus clientes, as\u00ed como posibles ajustes seg\u00fan sus necesidades o asesoramiento, puede ser fundamental para mantener su fidelidad. <\/b><span style=\"font-weight: 400;\">Adem\u00e1s, una alta tasa de rotaci\u00f3n en el mercado tambi\u00e9n indica que tienes la oportunidad de atraer a nuevos clientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde Spacewell Energy, te alentamos a mejorar tus servicios de forma continua, y nos complace acompa\u00f1arte en este proceso. Si deseas obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Spacewell Energy puede ayudarte a acceder a nuevas herramientas y soluciones, no dudes en ponerte en <\/span><a href=\"https:\/\/www.dexma.com\/es\/contacto\/\"><span style=\"font-weight: 400;\">contacto con nosotros.<\/span><\/a><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-d238a6d9-8b4c-4ac9-b397-6e034cae13e5\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-d238a6d9-8b4c-4ac9-b397-6e034cae13e5\" class=\"hs-cta-node hs-cta-d238a6d9-8b4c-4ac9-b397-6e034cae13e5\"><!-- [if lte IE 8]>\n\n\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/437281\/d238a6d9-8b4c-4ac9-b397-6e034cae13e5\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" id=\"hs-cta-img-d238a6d9-8b4c-4ac9-b397-6e034cae13e5\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/437281\/d238a6d9-8b4c-4ac9-b397-6e034cae13e5.png\" alt=\"Descarga el Informe sobre el Estado de la Energ\u00eda 2024 - Spacewell Energy\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(437281, 'd238a6d9-8b4c-4ac9-b397-6e034cae13e5', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las comercializadoras de energ\u00eda son un actor con el que casi todas las personas o empresas deben interaccionar. Las organizaciones requieren de energ\u00eda para poder desarrollar su actividad empresarial y por ello buscan las comercializadoras que mejor servicio les proporcionen. En el art\u00edculo de la semana pasada nos adentramos en el contexto de las Empresas [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":35308,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-37155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024 - Spacewell | A Nemetschek Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024\" \/>\n<meta property=\"og:description\" content=\"Las comercializadoras de energ\u00eda son un actor con el que casi todas las personas o empresas deben interaccionar. Las organizaciones requieren de energ\u00eda para poder desarrollar su actividad empresarial y por ello buscan las comercializadoras que mejor servicio les proporcionen. En el art\u00edculo de la semana pasada nos adentramos en el contexto de las Empresas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T09:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"GR DEV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GR DEV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/\"},\"author\":{\"name\":\"GR DEV\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\"},\"headline\":\"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024\",\"datePublished\":\"2024-02-23T09:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/\"},\"wordCount\":1907,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/\",\"name\":\"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024 - Spacewell | A Nemetschek Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png\",\"datePublished\":\"2024-02-23T09:30:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png\",\"width\":1680,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/recursos\\\/blog\\\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/es\\\/#\\\/schema\\\/person\\\/3ab9f25a5170063123a203b278975eb8\",\"name\":\"GR DEV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g\",\"caption\":\"GR DEV\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/es\\\/author\\\/gr-dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024 - Spacewell | A Nemetschek Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024","og_description":"Las comercializadoras de energ\u00eda son un actor con el que casi todas las personas o empresas deben interaccionar. Las organizaciones requieren de energ\u00eda para poder desarrollar su actividad empresarial y por ello buscan las comercializadoras que mejor servicio les proporcionen. En el art\u00edculo de la semana pasada nos adentramos en el contexto de las Empresas [&hellip;]","og_url":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2024-02-23T09:30:37+00:00","og_image":[{"width":1680,"height":945,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png","type":"image\/png"}],"author":"GR DEV","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Escrito por":"GR DEV","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/"},"author":{"name":"GR DEV","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8"},"headline":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024","datePublished":"2024-02-23T09:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/"},"wordCount":1907,"publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/","url":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/","name":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024 - Spacewell | A Nemetschek Company","isPartOf":{"@id":"https:\/\/spacewell.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png","datePublished":"2024-02-23T09:30:37+00:00","breadcrumb":{"@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2024\/02\/Survey-Report-2023-Featured-LP-Blog-3-Utilities.png","width":1680,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/es\/recursos\/blog\/comercializadoras-de-energia-servicios-energeticos-y-objetivos-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Comercializadoras de Energ\u00eda: Servicios Energ\u00e9ticos y Objetivos 2024"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/es\/#website","url":"https:\/\/spacewell.com\/es\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/es\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/es\/#\/schema\/person\/3ab9f25a5170063123a203b278975eb8","name":"GR DEV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c441388245d3fac0379458f7558a0cf897d50b2cbbc2f90fe4bc9396e01c79d?s=96&d=mm&r=g","caption":"GR DEV"},"url":"https:\/\/spacewell.com\/es\/author\/gr-dev\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/comments?post=37155"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/posts\/37155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media\/35308"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/media?parent=37155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/categories?post=37155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/es\/wp-json\/wp\/v2\/tags?post=37155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}