


{"id":51961,"date":"2026-04-22T16:06:13","date_gmt":"2026-04-22T14:06:13","guid":{"rendered":"https:\/\/spacewell.com\/?p=51961"},"modified":"2026-04-22T16:06:13","modified_gmt":"2026-04-22T14:06:13","slug":"cyber-essentials-plus-certification-in-the-uk","status":"publish","type":"post","link":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/","title":{"rendered":"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien"},"content":{"rendered":"<div class=\"gb-container gb-container-2fca63ba gb-container-5731d80c\">\n\n<p class=\"wp-block-paragraph\">Spacewell hat die britische Cyber Essentials Plus-Zertifizierung erhalten, was unsere Position als vertrauensw\u00fcrdiger und sicherer Technologiepartner f\u00fcr unsere Kunden auf dem britischen Markt weiter st\u00e4rkt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cyber Essentials Plus ist die h\u00f6chste Zertifizierungsstufe im Rahmen des von der britischen Regierung unterst\u00fctzten Cyber Essentials-Programms, das vom National Cyber Security Centre (NCSC) geleitet wird. Sie erfordert eine unabh\u00e4ngige und gr\u00fcndliche technische Pr\u00fcfung der Systeme, Ger\u00e4te und Kontrollen eines Unternehmens. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Bewertung best\u00e4tigt, dass die wichtigsten Sicherheitsma\u00dfnahmen zum Schutz vor den h\u00e4ufigsten internetbasierten Cyberangriffen wirksam umgesetzt wurden. Sie hilft Unternehmen, das Risiko zu verringern und ihren Kunden und Partnern eine solide Cyberhygiene zu demonstrieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"why-uk-organisations-choose-secure-partners-for-sm\">Die Wahl eines sicheren Partners f\u00fcr Smart Building Software<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Unternehmen, die sich bei der Verwaltung von Geb\u00e4udedaten, Arbeitsplatzerfahrungen und kritischen Anlagenabl\u00e4ufen auf Spacewell verlassen, ist Cybersicherheit heute eine gesch\u00e4ftskritische Anforderung, nicht nur ein IT-Problem. Viele von uns haben in den Nachrichten gesehen, wie Cyberattacken sensible Informationen preisgeben, den Betrieb st\u00f6ren und das Vertrauen der Stakeholder besch\u00e4digen k\u00f6nnen, insbesondere wenn gro\u00dfe Anlagenportfolios und Arbeitsplatzsysteme betroffen sind. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch die Erlangung von Cyber Essentials Plus bietet Spacewell britischen Kunden die unabh\u00e4ngige Gewissheit, dass unsere Infrastruktur, unser Benutzerzugang und unsere Cloud-Dienste kontinuierlich auf Cyber-Bedrohungen getestet werden.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die Spacewell Cyber Essential Plus-Zertifizierung unterst\u00fctzt auch Unternehmen, die in regulierten Umgebungen oder komplexen Lieferketten t\u00e4tig sind<\/strong>, in denen nachweisbare Sicherheitsstandards bei der Beschaffung und bei den Risikoprozessen von Lieferanten zunehmend gefordert werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"our-uk-cybersecurity-roadmap-beyond-cyber-essentia\">Unser Fahrplan f\u00fcr die Cybersicherheit in Gro\u00dfbritannien: \u00fcber Cyber Essentials Plus hinaus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Spacewells smart building L\u00f6sungen sind so konzipiert, dass sie Menschen, Orte und Systeme sicher miteinander verbinden. Sie verf\u00fcgen \u00fcber eine starke Verschl\u00fcsselung, ein modernes Zugangsmanagement und Sicherheit, die in unseren Entwicklungszyklus eingebettet ist. Die technischen Sicherheitsvorkehrungen werden durch regelm\u00e4\u00dfige interne und externe Audits, Penetrationstests und die Einhaltung internationaler Standards wie ISO 27001 und SOC 2-\u00e4quivalente Kontrollen erg\u00e4nzt, die eine zus\u00e4tzliche Vertrauensebene zus\u00e4tzlich zu Cyber Essentials Plus bieten.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F\u00fcr unsere Kunden bedeutet dies, dass sie Spacewell-L\u00f6sungen in gro\u00dfem Umfang einsetzen k\u00f6nnen<\/strong>, da sie wissen, dass die Cybersicherheit als grundlegende Voraussetzung und nicht als nachtr\u00e4glicher Gedanke behandelt wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Erreichen von Cyber Essentials Plus in Gro\u00dfbritannien ist ein wichtiger Meilenstein, aber es ist nicht der Endpunkt unserer Sicherheitsreise. Wir werden weiterhin in unsere Sicherheitskapazit\u00e4ten im Einklang mit anerkannten internationalen Standards investieren und Spacewell wird ein vertrauensw\u00fcrdiger und sicherer Partner bleiben, der Organisationen dabei hilft, den Wert von smart building-Daten zu erschlie\u00dfen und gleichzeitig ihre Informationen und Abl\u00e4ufe zu sch\u00fctzen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f6chten Sie mehr \u00fcber die Sicherheitsverpflichtungen von Spacewell erfahren? <a href=\"https:\/\/spacewell.com\/de\/plattform-fur-intelligente-gebaude\/\">Hier finden Sie weitere Details zu unserer Plattformsicherheit<\/a>.<\/p>\n\n\n\n<iframe src=\"https:\/\/registry.blockmarktech.com\/certificates\/728401b1-6def-45c8-8402-71ee9a3d3c4f\/widget\/?tooltip_position=bottom&#038;theme=transparent%22%20style=\" border:none=\"\"><\/iframe>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Spacewell hat die britische Cyber Essentials Plus-Zertifizierung erhalten, was unsere Position als vertrauensw\u00fcrdiger und sicherer Technologiepartner f\u00fcr unsere Kunden auf dem britischen Markt weiter st\u00e4rkt. Cyber Essentials Plus ist die h\u00f6chste Zertifizierungsstufe im Rahmen des von der britischen Regierung unterst\u00fctzten Cyber Essentials-Programms, das vom National Cyber Security Centre (NCSC) geleitet wird. Sie erfordert eine unabh\u00e4ngige &#8230; <a title=\"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien\" class=\"read-more\" href=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/\" aria-label=\"Mehr Informationen \u00fcber Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":33,"featured_media":52194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[84,79],"tags":[],"class_list":["post-51961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","category-unternehmen","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spacewell ist jetzt Cyber Essential Plus zertifiziert<\/title>\n<meta name=\"description\" content=\"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien\" \/>\n<meta property=\"og:description\" content=\"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T14:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-1024x538.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Helena Palomo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helena Palomo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/\"},\"author\":{\"name\":\"Helena Palomo\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/person\\\/fb39acde59094999074f3ae62e2b159a\"},\"headline\":\"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien\",\"datePublished\":\"2026-04-22T14:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/\"},\"wordCount\":468,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png\",\"articleSection\":[\"Neuigkeiten\",\"Unternehmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/\",\"name\":\"Spacewell ist jetzt Cyber Essential Plus zertifiziert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png\",\"datePublished\":\"2026-04-22T14:06:13+00:00\",\"description\":\"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png\",\"width\":2350,\"height\":1234},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/cyber-essentials-plus-certification-in-the-uk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/person\\\/fb39acde59094999074f3ae62e2b159a\",\"name\":\"Helena Palomo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g\",\"caption\":\"Helena Palomo\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/author\\\/helena-palomo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spacewell ist jetzt Cyber Essential Plus zertifiziert","description":"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/","og_locale":"de_DE","og_type":"article","og_title":"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien","og_description":"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.","og_url":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2026-04-22T14:06:13+00:00","og_image":[{"width":1024,"height":538,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-1024x538.png","type":"image\/png"}],"author":"Helena Palomo","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Verfasst von":"Helena Palomo","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/"},"author":{"name":"Helena Palomo","@id":"https:\/\/spacewell.com\/de\/#\/schema\/person\/fb39acde59094999074f3ae62e2b159a"},"headline":"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien","datePublished":"2026-04-22T14:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/"},"wordCount":468,"publisher":{"@id":"https:\/\/spacewell.com\/de\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png","articleSection":["Neuigkeiten","Unternehmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/","url":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/","name":"Spacewell ist jetzt Cyber Essential Plus zertifiziert","isPartOf":{"@id":"https:\/\/spacewell.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png","datePublished":"2026-04-22T14:06:13+00:00","description":"Spacewell hat Cyber Essentials Plus in Gro\u00dfbritannien erreicht. Damit haben Unternehmen einen sicheren, vertrauensw\u00fcrdigen Partner f\u00fcr Smart Building Software, bei dem die Cybersicherheit an erster Stelle steht.","breadcrumb":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2026\/04\/Spacewell-obtains-Cyber-Essentials-Plus-Certification-2-1.png","width":2350,"height":1234},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/cyber-essentials-plus-certification-in-the-uk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/de\/"},{"@type":"ListItem","position":2,"name":"Spacewell erh\u00e4lt die Cyber Essentials Plus Zertifizierung in Gro\u00dfbritannien"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/de\/#website","url":"https:\/\/spacewell.com\/de\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/de\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spacewell.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/de\/#\/schema\/person\/fb39acde59094999074f3ae62e2b159a","name":"Helena Palomo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/641ac712228222ecdc738094f84c0bac1d1a2a1de646d5cd9d96ff67c960ec63?s=96&d=mm&r=g","caption":"Helena Palomo"},"url":"https:\/\/spacewell.com\/de\/author\/helena-palomo\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts\/51961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/comments?post=51961"}],"version-history":[{"count":11,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts\/51961\/revisions"}],"predecessor-version":[{"id":52057,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts\/51961\/revisions\/52057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/media\/52194"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/media?parent=51961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/categories?post=51961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/tags?post=51961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}