


{"id":10322,"date":"2022-01-24T10:02:00","date_gmt":"2022-01-24T09:02:00","guid":{"rendered":"https:\/\/spacewell.com\/unkategorisiert\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/"},"modified":"2023-09-13T15:10:53","modified_gmt":"2023-09-13T13:10:53","slug":"unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein","status":"publish","type":"post","link":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/","title":{"rendered":"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein"},"content":{"rendered":"<div class=\"gb-container gb-container-86aa3979 gb-container-5731d80c\">\n\n<p class=\"wp-block-paragraph\"><strong>Antwerpen<\/strong> \u00ad\u2013 Das unabh\u00e4ngige Analystenunternehmen Verdantix hat am 18. Januar seinen aktuellen Green-Quadrant-Bericht zu IoT ver\u00f6ffentlicht: \u201e<a href=\"https:\/\/research.verdantix.com\/report\/green-quadrant-iot-platforms-for-smart-buildings-2022\">Green Quadrant: IoT Platforms For Smart Buildings 2022<\/a>\u201d. Diese Benchmark bietet einen detaillierten, faktenbasierten Vergleich der 17 bekanntesten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude, die aktuell auf dem Markt erh\u00e4ltlich sind.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-ddefc3fd gb-headline-text\">F\u00fchrend im wachsenden Markt f\u00fcr Geb\u00e4ude-IoT<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In seinem Bericht stuft Verdantix Spacewell neben den langj\u00e4hrigen Anbietern f\u00fcr Geb\u00e4udeautomation Siemens, Johnson Controls und Schneider Electric im oberen rechten Quadranten als \u201eF\u00fchrend\u201c ein. Bei Spacewell wird sowohl die Breite als auch die Benutzerfreundlichkeit der L\u00f6sungen in einem Immobilienmarkt gew\u00fcrdigt, der zunehmend von den Nutzern bestimmt wird. Dar\u00fcber hinaus zeichnet sich Spacewell durch das umfangreiche Netzwerk aus sowohl Software- als auch Hardware-Partnern aus, das die M\u00f6glichkeit f\u00fcr ein umfassendes IoT-Angebot mit einer Vielzahl von Funktionen bietet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eSpacewell ist einer der f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr Geb\u00e4ude am Markt. <em>Dem zugrunde liegen eine intensivierte strategische Fokussierung sowie Investitionen in das IoT-Angebot in den vergangenen zwei Jahren<\/em>\u201c, sagt Dayann Charles, Autor des Berichts. <em>\u201eDie L\u00f6sungen von Spacewell schneiden \u00fcber mehrere wichtige Funktionsbereiche hinweg sehr gut ab. Dazu geh\u00f6ren beispielsweise das Energiemanagement, das durch die \u00dcbernahme von DEXMA noch verst\u00e4rkt wird, sowie die Raum\u00fcberwachung und Arbeitsplatz-Dienste. Spacewell bietet sich als herausragender Technologiepartner f\u00fcr Organisationen an, die bei Raum- und Energienutzung auf Effizienz setzen.\u201c<\/em><\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-9d0d3156 gb-headline-text\">Besondere St\u00e4rken des Spacewell-Angebots<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In seinem Bericht erw\u00e4hnt Verdantix insbesondere St\u00e4rken bei der <strong>Raum\u00fcberwachung und -analyse<\/strong>, <strong>bei Arbeitsplatz-Diensten<\/strong>, <strong>Facilitymanagement-Diensten und Energiemanagement<\/strong>, <strong>unter Einbeziehung von KI<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Bereich Raum\u00fcberwachung und -analyse beschreibt der Bericht, dass <strong>\u201e<\/strong>Spacewell Echtzeit- und Verlaufsdaten zu R\u00e4umen wie Belegung und Besucherfrequenz nachverfolgt und Dashboards mit Einsparpotenzialen und M\u00f6glichkeiten f\u00fcr die Reduzierung der Quadratmeterzahl liefert. Diese Empfehlungen sind f\u00fcr Unternehmen sehr wertvoll, die in der Zeit nach COVID Immobilien rationalisieren und die Fl\u00e4chennutzung maximieren wollen. Die Plattform bietet au\u00dferdem einige der stabilsten Funktionen f\u00fcr die Erfassung von Fl\u00e4chendaten \u00fcber Altsysteme wie Zugangskontrolle, Geb\u00e4udemanagementsysteme (BMSs) und Sensoren. Dabei st\u00fctzt sie sich auf ihr breites Angebot an Programmierschnittstellen (APIs).\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spacewell schneidet auch im Bereich Energiemanagement sehr gut ab, was auf die \u00dcbernahme der <a href=\"https:\/\/www.dexma.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">DEXMA Smart Energy Platform<\/a> im Jahr 2020 zur\u00fcckzuf\u00fchren ist. \u201eDie DEXMA-L\u00f6sung nutzt KI f\u00fcr die proaktive und durchg\u00e4ngige Optimierung der Energieleistung. Die L\u00f6sung liefert au\u00dferdem Empfehlungen f\u00fcr Einsparpotenziale einschlie\u00dflich Finanzprognosen f\u00fcr diese Ma\u00dfnahmen und Details f\u00fcr deren Umsetzung.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus erw\u00e4hnt der Bericht Spacewells \u201ef\u00fchrende <a href=\"https:\/\/spacewell.com\/de\/loesungen\/intelligente-arbeitsplatzloesungen\/workplace-experience\/intelligente-arbeitsplatz-app\/\">nutzerorientierte mobile App<\/a> f\u00fcr Arbeitsplatz-Dienste\u201c, die Raum- und Komfortdaten von Sensoren verwendet, um die Mitarbeitererfahrung zu verbessern und Arbeitsplatz-Dienste zu optimieren. Dies hat f\u00fcr viele Unternehmen eine hohe Priorit\u00e4t, die die R\u00fcckkehr ins B\u00fcro nach der Pandemie vorbereiten.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-fb0defc2 gb-headline-text\">Untersuchungsmethodik<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Basierend auf der unternehmenseigenen Green-Quadrant-Methodik f\u00fchrt Verdantix in der Analyse Informationen aus umfangreichen Live-Produktpr\u00e4sentationen von Anbietern, <a href=\"https:\/\/www.verdantix.com\/report\/green-quadrant-iot-platforms-for-smart-buildings-2022\" target=\"_blank\" rel=\"noreferrer noopener\">deren<\/a> Antworten auf einen Fragebogen mit 154 Punkten und Erkenntnisse aus einer Umfrage unter 285 Immobilienmanagern zusammen.<\/p>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Antwerpen \u00ad\u2013 Das unabh\u00e4ngige Analystenunternehmen Verdantix hat am 18. Januar seinen aktuellen Green-Quadrant-Bericht zu IoT ver\u00f6ffentlicht: \u201eGreen Quadrant: IoT Platforms For Smart Buildings 2022\u201d. Diese Benchmark bietet einen detaillierten, faktenbasierten Vergleich der 17 bekanntesten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude, die aktuell auf dem Markt erh\u00e4ltlich sind. F\u00fchrend im wachsenden Markt f\u00fcr Geb\u00e4ude-IoT In seinem Bericht stuft &#8230; <a title=\"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein\" class=\"read-more\" href=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/\" aria-label=\"Mehr Informationen \u00fcber Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":29,"featured_media":6300,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[84],"tags":[],"class_list":["post-10322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spacewell zum f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ernannt<\/title>\n<meta name=\"description\" content=\"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein\" \/>\n<meta property=\"og:description\" content=\"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacewell | A Nemetschek Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpacewellHQ\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-24T09:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-13T13:10:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marketing Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@Spacewell_HQ\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/\"},\"author\":{\"name\":\"Marketing Team\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\"},\"headline\":\"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein\",\"datePublished\":\"2022-01-24T09:02:00+00:00\",\"dateModified\":\"2023-09-13T13:10:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png\",\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/\",\"name\":\"Spacewell zum f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ernannt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png\",\"datePublished\":\"2022-01-24T09:02:00+00:00\",\"dateModified\":\"2023-09-13T13:10:53+00:00\",\"description\":\"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png\",\"width\":1200,\"height\":630,\"caption\":\"SB Verdantix Green Quadrant IoT Platforms For Smart Buildings 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/unternehmen\\\/neuigkeiten\\\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\",\"name\":\"Spacewell | A Nemetschek Company\",\"description\":\"Make buildings work for people\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacewell.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#organization\",\"name\":\"Spacewell | A Nemetschek Company\",\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"contentUrl\":\"https:\\\/\\\/spacewell.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/spacewell-logo-500x88-1.webp\",\"width\":500,\"height\":88,\"caption\":\"Spacewell | A Nemetschek Company\"},\"image\":{\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpacewellHQ\",\"https:\\\/\\\/x.com\\\/Spacewell_HQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spacewell.com\\\/de\\\/#\\\/schema\\\/person\\\/56fc87cc20a52c431f3831f2c17e946a\",\"name\":\"Marketing Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g\",\"caption\":\"Marketing Team\"},\"url\":\"https:\\\/\\\/spacewell.com\\\/de\\\/author\\\/marketing-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spacewell zum f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ernannt","description":"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/","og_locale":"de_DE","og_type":"article","og_title":"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein","og_description":"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.","og_url":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/","og_site_name":"Spacewell | A Nemetschek Company","article_publisher":"https:\/\/www.facebook.com\/SpacewellHQ","article_published_time":"2022-01-24T09:02:00+00:00","article_modified_time":"2023-09-13T13:10:53+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png","type":"image\/png"}],"author":"Marketing Team","twitter_card":"summary_large_image","twitter_creator":"@Spacewell_HQ","twitter_site":"@Spacewell_HQ","twitter_misc":{"Verfasst von":"Marketing Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#article","isPartOf":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/"},"author":{"name":"Marketing Team","@id":"https:\/\/spacewell.com\/de\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a"},"headline":"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein","datePublished":"2022-01-24T09:02:00+00:00","dateModified":"2023-09-13T13:10:53+00:00","mainEntityOfPage":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/"},"wordCount":525,"publisher":{"@id":"https:\/\/spacewell.com\/de\/#organization"},"image":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png","articleSection":["Neuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/","url":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/","name":"Spacewell zum f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ernannt","isPartOf":{"@id":"https:\/\/spacewell.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#primaryimage"},"image":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png","datePublished":"2022-01-24T09:02:00+00:00","dateModified":"2023-09-13T13:10:53+00:00","description":"Der Benchmark von unabh\u00e4ngiges Forschungsunternehmen Verdantix bietet einen faktenbasierten Vergleich der 17 wichtigsten IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude.","breadcrumb":{"@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#primaryimage","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/07\/SB_Verdantix_Green_Quadrant_IoT_Platforms_For_Smart_Buildings_2022-Blog-1200x630-1.png","width":1200,"height":630,"caption":"SB Verdantix Green Quadrant IoT Platforms For Smart Buildings 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/spacewell.com\/de\/unternehmen\/neuigkeiten\/unabhaengiges-forschungsunternehmen-stuft-spacewell-als-einen-fuehrenden-anbieter-von-iot-plattformen-fuer-intelligente-gebaeude-ein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacewell.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unabh\u00e4ngiges Forschungsunternehmen stuft Spacewell als einen f\u00fchrenden Anbieter von IoT-Plattformen f\u00fcr intelligente Geb\u00e4ude ein"}]},{"@type":"WebSite","@id":"https:\/\/spacewell.com\/de\/#website","url":"https:\/\/spacewell.com\/de\/","name":"Spacewell | A Nemetschek Company","description":"Make buildings work for people","publisher":{"@id":"https:\/\/spacewell.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacewell.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spacewell.com\/de\/#organization","name":"Spacewell | A Nemetschek Company","url":"https:\/\/spacewell.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spacewell.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","contentUrl":"https:\/\/spacewell.com\/wp-content\/uploads\/2023\/05\/spacewell-logo-500x88-1.webp","width":500,"height":88,"caption":"Spacewell | A Nemetschek Company"},"image":{"@id":"https:\/\/spacewell.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpacewellHQ","https:\/\/x.com\/Spacewell_HQ"]},{"@type":"Person","@id":"https:\/\/spacewell.com\/de\/#\/schema\/person\/56fc87cc20a52c431f3831f2c17e946a","name":"Marketing Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33dd4b194f6044b53d8410d1a677b226d86f23969442e70903a2b3bd700aac4d?s=96&d=mm&r=g","caption":"Marketing Team"},"url":"https:\/\/spacewell.com\/de\/author\/marketing-team\/"}]}},"_links":{"self":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts\/10322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/comments?post=10322"}],"version-history":[{"count":0,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/posts\/10322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/media\/6300"}],"wp:attachment":[{"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/media?parent=10322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/categories?post=10322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacewell.com\/de\/wp-json\/wp\/v2\/tags?post=10322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}